{"id":3577,"date":"2016-08-01T07:01:50","date_gmt":"2016-08-01T06:01:50","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/apartirdelos50\/?p=3577"},"modified":"2016-08-01T07:01:50","modified_gmt":"2016-08-01T06:01:50","slug":"crecimiento-interios-aprender-a-estar-solos","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/2016\/08\/01\/crecimiento-interios-aprender-a-estar-solos\/","title":{"rendered":"Crecimiento personal &#8220;Aprender a estar solos&#8221;"},"content":{"rendered":"<p><span style=\"font-family: Verdana; font-size: large;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2008\/12\/_86.jpg\" alt=\"\" width=\"460\" height=\"314\" \/><\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: large;\"><span style=\"font-family: Verdana;\">Hubo un tiempo en el que yo tambi\u00e9n jugu\u00e9 en el equipo de las personas que, por tener p\u00e1nico a la soledad, se agarraban a un clavo ardiendo (y de los que quema de verdad) con tal de no tener que enfrentarse al vac\u00edo f\u00edsico consiguiente. \u00a1Cu\u00e1ntas veces habr\u00e9 escuchado a lo largo de mi vida la frase terrible \u00a0&#8211;<\/span><em><span style=\"font-family: Verdana;\">\u201c\u00a1Es que yo no puedo estar sola<\/span><\/em><span style=\"font-family: Verdana;\">\u201d!,expresada en femenino porque han sido mayormente mujeres quienes la han pronunciado delante de m\u00ed; puede que a este respecto los hombres se callen para no parecer d\u00e9biles aunque luego ellos tambi\u00e9n busquen su apa\u00f1o, no lo s\u00e9.<\/span><\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Porque hay dos soledades: la f\u00edsica o exterior, la de vivir solo o estar solo y la an\u00edmica o interior que, a pesar de ser mucho m\u00e1s demoledora que la primera, suele ser a la otra, a la que mayor pavor profesa la humanidad, aunque sea la interior, la que deprime, ahoga, y algunas veces, mata.<\/span><\/p>\n<p><span style=\"font-size: large;\"><span style=\"font-family: Verdana;\">Como la mayor\u00eda de mujeres de mi generaci\u00f3n fui educada para compartir mi vida; con esposo e hijos, preferentemente. Luego pas\u00f3 lo que pas\u00f3 y aprend\u00ed que la realidad vital no siempre es como uno se la hab\u00eda imaginado. Digamos que me pusieron en un camino de dependencia afectiva: a la familia primero y al matrimonio despu\u00e9s. Si hab\u00eda algo que parec\u00eda ser terrible ya me lo avisaban con tiempo haci\u00e9ndome ver que mi actitud ante la vida iba mal encaminada. La espada de Damocles colgaba sobre mi cabeza sin remisi\u00f3n: <\/span><em><span style=\"font-family: Verdana;\">\u201cSi no te portas bien te quedar\u00e1s sola\u201d. \u201cSi no aprendes a <\/span><\/em><\/span><span style=\"font-size: large;\"><em><span style=\"font-family: Verdana;\">ceder <\/span><\/em><em><span style=\"font-family: Verdana;\">ning\u00fan novio se casar\u00e1 contigo<\/span><\/em><span style=\"font-family: Verdana;\">\u201d. \u201c<\/span><em><span style=\"font-family: Verdana;\">Como no cambies de car\u00e1cter <\/span><\/em><em><span style=\"font-family: Verdana;\">acabar\u00e1s amargada y sola<\/span><\/em><span style=\"font-family: Verdana;\">\u201d. Y mil dulzuras por el estilo \u2013de las que nunca descubr\u00ed la verdadera intenci\u00f3n- que me iban avisando de los riesgos que correr\u00eda si persist\u00eda en sacar los pies del tiesto social. Pero como en mi condici\u00f3n estaba tener ideas propias pronto le vi las orejas al lobo de la tan temible y vaticinada \u201csoledad\u201d.<\/span><\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">La sociedad te deja de lado si llamas la atenci\u00f3n o intentas liberarte de cualquier yugo que haya sido previsto para ti. Obediencia, sumisi\u00f3n y asunci\u00f3n del lugar que ha sido asignado; y si no, el ostracismo puro y duro. (Aqu\u00ed el par\u00e9ntesis necesario para precisar que, a d\u00eda de hoy, la cosa ha cambiado algo y ya no se ceban tanto en las mujeres como antes. Como mujer hablo pues y dentro del contexto de mi generaci\u00f3n.)<\/span><\/p>\n<p><span style=\"font-size: large;\"><span style=\"font-family: Verdana;\">La peor pelea que tuve con la soledad f\u00edsica fue cuando me divorci\u00e9 teniendo una criatura muy peque\u00f1a, aunque ya estaba sola antes de separarme, \u201c<\/span><em><span style=\"font-family: Verdana;\">la terrible soledad de dos en compa\u00f1\u00eda<\/span><\/em><span style=\"font-family: Verdana;\">\u201d que es una dura verdad, de la que doy fe. Por eso prefer\u00ed quedarme sola sola. Huelga decir que el concepto autoestima jug\u00f3 en mi contra durante bastante tiempo hasta que pas\u00f3 a formar parte de la plantilla fija de mi equipo y empez\u00f3 a permitirme ganar algunos partidos.<\/span><\/span><\/p>\n<p><span style=\"font-size: large;\"><span style=\"font-family: Verdana;\">Por el contrario, la soledad interior se presentaba como una agon\u00eda recurrente y en cuanto asom\u00f3 las orejas cort\u00e9 por lo sano. Aliment\u00e9 con las mejores <\/span><em><span style=\"font-family: Verdana;\">delicatessen<\/span><\/em><span style=\"font-family: Verdana;\"> a mi alcance a esa ni\u00f1a interior que nunca se sinti\u00f3 aceptada y sin embargo, consigui\u00f3 ser feliz. Me limit\u00e9 a permitirme mucho a m\u00ed misma y a darme cuenta de que cuando los dem\u00e1s dec\u00edan \u201cego\u00edsmo\u201d yo sent\u00eda que para m\u00ed era \u201csupervivencia\u201d.<\/span><\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">La soledad f\u00edsica es otra cosa. Es la que hace que una persona en plena madurez de su vida se vea abocada a un aislamiento forzoso del resto de los seres humanos. Y eso\u2026es matem\u00e1ticamente imposible en la mayor\u00eda de los casos porque todos tenemos a alguien al lado o cerca con quien charlar un rato, compartir un caf\u00e9 o un paseo. Lo que ocurre es que nos encerramos en nosotros mismos y rechazamos la ayuda y el apoyo que se nos pueda ofrecer desde el exterior. La soledad interna que nos chiva que somos infelices nos impele a tirarnos de cabeza en la piscina de la soledad externa para dar boqueadas de angustia y que vean los dem\u00e1s c\u00f3mo estamos a punto de ahogarnos y que entonces, por pura conmiseraci\u00f3n, nos lancen un salvavidas que nos solucionar\u00e1 el problema, que no es otro que la repulsa a asumir una realidad que nos resulta desagradable.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Cuando se pone todo lo que est\u00e1 en nuestras manos para encarar las vicisitudes de la vida, -aunque no siempre se consigan \u00f3ptimos resultados-, cuando se siente que se est\u00e1 haciendo lo que se tiene que hacer\u2026 entonces el fantasma de la soledad pasa de largo hasta la parada siguiente, donde hallar\u00e1, casi con toda seguridad, el caldo de cultivo que necesita para meter miedo\u2026a otra persona. <\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Consegu\u00ed vencer al fantasma de la soledad plant\u00e1ndole cara, no permiti\u00e9ndole que se ense\u00f1oreara de mi casa ni de mi alma. \u201cUtilizando\u201d a quienes me quer\u00edan para pedirles ayuda y escuchar y atender. Y d\u00e1ndome cuenta de que yo puedo ser mi mejor compa\u00f1\u00eda\u2026a poco que me lo proponga.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">La vida, el mundo, la gente, no est\u00e1n ah\u00ed para hacerme da\u00f1o en exclusiva; todo lo contrario. Si miro bien, la vida, el mundo, la gente, pueden existir para regalarme muchos peque\u00f1os motivos de felicidad. Tan s\u00f3lo hay que ponerse a ello\u2026<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">En fin.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">LaAlquimista<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Si alguien desea contactar:<\/span><\/p>\n<p><span style=\"font-size: large;\"><a><span style=\"font-family: Verdana;\">apartirdeloscincuenta@gmail.com<\/span><\/a><\/span><\/p>\n<p><span style=\"font-size: large;\">*Reflexiones despu\u00e9s de ver la obra de teatro de Cesc Gay &#8220;Los vecinos de arriba&#8221;<\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00a0 Hubo un tiempo en el que yo tambi\u00e9n jugu\u00e9 en el equipo de las personas que, por tener p\u00e1nico a la soledad, se agarraban a un clavo ardiendo (y de los que quema de verdad) con tal de no tener que enfrentarse al vac\u00edo f\u00edsico consiguiente. \u00a1Cu\u00e1ntas veces habr\u00e9 escuchado a lo largo de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3577","post","type-post","status-publish","format-standard","hentry","category-filosofia-de-vida-reflexiones"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/posts\/3577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/comments?post=3577"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/posts\/3577\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/media?parent=3577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/categories?post=3577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/tags?post=3577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}