{"id":3590,"date":"2016-08-22T08:00:12","date_gmt":"2016-08-22T07:00:12","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/apartirdelos50\/?p=3590"},"modified":"2016-08-22T08:00:12","modified_gmt":"2016-08-22T07:00:12","slug":"de-vuelta-a-la-playa","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/2016\/08\/22\/de-vuelta-a-la-playa\/","title":{"rendered":"De vuelta a la playa"},"content":{"rendered":"<p><span style=\"font-family: Verdana; font-size: large;\">\u00a0<a href=\"\/apartirdelos50\/wp-content\/uploads\/sites\/19\/2016\/08\/Sombrilla1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3595\" title=\"Sombrilla\" src=\"\/apartirdelos50\/wp-content\/uploads\/sites\/19\/2016\/08\/Sombrilla1.jpg\" alt=\"\" width=\"486\" height=\"648\" srcset=\"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-content\/uploads\/sites\/19\/2016\/08\/Sombrilla1.jpg 486w, https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-content\/uploads\/sites\/19\/2016\/08\/Sombrilla1-225x300.jpg 225w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><\/a><\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Una de las diferencias b\u00e1sicas entre el Cant\u00e1brico y el Mediterr\u00e1neo estriba en que en el primero no puedes sentarte a meditar cerca de la orilla por m\u00e1s de un rato relativamente corto: los paseantes te atropellar\u00e1n o la marea \u2013si es que est\u00e1 subiendo- te empapar\u00e1. Pero en el Mediterr\u00e1neo la cosa cambia sustancialmente; puedes sentarte casi con los pies metidos en el agua y no te avasallar\u00e1 una turbamulta paseante ni el agua dejar\u00e1 de mantener su ritmo cadencioso. Aqu\u00ed la gente pasea por el paseo mar\u00edtimo al caer la tarde y en la playa se limita a tomar el sol, jugar en el agua y dar de comer al due\u00f1o del chiringuito m\u00e1s cercano.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Esta situaci\u00f3n es perfecta para las personas que, como yo misma, van a la playa \u00fanicamente por el placer de oler el mar, escuchar el mar, contemplar el mar y ba\u00f1arse en \u00e9l. Dejarse llevar por esos sentidos corporales y que el \u00e1nimo se acomode a un pensamiento volandero o a la simple y sencilla divagaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Y observar a diestro y siniestro porque no es la playa el lugar id\u00f3neo \u2013a mi entender- para leer un libro (cualquier clase de libro). El reflejo del sol da\u00f1a la vista y el cansancio ocular aflora enseguida. Como revistas no leo y sudokus no hago y tampoco me expongo al sol en plan lagartija ni me quedo dormida no me queda otra que mirar al horizonte y perderme en enso\u00f1aciones.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Ayer mismo, de vuelta de dar un largo paseo por la orilla \u2013somos cuatro los paseantes a primer\u00edsimo hora de la ma\u00f1ana- fui observando que, a la altura de los hoteles que festonean la costa, la masa humana se concentra como si les acuciara la necesidad de agruparse frente a un hipot\u00e9tico enemigo. Un poco m\u00e1s all\u00e1, tan s\u00f3lo cincuenta metros, extensiones de playa limpia y virgen dormitan al sol sin pies que profanen la arena ni gritos que asusten a los cangrejos. \u00bfPor qu\u00e9 se hacina la gente cuando tiene la posibilidad de ubicarse en espacios grandes? \u00bfSer\u00e1 por miedo o por pura vagancia? Todos los rusos juntos. Todos los alemanes juntos. Los catalanes de la zona a la altura del aparcamiento. Los turistas nacionales, alrededor del chiringuito. Creo que le llaman \u201cefecto lapa\u201d.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Las tumbonas. Esos mamotretos que alguna empresa con monopolio municipal \u2013todas azules, todas cada a\u00f1o un poco m\u00e1s viejas- se alquilan al m\u00f3dico precio de 5\u20ac. Si te vas a casa y luego vuelves hay que volver a pagar el alquiler aunque sea en el mismo d\u00eda. Al filo de la ma\u00f1anita, cuando gusto de pasearme el entorno solitario y hermoso, observo a los \u201ctumboneros\u201d colocando su mercanc\u00eda, de dos en dos, en las mejores posiciones cerca de la orilla del mar y orientadas hacia el astro rey. Luego van llegando los de casa y protestan, \u201ceh, que la playa es p\u00fablica\u201d y van acomod\u00e1ndose alrededor de las solitarias y vac\u00edas tumbonas que est\u00e1n esperando a que alguna pareja de despistados abone los 10\u20ac correspondientes por tumbarse sobre una superficie pl\u00e1stica, oliendo a aceites de mil cuerpos pret\u00e9ritos. Las utilizan de otra manera los subsaharianos ilegales para esconderse debajo cuando asoman por el paseo los chalecos reflectantes de la guardia municipal de playas.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Ah\u00ed llegan: los vendedores ambulantes en la playa. Esa es otra y no de tama\u00f1o peque\u00f1o. Estando como est\u00e1 absolutamente prohibida la venta ambulante \u2013no s\u00f3lo en la playa sino en todo el pueblo- los pobres vendedores pululan por la arena ofreciendo sus mercanc\u00edas made in china pero con marcas francesas imitadas. Cuando se acostumbran dejan de mirar los pechos de las adoradoras de Helios y se dedican a lo suyo: a ganarse la comisi\u00f3n que la mafia de turno les ofrece por cada bolso, cartera, gafas o gorra vendida. Los municipales miran desde lejos y no hacen nada porque no tienen orden de hacer nada, lo que siempre me ha llevado a pensar si el tinglado de venta ambulante en la playa no est\u00e1 dirigido por alg\u00fan concejal con sonrisa de conejo por delante y muchos votos por detr\u00e1s. <\/span><span style=\"font-family: Verdana; font-size: large;\">Me desconcentran. Luego vienen las familias con sus ni\u00f1os y sus suegras y cu\u00f1adas \u2013que son las que m\u00e1s gritan despu\u00e9s de las madres. Los ni\u00f1os molestan bastante menos que sus mayores. <\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Es entonces cuando llega el momento de marcharme con viento fresco \u2013aunque en realidad sea bastante calentito- y cuando echo la \u00faltima mirada a la playa repleta, se me ocurre pensar que la crisis empuja al que no tiene dinero a disfrutar de un espacio l\u00fadico, hermoso y natural que es gratis a la vez que los hoteles est\u00e1n repletos hasta la bandera de for\u00e1neos que vienen a dejar sus dineros en esta tierra maltratada por tanto y por tantos.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">En fin.<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">LaAlquimista<\/span><\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">Por si alguien desea contactar:<\/span><\/p>\n<p><span style=\"font-size: large;\"><a><span style=\"font-family: Verdana;\">apartirdeloscincuenta@gmail.com<\/span><\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: Verdana; font-size: large;\">\u00a0<\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00a0 Una de las diferencias b\u00e1sicas entre el Cant\u00e1brico y el Mediterr\u00e1neo estriba en que en el primero no puedes sentarte a meditar cerca de la orilla por m\u00e1s de un rato relativamente corto: los paseantes te atropellar\u00e1n o la marea \u2013si es que est\u00e1 subiendo- te empapar\u00e1. Pero en el Mediterr\u00e1neo la cosa cambia [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3590","post","type-post","status-publish","format-standard","hentry","category-filosofia-de-vida-reflexiones"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/posts\/3590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/comments?post=3590"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/posts\/3590\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/media?parent=3590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/categories?post=3590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/apartirdelos50\/wp-json\/wp\/v2\/tags?post=3590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}