{"id":202,"date":"2015-02-12T10:29:12","date_gmt":"2015-02-12T09:29:12","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/desde-banquillo\/?p=202"},"modified":"2015-02-12T10:29:12","modified_gmt":"2015-02-12T09:29:12","slug":"cuanto-disfrute-viendo-al-barca-en-san-mames-barria","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/2015\/02\/12\/cuanto-disfrute-viendo-al-barca-en-san-mames-barria\/","title":{"rendered":"Cu\u00e1nto disfrut\u00e9 viendo al Bar\u00e7a en San Mam\u00e9s Barria"},"content":{"rendered":"<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A1-1819957003.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-203\" title=\"A1-1819957003\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A1-1819957003.jpg\" alt=\"\" width=\"1024\" height=\"722\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A1-1819957003.jpg 1275w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A1-1819957003-300x212.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A1-1819957003-768x542.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A1-1819957003-1024x723.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><br \/>\nBar Elizazu de mi amigo Manu Taboada. Sobre de la mesa un plato de jam\u00f3n exquisito y un caf\u00e9 con leche en vaso grande. Delante una tele fant\u00e1stica. Comienza el partido Athletic- Barsa. Cuando hablas de futbol y ves jugar al equipo cul\u00e9 inevitablemente aparece el bal\u00f3n como eje central del juego. En el f\u00fatbol de hoy en d\u00eda la velocidad la da el bal\u00f3n con su circulaci\u00f3n en continuos pases que no se pierden.\u00a0 Esta continuidad en el juego es la que te permite avanzar o circular sobre del terreno de juego de un lado para otro hasta que aparece la ocasi\u00f3n para buscar un pase al pasillo interior o exterior o bien a\u00a0 un centrocampista o a un lateral que den a su vez ese \u00faltimo pase para finalizar la jugada.<\/p>\n<p>Adem\u00e1s, con este juego combinativo y de posesion\u00a0 haces ir de culo, retroceder al equipo rival, aunque a veces parezca que no haces nada. Por esa raz\u00f3n interesa tanto tocar en el campo contrario y que los tres delanteros &#8211;<strong>Messi, Luis Suarez y Neymar<\/strong>&#8211; fijen bien a los cuatro defensas rivales en la salida de pelota. As\u00ed pueden robar el bal\u00f3n muy arriba para estar otra vez cerca de la porter\u00eda contraria con la intenci\u00f3n de hacer gol Fue una pasada ver estas acciones durante casi todo el Athletic de Bilbao -F. C. Barcelona.<\/p>\n<p>Fue ver a un equipo con una posesion del 73% o lo que es lo mismo, que\u00a0 tocaba,tocaba y tocaba. Pero no para retener el bal\u00f3n sino para pasarlo r\u00e1pido y as\u00ed matar al equipo adversario. Adem\u00e1s en este partido se vio una cosa muy clara: Cuando tienes la posesion, el bal\u00f3n ordena al poseedor y desordena -y de qu\u00e9 manera- al equipo rival.\u00a0 Esto se lo he o\u00eddo much\u00edsimas veces tanto al profe <strong>Juanma Lillo<\/strong> como al gran sabio<strong> Raul Caneda<\/strong>, ex entrenadores de la Real Sociedad. Aunque no lo parezca, con los pases rapidos te vas ordenando y al contrario lo vuelves loco, lo atontas, ya que se ven en un imposible de recuperar el bal\u00f3n para jugarlo ellos.<\/p>\n<p>Esto es posible porque los primeros que creen en este estilo de juego son los propios futbolistas. La dificultad est\u00e1 en saber c\u00f3mo seguir seduciendo a los jugadores para que acepten esta filosf\u00eda, que resulta fant\u00e1stica para unos y aburrida para los que el f\u00fatbol de este estilo no le gusta. En el Bar\u00e7a el f\u00fatbol combinativo y de posesion lleva mucho tiempo implantado desde la base a la c\u00faspide del equipo profesional, vamos que desde ni\u00f1os les inculcan este estilo de juego donde siempre debe de estar presente el bal\u00f3n.<\/p>\n<p>En este texto no me puedo olvidar de <strong>Leo Messi<\/strong>, yo en los 62 a\u00f1os que tengo no he visto mejor futbolista. Ya s\u00e9 que es cuesti\u00f3n de gustos y respeto el de todos, pero ver llevar la pelota pegada al pie, desbordando en carrera y tirando mu\u00f1ecos a un lado y al otro, dando pases que solo los inventa \u00e9l y ganado casi siempre los duelos individuales, es pura fantasia. Vamos, que es para quitarse el sombrero. A\u00fan tengo en la retina el gol que marc\u00f3 <strong>Pedro<\/strong> a pase de <strong>Busquets<\/strong>, en donde <em>la Pulga<\/em>, que pica despu\u00e9s de hacer un eslalom y un cambio de direcci\u00f3n dejando a cuatro jugadores desordenados, mete el pase a <strong>Sergio Busquets<\/strong> que se lo da a <strong>Pedro<\/strong> para que solo delante de portero lo aloje en las mallas de la porter\u00eda de San Mames Barria. Los aficionados bilba\u00ednos, como grandes entendidos al f\u00fatbol, despidieron a un equipo que realiz\u00f3 un partido extraordinario ante un rival que nunca se rindi\u00f3. Felicidades por la gran tarde de f\u00fatbol que nos dieron dos estilos muy diferentes pero muy validos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Bar Elizazu de mi amigo Manu Taboada. Sobre de la mesa un plato de jam\u00f3n exquisito y un caf\u00e9 con leche en vaso grande. Delante una tele fant\u00e1stica. Comienza el partido Athletic- Barsa. Cuando hablas de futbol y ves jugar al equipo cul\u00e9 inevitablemente aparece el bal\u00f3n como eje central del juego. En el f\u00fatbol [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-202","post","type-post","status-publish","format-standard","hentry","category-futbol"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/comments?post=202"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/202\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/media?parent=202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/categories?post=202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/tags?post=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}