{"id":206,"date":"2015-02-16T09:52:42","date_gmt":"2015-02-16T08:52:42","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/desde-banquillo\/?p=206"},"modified":"2015-02-16T09:52:42","modified_gmt":"2015-02-16T08:52:42","slug":"competir","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/2015\/02\/16\/competir\/","title":{"rendered":"Competir con lo que hay"},"content":{"rendered":"<p>Se hab\u00edan consumido las diez primeras jornadas de liga y la Real Sociedad hab\u00eda ingresado en la U.C.I. con claros signos de encefalograma plano ya que ocupaba el puesto 19 en la clasificaci\u00f3n, es decir, puesto de descenso. El conjunto realista, al que hasta la jornada 10 de liga entrenaba el entrenador de la casa <strong>Jagoba Arrasate<\/strong>, de los treinta puntos posibles solo consigui\u00f3 seis. Un paup\u00e9rrimo balance con unos registros que invitaban a pensar en lo peor. El consejo de administraci\u00f3n del club puso\u00a0 su maquinaria en marcha y trajo un entrenador con mucha personalidad. Seg\u00fan el presidente, un entrenador que cambie la mala din\u00e1mica del equipo en liga m\u00e1s el entramado de Zubieta.<\/p>\n<p>En la jornada 11 los t\u00e9cnicos del filial <strong>Asier Santana e Imanol Alguacil<\/strong> dirigieron al equipo ante el subcampe\u00f3n de Europa, el Atl\u00e9tico de Madrid del <strong>Cholo Simeone<\/strong>. Para traer al sr <strong>Moyes<\/strong> se esper\u00f3 una semana m\u00e1s para hacer las cosas con calma y con la importancia que merec\u00edan. Fue en el partido de Riazor ante el Deportivo de la Coru\u00f1a (0-0) cuando debut\u00f3 el t\u00e9cnico escoc\u00e9s. Despu\u00e9s de 12 jornadas con<strong> Moyes<\/strong> en el banquillo de la Real los n\u00fameros hasta el momento son los siguientes: tres partidos ganados -Elche, Bar\u00e7a y Eibar-; tres partidos perdidos -Villarreal, Rayo y Real Madrid- y la friolera de seis partidos empatados -Deportivo, Athletic, Levante, Granada, Celta y Almer\u00eda-, por lo que de\u00a0 treinta y seis puntos posibles solo se han sumado 15 puntos.<\/p>\n<p>Con esto que nadie crea que se acuse al sr <strong>Moyes<\/strong> de ser un entrenador que juega al empate, pues algunos partidos los ha ido ganando o empatando y se les han escapado los puntos en los \u00faltimos minutos del encuentro, como\u00a0 contra el Levante, Granada, Rayo o Celta. Todo esto es simplemente una cuesti\u00f3n de curiosidad estad\u00edstica. Sin m\u00e1s, futbol.<\/p>\n<p>Ya en un texto anterior comente que seg\u00fan diversos estudios, el cambio de entrenador cuesta una peque\u00f1a fortuna y que a medio plazo no tiende a mejorar el rendimiento deportivo de los equipos menos potentes. Y eso es lo que est\u00e1 ocurriendo, ya que si miramos la tabla clasificatoria eso equipos que cambiaron de entrenador ( Granada, Cordoba, Almeria, Getafe, Real Sociedad y Levante) no se les ha notado una mejor\u00eda, tanto en el juego como en la suma de puntos para salir de zona peligrosa.<\/p>\n<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A3-125287561.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-208\" title=\"A3-12528756\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A3-125287561.jpg\" alt=\"\" width=\"1024\" height=\"695\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A3-125287561.jpg 1326w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A3-125287561-300x204.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A3-125287561-768x521.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/A3-125287561-1024x695.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><br \/>\nEstamos teniendo muy mala fortuna con las lesiones de jugadores muy importantes (<strong>Vela, Carlos Mart\u00ednez, Mikel Gonz\u00e1lez, Zurutuza o Canales<\/strong>). Adem\u00e1s,\u00a0 ahora hay que tener en cuenta las cinco tarjetas de<strong> Yuri<\/strong> por lo que no podr\u00e1 jugar ante el Sevilla. Hay que contar y competir con los que hay. En estos momentos es tonter\u00eda acordarse de los que no est\u00e1n, ya que, primero, es un menosprecio a los menos habituales y, segundo, no se puede contar con ellos a la hora de confeccionar las alineaciones. As\u00ed que a competir con los que est\u00e1n disponibles y acertar con un once tipo de aqu\u00ed a final del campeonato, que puede ser de momento y hasta que se recuperen los lesionados: <strong>Rulli, Zaldua, Ansotegi, I\u00f1igo, De la Bella, Markel, Pardo, Prieto, Granero, Chory y Agirretxe<\/strong>. Equipo con equilibrio y calidad t\u00e9cnica.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Se hab\u00edan consumido las diez primeras jornadas de liga y la Real Sociedad hab\u00eda ingresado en la U.C.I. con claros signos de encefalograma plano ya que ocupaba el puesto 19 en la clasificaci\u00f3n, es decir, puesto de descenso. El conjunto realista, al que hasta la jornada 10 de liga entrenaba el entrenador de la casa [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-206","post","type-post","status-publish","format-standard","hentry","category-real-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/comments?post=206"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/206\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/media?parent=206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/categories?post=206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/tags?post=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}