{"id":210,"date":"2015-02-17T10:37:08","date_gmt":"2015-02-17T09:37:08","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/desde-banquillo\/?p=210"},"modified":"2015-02-17T10:37:08","modified_gmt":"2015-02-17T09:37:08","slug":"que-real-queremos","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/2015\/02\/17\/que-real-queremos\/","title":{"rendered":"\u00bfQu\u00e9 Real queremos?"},"content":{"rendered":"<p>Si nos vamos a la temporada 06\/07, que fue la campa\u00f1a en la que nuestro equipo baj\u00f3 a Segunda Divisi\u00f3n, nos encontramos que, por unos motivos o por otros y que b\u00e1sicamente eran las urgencias de no perder la categor\u00eda, en nuestra plantilla hab\u00eda la friolera de 16 jugadores for\u00e1neos en fichajes. Se los enumero: Bravo, Novo, Cifuentes, Fabio Felicio, Garitano, Gerardo, German Herrera, Jesuli, Juanito, Kovacevic, Rivas, Rosato, Savio, Skuobo, Stevanovic, V\u00edctor L\u00f3pez. Los entrenadores fueron primero Bakero y luego Lotina.<\/p>\n<p>En esta temporada los resultados fueron tan escasos que hubo rachas con Bakero en las que de 21 puntos posibles solo se sumaron 2 tras empatar con el Athletic y el Mallorca. Hubo otraracha y ya con Lotina en el banquillo de Anoeta en la que de 24 puntos posibles solo se suma 1 punto, cuando se empata ante el Sevilla. Vamos, que la Real vivi\u00f3 una temporada llena de desprop\u00f3sitos, tanto en resultados como en las incorporaciones por el miedo a irnos a Segunda Divisi\u00f3n.<\/p>\n<p>Una vez que entra en el cargo el presidente Aperribay\u00a0 el cambio de filosof\u00eda es inminente hacia un proyecto m\u00e1s austero y con la Real de siempre, la de toda la vida: cantera y\u00a0 cuatro fichajes que marcan las diferencias, que en aquella \u00e9poca no fueron cuatro sino ocho, aunque en este proyecto quedan muchos empleados por el camino ante la adversidad del aspecto econ\u00f3mico. Vamos, que est\u00e1bamos en proceso de desaparici\u00f3n y hab\u00eda que levantar aquello como fuera metiendo al equipo otra vez en la Primera Divisi\u00f3n. Y se consigui\u00f3 con un entrenador for\u00e1neo, Martin Lasarte, y con una plantilla en donde los for\u00e1neos eran ocho: Bravo, De la Bella, Rivas, Bueno, Jonathan Estrada, Sergio Rodriguez, N\u2019Sue, Songo\u2019o .<\/p>\n<p>Ya con el ascenso a la Liga BBVA o liga de las estrellas o la mejor liga del mundo y con el mismo entrenador al frente de la Real se confeciona una plantilla competitiva para el primer a\u00f1o y mantener al equipo en el lugar que debe estar siempre y que no es otro que la Primera Divisi\u00f3n. En aquel equipo militaban estos for\u00e1neos: Bravo, Rivas, De la Bella, Tamudo, Llorente, Demidov, Sutil, Sarpong y Diego Ifr\u00e1n. Otra vez ocho for\u00e1neos y el regreso del fichaje estrella, el canterano que vuelve a casa, Joseba Llorente. El equipo mantiene la categor\u00eda tras quedar en el puesto 15 de la clasificaci\u00f3n. Gracias a un empate en casa ante el Getafe nos aseguramos mantener la categor\u00eda.<\/p>\n<p>Despu\u00e9s de estas historias en varias temporadas el consejo da otra vuelta de tuerca y cambia el librode estilo y ficha a un entrenador franc\u00e9s, el sr Montanier. Luego apuesta por el continuismo de la metodolog\u00eda de trabajo que dio muy buenos resultados y se le da la oportunidad de su vida a un entrenador de la casa como Jagoba Arrasate, que es la apuesta del presidente. Tras la eliminaci\u00f3n del equipo de Europa y la mala racha de resultados en la liga regular Arrasate es destituido en la jornada 10.<\/p>\n<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0PKTL1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-211\" title=\"DOCU_DVA\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0PKTL1.jpg\" alt=\"\" width=\"1024\" height=\"655\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0PKTL1.jpg 1406w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0PKTL1-300x192.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0PKTL1-768x492.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0PKTL1-1024x655.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Ahora llega el proyecto del sr. Moyes, un entrenador con prestigio y con una gran personalidad que encandil\u00f3 al presidente. En su primera entrevista en El Diario Vasco Moyes lanza estas perlas: \u00ab Tengo clara la direcci\u00f3n a seguir en la Real y ahora quiero encontrar gente que me siga en ese camino\u00bb; \u00ab Creo en la filosof\u00eda de la Real y en el trabajo que se hace, pero no se si solo con la gente de Zubieta se puede competir al m\u00e1s alto nivel\u00bb; \u00abLo primero es siempre la cantera pero esa filosof\u00eda no puede ir en detrimento del equipo\u00bb. Y la \u00faltima perla: \u00abEs mejor ir a la Champions con pocos canteranos o terminar en el puesto 14 con muchos canteranos\u00bb.<\/p>\n<p>Ahora la pelota esta en el tejado del consejo y del m\u00edster o m\u00e1nager, ya que se deben sentar y planificar cu\u00e1l es el camino a seguir: si un equipo competitivo con buenos futbolistas para disputarle el puesto europeo al Atl\u00e9tico de Madrid, Villarreal, Valencia o Sevilla, o por el contrario seguimos apostando por la cantera con esos cuatro fichajes que marquen las diferencias y con una paciencia y un atrevimiento extraordinario para darle minutos a nuestros futbolistas potenciales. Esta segunda opci\u00f3n supone correr el riesgo de que cuando tengas futbolistas muy buenos como el caso de Illarra o Griezman vengan los grandes de la Liga o Europa y te los lleve. El debate est\u00e1 en manos de los componentes del consejo de administraci\u00f3n y sus accionistas para preguntarles qu\u00e9 Real Sociedad queremos. Esta forma seria la mejor opci\u00f3n para la implicaci\u00f3n de todos,\u00a0 incluidos los abonados.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Si nos vamos a la temporada 06\/07, que fue la campa\u00f1a en la que nuestro equipo baj\u00f3 a Segunda Divisi\u00f3n, nos encontramos que, por unos motivos o por otros y que b\u00e1sicamente eran las urgencias de no perder la categor\u00eda, en nuestra plantilla hab\u00eda la friolera de 16 jugadores for\u00e1neos en fichajes. Se los enumero: [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-210","post","type-post","status-publish","format-standard","hentry","category-real-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/comments?post=210"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/210\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/media?parent=210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/categories?post=210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/tags?post=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}