{"id":220,"date":"2015-02-25T08:56:07","date_gmt":"2015-02-25T07:56:07","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/desde-banquillo\/?p=220"},"modified":"2015-02-25T08:56:07","modified_gmt":"2015-02-25T07:56:07","slug":"modelos-futbol-cantera","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/2015\/02\/25\/modelos-futbol-cantera\/","title":{"rendered":"Los diferentes modelos de f\u00fatbol cantera"},"content":{"rendered":"<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0P1NS1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-221\" title=\"DOCU_DVA\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0P1NS1.jpg\" alt=\"\" width=\"1024\" height=\"731\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0P1NS1.jpg 1260w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0P1NS1-300x214.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0P1NS1-768x549.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/02\/DF0P1NS1-1024x731.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><br \/>\nEl proceso de selecci\u00f3n de los jugadores potenciales en el f\u00fatbol base y en el f\u00fatbol profesional ha cobrado una enorme importancia en los \u00faltimos a\u00f1os y se debe principalmente a diferentes circunstancias que han propiciado que este trabajo haya tomado una gran relevancia. La reducci\u00f3n en la inversi\u00f3n realizada por los clubes en la compra de futbolistas, detectando e incorporando a estos en edades m\u00e1s tempranas y en las que su precio de mercado es much\u00edsimo inferior\u00a0 al que tendr\u00edan\u00a0 una vez consagrados como futbolistas muy buenos. Este hecho est\u00e1 experimentado una mayor importancia actualmente por la crisis econ\u00f3mica, que afecta a todos los pa\u00edses del mundo del f\u00fatbol. El nuestro no es nada ajeno a este gran problema.<\/p>\n<p>Los equipos profesionales y los componentes que integran los grupos de trabajo dedicados a la formaci\u00f3n del futuro jugador para llegar desde la base a la c\u00faspide cada vez tienen m\u00e1s preocupaci\u00f3n en torno a este tema, ya desde los inicios de su carrera deportiva, porque desde la incorporaci\u00f3n en edades tempranas hasta llegar al primer equipo el futbolista deber\u00e1 cubrir un camino largo, duro y lleno de dificultades de todo tipo.<\/p>\n<p>La Real Sociedad tiene una red de informadores en Gipuzkoa, Alava, La Rioja, Iparralde y Navarra en donde se ven partidos, y los jugadores m\u00e1s potenciales detectados hacen sus respectivas pruebas en la ciudad deportiva de Zubieta. Los que pasan el corte se incorporan a los equipos de la base: infantiles, cadetes o juveniles. Tambi\u00e9n hay ocasiones en las que el jugador es captado para jugar en el segundo equipo, el Sanse. Ah\u00ed est\u00e1n los recientes casos de Callens, He\u00e9tor, Bispo o Abu Diarra. Se trata de jugadores for\u00e1neos que ocupan puestos que en ese momento en el f\u00fatbol base no hay o no salen. En esta apuesta tenemos verdadera mala fortuna, ya que desde la temporada 2008-09 a la 2014-15 en el primer equipo s\u00f3lo han jugado el argelino-franc\u00e9s <strong>Cadamuro<\/strong> -ahora est\u00e1 cedido en Osasuna tras tener muy poca regularidad en la Real- ,\u00a0 <strong>Sio<\/strong>, que tuvo alguna aparici\u00f3n espor\u00e1dica y<strong> Callens<\/strong>, que este a\u00f1o ha debutado en un partido de Copa. Las incorporaciones en este periodo fueron: <strong>Arkaitz P\u00e9rez, Morgado, Cadamuro, Sio, Cristian Mej\u00edas, Mandaluniz, Nanizayamo, Callens, Aketxe, Joan Pons, Fuchs, H\u00e9ctor, Abu Diarra y Bispo<\/strong>.<\/p>\n<p>Hay un modelo de cantera que muchos equipos suelen hacer, sobre todo los grandes, que con mucho orgullo suelen presumir de f\u00fatbol formaci\u00f3n y cantera y no lo es para mi opini\u00f3n, ya que lo que hacen es captar a jugadores de diversos pa\u00edses en edades muy tempranas y incorporarlos en sus equipos de base y entrenarlos en su metodolog\u00eda de trabajo.<\/p>\n<p>Por \u00faltimo, ha surgido otro estilo de captaci\u00f3n-negocio en el que hay equipos que incorporan a jugadores entre los 18 a los veinte y pico a\u00f1os. Se trata de futbolistas potenciales que los firman como un fondo de inversi\u00f3n, ya que les cuestan poco dinero y si le salen muy buenos los venden por mucho m\u00e1s. Con ese dinero seguir\u00e1n invirtiendo en el f\u00fatbol formaci\u00f3n, que cuesta a cada equipo un past\u00f3n. Como ven varios modelos y muy v\u00e1lidos. Para algunos una casta\u00f1a por su poco acierto y para otros un negocio redondo.<br \/>\n<!--DOCTY--><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El proceso de selecci\u00f3n de los jugadores potenciales en el f\u00fatbol base y en el f\u00fatbol profesional ha cobrado una enorme importancia en los \u00faltimos a\u00f1os y se debe principalmente a diferentes circunstancias que han propiciado que este trabajo haya tomado una gran relevancia. La reducci\u00f3n en la inversi\u00f3n realizada por los clubes en la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4,5],"tags":[],"class_list":["post-220","post","type-post","status-publish","format-standard","hentry","category-futbol","category-real-sociedad","category-real-sociedad-b"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/comments?post=220"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/220\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/media?parent=220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/categories?post=220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/tags?post=220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}