{"id":247,"date":"2015-03-18T07:28:55","date_gmt":"2015-03-18T06:28:55","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/desde-banquillo\/?p=247"},"modified":"2015-03-18T07:28:55","modified_gmt":"2015-03-18T06:28:55","slug":"carmelo-amas","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/2015\/03\/18\/carmelo-amas\/","title":{"rendered":"Carmelo Amas, forjador de futbolistas"},"content":{"rendered":"<p>En mis primeros a\u00f1os de entrenador con los t\u00edtulos de juvenil y regional terminados -el nacional lo logr\u00e9 m\u00e1s tarde en Albacete- estaba al frente del Lagun Onak juvenil. La plantilla estaba compuesta por unos futbolistas azpeitiarras fant\u00e1sticos: los porteros <strong>Ignacio<\/strong> y <strong>Ram\u00f3n<\/strong> y los jugadores de campo <strong>Larra\u00f1aga, Aitor, Oscar, Iribar, Iriarte, Jaime Lizarralde, Manterola, Beitia, Yulen, Imanol, San Sebasti\u00e1n, Amenabar y Campatza<\/strong>. El equipo juvenil de la Real Sociedad lo entrenaba <strong>Artajo<\/strong> y en el jugaban, entre otros,\u00a0 <strong>Idiakez, Gorosabel, Yubero<\/strong> (DEP) <strong>Aranzabal, Garagartza, Goiko<\/strong> -un medio centro de Mendaro fant\u00e1stico-. Para el torneo de Semana Santa fue seleccionado <strong>Jaime Lizarralde<\/strong>, un jugador como la copa de un pino y al que yo lo recog\u00eda en Azpeitia y lo llevaba a entrenar en el hip\u00f3dromo con el gran y admirado <strong>Xabier Exposito<\/strong>. Por cierto, que como hoy en d\u00eda hace <strong>Moyes<\/strong> entrenaba a puerta cerrada y no dejaba ver los entrenamientos de los seleccionados para dicho torneo. El torneo lo gan\u00f3 la Real Sociedad ante rivales como el F.C. Barcelona de <strong>Busquets, Coto, Iago Falque, Illa, Mi\u00f1o, Rochina, Rueda, Abraham,Toribio o Verd\u00fa.<\/strong> Se dej\u00f3 por el camino al Villarreal y al\u00a0 Ajax. La final se jug\u00f3 ante el Rosenborg y\u00a0 se gan\u00f3 (2-1) gracias a los goles marcados por <strong>Errasti<\/strong> &#8211; hoy en el Eibar- y <strong>Julen Colinas<\/strong> -que actualmente juega en el Toledo-. Qu\u00e9 recuerdos m\u00e1s fant\u00e1sticos. Siempre Gipuzkoa y los entrenadores que nos sentimos gipuzcoanos trabajando para la Real Sociedad como maximo objetivo y por el de los futbolistas.<\/p>\n<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/1F143T31.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-248\" title=\"1F143T31\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/1F143T31.jpg\" alt=\"\" width=\"1024\" height=\"710\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/1F143T31.jpg 1297w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/1F143T31-300x208.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/1F143T31-768x533.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/1F143T31-1024x711.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>En ese futbol que tambien existe surge la figura de un hombre que quiero recordar con cari\u00f1o y admiraci\u00f3n:\u00a0 <strong>Carmelo Amas.\u00a0<\/strong> Recuerdo que all\u00e1 por 1973 le vi jugar en la Real de\u00a0 Rafa Iriondo, en el viejo e inolvidable Atotxa. Una joya donostiarra. La delantera blanquiazul estaba formada por <strong>Araquistain, Amas, Ansola (DEP), Urresti y Boronat<\/strong>. Tambi\u00e9n form\u00f3 parte de la m\u00edtica delantera del Espanyol de los cinco delfines:<strong> Amas, Marcial, Re, Rodilla y Jose Mar\u00eda<\/strong>.\u00a0 En 1976 y una vez acabada su carrera de futbolista sigue vinculado a la Real Sociedad haci\u00e9ndose cargo del equipo juvenil durante m\u00e1s de dos d\u00e9cadas, que se dice pronto. En\u00a0 junio de 1999 en cuando se realiza su despedida del equipo realista, homenaje en Anoeta incluido.<\/p>\n<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00W542.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-249\" title=\"FOTO DIARIO VASCO-2.JPG\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00W542.jpg\" alt=\"\" width=\"1024\" height=\"645\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00W542.jpg 1358w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00W542-300x189.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00W542-768x484.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00W542-1024x645.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><br \/>\nPor sus manos pasaron futuras estrellas del equipo txuri urdin y muchos jugadores internacionales en categor\u00edas inferiores. Con <strong>Xabier Exposito<\/strong>, que fue su descubridor como futbolista cuandolo fich\u00f3 de los playeros para su A\u00f1orga querido, tuvo la oportunidad de trabajar le en el primer equipo en la temporada 91-92 . Fue el segundo de abordo. Dirigieron al equipo durante veinte partidos de liga y salvaron la categor\u00eda de forma brillante venciendo en los campos de Mestalla, Nou Camp y Bernabe\u00fa, que no es poco. Como colof\u00f3n a su extaordinaria trayectoria en el equipo de sus amores logro ganar dos\u00a0 Copa de Campeones de Espa\u00f1a de juveniles en dos ocasiones consecutivas en las temporadas ,97-98 y la 98-99,, si mal no recuerdo. En aquellos equipos jugaban jugadores como <strong>Llorente, Jaka, Gurrutxaga, Labaka, Gabilondo <\/strong>o<strong> Sergio Francisco<\/strong>.<\/p>\n<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00CF51.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-250\" title=\"FINAL COPA DE CAMPEONES JUVENILES\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00CF51.jpg\" alt=\"\" width=\"1024\" height=\"680\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00CF51.jpg 1354w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00CF51-300x199.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00CF51-768x510.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/03\/DF00CF51-1024x681.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Resumiendo. Hoy mi m\u00e1s sentido homenaje es para un hombre de f\u00fatbol con un curriculum fant\u00e1stico labrado en los dos equipos de sus amores: la\u00a0 Real Sociedad senior y la Real Sociedad juvenil.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En mis primeros a\u00f1os de entrenador con los t\u00edtulos de juvenil y regional terminados -el nacional lo logr\u00e9 m\u00e1s tarde en Albacete- estaba al frente del Lagun Onak juvenil. La plantilla estaba compuesta por unos futbolistas azpeitiarras fant\u00e1sticos: los porteros Ignacio y Ram\u00f3n y los jugadores de campo Larra\u00f1aga, Aitor, Oscar, Iribar, Iriarte, Jaime Lizarralde, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-247","post","type-post","status-publish","format-standard","hentry","category-real-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/comments?post=247"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/247\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/media?parent=247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/categories?post=247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/tags?post=247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}