{"id":360,"date":"2015-06-25T12:25:44","date_gmt":"2015-06-25T10:25:44","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/desde-banquillo\/?p=360"},"modified":"2015-06-25T12:25:44","modified_gmt":"2015-06-25T10:25:44","slug":"las-palmas-primera","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/2015\/06\/25\/las-palmas-primera\/","title":{"rendered":"Orgullo canari\u00f3n, Las Palmas vuelve a Primera"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-361\" title=\"UD LAS PALMAS - ZARAGOZA\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas.jpg\" alt=\"\" width=\"1024\" height=\"680\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas.jpg 3021w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas-300x199.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas-768x510.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas-1024x680.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><br \/>\nEl pasado domingo en la isla redonda el f\u00fatbol se convirti\u00f3 en una felicidad sublime y en patrimonio de la afici\u00f3n amarilla y de todos los estamentos de la U.D. Las Palmas. Y todo esto a cuenta de un ascenso muy merecido pero tambi\u00e9n ag\u00f3nico ya que el gol que pon\u00eda a los p\u00edo p\u00edo en la mejor liga del mundo lleg\u00f3 en el minuto 85 cuando<strong> Viera<\/strong> &#8211; el <strong>Romario<\/strong> canarion- aprovech\u00f3 una salida a destiempo del portero <strong>Bono<\/strong> y le rob\u00f3 la cartera con la testa a\u00a0 <strong>David Garc\u00eda<\/strong>, la acrob\u00e1tica chilena <strong>Aythami<\/strong> termin\u00f3 con el bal\u00f3n rodando por todo el larguero para que el m\u00e1s listo, el m\u00e1s espabilado, el que est\u00e1 en todos los balones sueltos, el &#8216;chino&#8217; <strong>Araujo<\/strong> la colara en la porter\u00eda ma\u00f1a y provocara una explosi\u00f3n de j\u00fabilo en todo el grader\u00edo amarillo.<\/p>\n<p><strong>Paco Herrera<\/strong> apost\u00f3 por la veteran\u00eda y acert\u00f3, ya que el encuentro que se jugaba ped\u00eda marcar dos goles y mantener la porter\u00eda a cero . Tom\u00f3 la decisi\u00f3n de colocar en la porter\u00eda a <strong>Casto,<\/strong> portero con galones y m\u00e1s acostumbrado a estas finales. <strong>David Sim\u00f3n, David Garc\u00eda, Aythamy, Angel, Javi Castellanos, Roque, Culio, Asdrubal, Araujo, y Jonathan Viera<\/strong> completaron la alineaci\u00f3n. Filosof\u00eda canaria, ni m\u00e1s ni menos: ocho jugadores canariones m\u00e1s tres mejores que lo que tenemos en casa:\u00a0 <strong>Casto, Culio<\/strong> y el &#8216;chino&#8217; <strong>Araujo<\/strong>. Cuando comenz\u00f3 a rodar el bal\u00f3n se vio qui\u00e9n quer\u00eda ascender. La U.D. Las Palmas lo demostr\u00f3 con una gran interpretaci\u00f3n del juego a desarrollar y con dos abastecedores de balones a las espaldas de los centrales ma\u00f1os. <strong>Araujo<\/strong> trajo en jaque a la defensa zaragocista y para los ma\u00f1os fue un aut\u00e9ntico dolor de cabeza durante todo el encuentro. Estamos ante un jugador diferente y con un futuro muy prometedor. En el aspecto defensivo y desde <strong>Javi Castellanos<\/strong> hacia atr\u00e1s, el equipo\u00a0 fue un aut\u00e9ntico valladar y tanto en el primer como en el segundo acto el portero <strong>Casto<\/strong> fue un mero espectador. Aunque tambi\u00e9n hay que reconocer que con el cero a cero en el marcador, entre <strong>Culio<\/strong> y el larguero devolvieron el bal\u00f3n al campo tras un saque de esquina. \u00a1Qu\u00e9 sudor m\u00e1s fr\u00edo recorri\u00f3 la frente de los 28.500 espectadores canariones! El resto fue un dominio apabullante de los entrenados y dirigidos por<strong> Paco Herrera<\/strong>.<\/p>\n<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-362\" title=\"UD LAS PALMAS - ZARAGOZA\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas_1.jpg\" alt=\"\" width=\"1024\" height=\"697\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas_1.jpg 3048w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas_1-300x204.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas_1-768x523.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/06\/laspalmas_1-1024x697.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>El \u00faltimo ascenso a Primera Divisi\u00f3n se logr\u00f3 en la temporada 1999-2000 de la mano del croata <strong>Sergio Kresic. <\/strong>Los p\u00edo p\u00edo\u00a0 se proclamaron campeones de Segunda Divisi\u00f3n tras ganar al Elche (4-1) en\u00a0 la \u00faltima jornada en un\u00a0\u00a0 encuentro disputado en el antiguo Estadio Insular. Fue una tarde inolvidable y apote\u00f3sica. Los aficionados saltaron al terreno de juego para festejar el ascenso y aquel d\u00eda debut\u00f3 tambi\u00e9n un fant\u00e1stico futbolista como lo fue <strong>Jorge Larena<\/strong>.<\/p>\n<p>Y ha que destacar tambi\u00e9n a la afici\u00f3n canariona, ya que lo mismo que las olas acarician la arena de las canteras los aficionados\u00a0 amarillos se desplazaron en oleadas desde el antiguo y hoy parque Estadio Insular hasta el campo de Siete palmas. Lo hicieron con fervor, ilusi\u00f3n, sentimiento, pasi\u00f3n y no dejaron nunca solo al equipo. Ya lo demostraron en el recibimiento a las tres de la madrugada que dieron al equipo tras llegar de Zaragoza con un tres a uno muy dif\u00edcil de superar. Pero ellos creyeron y as\u00ed les sali\u00f3. Con el pitido final todo la felicidad se desbord\u00f3 y los aficionados mantuvieron un comportamiento ejemplar con las bufandas y banderas al viento y cantando\u00a0 sin cesar el:\u00a0 \u00absoy de Las Palmas, el amarillo de la camiseta es el color de la arena de las canteras y el azul del pantal\u00f3n es el ancho oc\u00e9ano que nos rodea\u00bb. As\u00ed que el pr\u00f3ximo curso veremos el buen gusto por el toque y por la continuidad en el juego de esa universidad que siempre fue el f\u00fatbol canario de los malogrados <strong>Tonono<\/strong>, <strong>Guedes<\/strong> y los porteros guipuzcoanos <strong>Oregi<\/strong> y <strong>Ulacia<\/strong>. Gano el f\u00fatbol con el ascenso de un m\u00edtico: la U.D. Las Palmas. Felicidades<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; El pasado domingo en la isla redonda el f\u00fatbol se convirti\u00f3 en una felicidad sublime y en patrimonio de la afici\u00f3n amarilla y de todos los estamentos de la U.D. Las Palmas. Y todo esto a cuenta de un ascenso muy merecido pero tambi\u00e9n ag\u00f3nico ya que el gol que pon\u00eda a los p\u00edo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-360","post","type-post","status-publish","format-standard","hentry","category-futbol"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/comments?post=360"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/360\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/media?parent=360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/categories?post=360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/tags?post=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}