{"id":404,"date":"2015-09-14T11:37:49","date_gmt":"2015-09-14T09:37:49","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/desde-banquillo\/?p=404"},"modified":"2015-09-14T11:37:49","modified_gmt":"2015-09-14T09:37:49","slug":"futbol-futbolistas","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/2015\/09\/14\/futbol-futbolistas\/","title":{"rendered":"El f\u00fatbol es de los futbolistas"},"content":{"rendered":"<p>El verano de 2015 ser\u00e1 catalogado y recordado por los accionistas, abonados y aficionados realistas como un veranito movidito en lo puramente referido al f\u00fatbol. Y es que hemos tenido culebrones como en las series de novela mexicana. Primero fue el caso interminable del arquero <strong>Rulli<\/strong>. Hubo final feliz, ya que \u00e9l puso todo de su parte para quedarse en el equipo donostiarra. M\u00e1s tarde vino el reencuentro del fichaje m\u00e1s esperado y no fue otro que la vuelta desde el mism\u00edsimo Real Madrid de <strong>Asier Illarramendi<\/strong>. Este fichaje no estuvo exento de dimes y diretes. Para unos es un futbolista con poca ambici\u00f3n, ya que deber\u00eda jugar en una liga como la inglesa o la italiana antes de volver a la Real. Otros est\u00e1n m\u00e1s contentos que unas casta\u00f1uelas porque era el futbolista que nos faltaba. Como siempre ocurre en el\u00a0 f\u00fatbol todos damos nuestro punto de vista. Nada nuevo en la oficina.<\/p>\n<p>Es verdad que el presidente y consejo de administraci\u00f3n realista ha hecho una gran inversi\u00f3n en lo deportivo, pero la realidad es que solo se ha firmado en propiedad a <strong>Jonathas<\/strong> e <strong>Illarra<\/strong>. David Concha ha salido cedido al Numancia y tambi\u00e9n han llegado\u00a0 <strong>Babic<\/strong> y <strong>Kevin<\/strong> para el Sanse. Las dem\u00e1s son incorporaciones en modalidad cesi\u00f3n: <strong>Rulli, Oier Olaz\u00e1bal, Bruma <\/strong>y<strong> Reyes<\/strong>.<\/p>\n<p>Para actuar y defender uno de los puestos de m\u00e1s responsabilidad en el equipo, es decir en la porter\u00eda, firmamos a dos guardametas y los dos en forma de cesi\u00f3n por parte del grupo Maldonado y del Granada. Es una f\u00f3rmula que permite hacier tiempo para que crezcan los potrillos del Sanse, es decir, <strong>Rulli<\/strong> si triunfa el fondo lo llevar\u00e1 a un equipo de campanillas y <strong>Oier,<\/strong> con una opci\u00f3n de derecho a compra.<\/p>\n<p>En la l\u00ednea de cuatro atr\u00e1s o zona de preparaci\u00f3n y de m\u00e1xima seguridad defensiva, en la cual tenemos seis laterales y cinco centrales, firmamos en calidad de cesi\u00f3n sin opci\u00f3n de compra al central mexicano <strong>Reyes<\/strong>. Tampoco hay que olvidar la llegada de <strong>Ra\u00fal Navas<\/strong>, reci\u00e9n operado y jugador cedido en el Eibar el curso anterior.<\/p>\n<p>Para jugar por afuera, es decir por banda, se firma a un futbolista con las caracter\u00edsticas que le gusta al m\u00edster:\u00a0 veloz y\u00a0 con buen \u00faltimo pase. Se trata de <strong>Bruma<\/strong>, guineano con nacionalidad portuguesa que viene cedido del Galatasaray. La Real tiene una opci\u00f3n de compra sobre \u00e9l que ronda los ocho millones de euros. Tambi\u00e9n se firma a <strong>David Concha<\/strong>, una promesa emergente del Racing de Santander que jugar\u00e1 cedido en nuestra sucursal de Soria, el Numancia donde entrenan los ex realistas <strong>Arrasate<\/strong> y <strong>Alkiza<\/strong>. All\u00ed tambi\u00e9n coincidir\u00e1 con <strong>Jon Gazta\u00f1aga<\/strong>, el medio centro de car\u00e1cter defensivo que para m\u00ed no se tuvo que ir, ya que solo de esas caracter\u00edsticas tenemos a<strong> Markel<\/strong>.<\/p>\n<p>Y para el puesto m\u00e1s determinante,\u00a0 es decir para el que mete goles y da puntos, se firma a <strong>Jonathas<\/strong> que viene con el cartel de los 14 goles del curso anterior en las 35 jornadas que disput\u00f3 con el Elche. Sobre el papel buen futbolista . Ahora se le pide rendimiento y goles. Para eso se firm\u00f3. Aunque tambi\u00e9n siento la poca confianza depositada en el canterano <strong>Imanol Agirretxe<\/strong> que ve que llega otro delantero para competir con \u00e9l . \u00bfCu\u00e1ntos van ya? Sin m\u00e1s. F\u00fatbol profesional.<\/p>\n<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/09\/jonathas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-405\" title=\"A1-46446856.JPG\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/09\/jonathas.jpg\" alt=\"\" width=\"1024\" height=\"731\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/09\/jonathas.jpg 1260w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/09\/jonathas-300x214.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/09\/jonathas-768x549.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/09\/jonathas-1024x731.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>El mister escoc\u00e9s <strong>David Moyes<\/strong> cuenta con una de las plantillas m\u00e1s amplias y m\u00e1s caras de la historia de la Real Sociedad y dispone, ni m\u00e1s ni menos, que de 25 futbolistas, pero adem\u00e1s al tener al Sanse como equipo dependiente los menores de 23 a\u00f1os tambi\u00e9n los puede utilizar,\u00a0 como el reciente caso del lateral<strong> Aritz Elustondo<\/strong> ante el Sporting de Gij\u00f3n y el Betis. Tambi\u00e9n verdad que estos 25 jugadores van a tener una competencia feroz y brutal para poder colarse en el equipo titular o dentro de la convocatoria de 18 de todos los fines de semana. Si no me fallan las cuentas y no hay sanciones o lesiones sobran 6 o 7 futbolistas que se quedan fuera o sin viajar. Esto es todo un lujo. Hay competencia pero tambi\u00e9n queremos exigencia al staff t\u00e9cnico y a los futbolistas.<\/p>\n<p>En el \u00faltimo minuto del cierre del mercado se valoro la salida de <strong>Mikel Gonz\u00e1lez<\/strong> al Villarreal y el <strong>Chory<\/strong> en su \u00faltimo a\u00f1o de ficha tuvo ofertas pero muy poco jugosas. Tambi\u00e9n a <strong>Ra\u00fal Navas<\/strong> lo quiso el Sporting de Gij\u00f3n paro no pod\u00eda ser. En un final fren\u00e9tico de dimes y diretes son\u00f3 por Donosti la salida de <strong>Esteban Granero<\/strong>, ya que se ve muy titular a <strong>Illarra<\/strong>.<\/p>\n<p>Amigos, el reto es grande ya que el valor y los sueldos de este plantel son alto y no me olvido de los del mister, que es top. Este Consejo puso toda su maquinaria para confeccionar esta gran plantilla de jugadores. Como ocurre en los toros, en los partidos jugados hay diversidad de opiniones: unos que hemos perdido cuatro puntos, otros que la liga en Donosti comienza despu\u00e9s de las regatas y quienes piensan que hay que tener paciencia. Este reto y este objetivo lo deben cumplir ellos, los \u00fanicos protagonistas, los futbolistas. Todo lo que no sea estar en competici\u00f3n europea es una gran decepci\u00f3n para una afici\u00f3n que nunca falla y se entrega en cada partido demostr\u00e1ndolo continuamente. Sin m\u00e1s, el f\u00fatbol es de los futbolistas y si son buenos el objetivo est\u00e1 m\u00e1s cerca. Solo falta demostrarlo.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El verano de 2015 ser\u00e1 catalogado y recordado por los accionistas, abonados y aficionados realistas como un veranito movidito en lo puramente referido al f\u00fatbol. Y es que hemos tenido culebrones como en las series de novela mexicana. Primero fue el caso interminable del arquero Rulli. Hubo final feliz, ya que \u00e9l puso todo de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-404","post","type-post","status-publish","format-standard","hentry","category-real-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/comments?post=404"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/404\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/media?parent=404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/categories?post=404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/tags?post=404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}