{"id":442,"date":"2015-10-14T14:21:53","date_gmt":"2015-10-14T12:21:53","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/desde-banquillo\/?p=442"},"modified":"2015-10-14T14:21:53","modified_gmt":"2015-10-14T12:21:53","slug":"prueba-fiabilidad","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/2015\/10\/14\/prueba-fiabilidad\/","title":{"rendered":"Prueba de fiabilidad"},"content":{"rendered":"<p>Los tres primeros partidos de la Real Sociedad como equipo local est\u00e1n poniendo en duda y en entredicho la fortaleza de los blanquiazules en el coqueto estadio de Anoeta, ya que ante el Sporting, Espa\u00f1ol y Athletic el equipo solo fue capaz de sumar la p\u00edrrica cifra de dos puntos de los posibles nueve puntos posibles que estaban en juego.<\/p>\n<p>Vamos a comentarlo bien. El empate a cero ante el reci\u00e9n ascendido Sporting, m\u00e1s la derrota ante un Espa\u00f1ol inferior al de la pasada temporada y otro empate sin goles ante el eterno rival el Athletic en el famoso derbi vasco, han provocado un d\u00e9ficit donde donde parec\u00eda que pod\u00eda ser m\u00e1s fiable el equipo del escoc\u00e9s<strong> Moyes<\/strong>.<\/p>\n<p>La competici\u00f3n se par\u00f3 el pasado fin de semana por el tema de las selecciones nacionales y los clubes volver\u00e1n a competir al m\u00e1ximo nivel el pr\u00f3ximo. Los blanquiazules lo har\u00e1n\u00a0 m\u00e1s recuperaditos y m\u00e1s descansaditos, ya que la plantilla tuvo tres d\u00edas de fiesta -viernes, s\u00e1bado y domingo- y el lunes el equipo entren\u00f3 por la tarde en Zubieta para que les diese tiempo a todos a volver a Gipuzkoa.\u00a0 Como entrenador me pregunto si, estando como estamos y sin m\u00e1s rubor, es conveniente dar\u00a0 tres d\u00edas de fiesta. Adem\u00e1s, hay que tener en cuenta que hay futbolistas lesionados que recuperar y otros que a\u00fan no han competido ni un minuto,\u00a0 como <strong>Carlos Mart\u00ednez, Anso, H\u00e9ctor, Alain, Yuri <\/strong>y <strong>Ra\u00fal Navas, <\/strong>que se recupera de una operaci\u00f3n de pubis. Sin m\u00e1s, planificaci\u00f3n del mister y gustos.<\/p>\n<p>Otro de los problemas que estamos padeciendo en forma de lesi\u00f3n desde el inicio de la pretemporada son las lesiones musculares -casi todas roturitas de fibras- que est\u00e1n cortando de ra\u00edz la posibilidad de coger un correcto ritmo de competici\u00f3n a los futbolistas que las han padecido. Malditas lesiones, pero as\u00ed es el f\u00fatbol.<\/p>\n<p>Se reanuda la competici\u00f3n y pr\u00f3ximo rival ser\u00e1\u00a0 el Atl\u00e9tico de Madrid de<strong> Antoine Griezmann<\/strong> y <strong>&#8216;Cholo&#8217; Simeone<\/strong>, un equipo intenso, rocoso, competitivo y que juega cada bal\u00f3n al l\u00edmite de la ley. Es uno de los elegidos para estar en los puestos cabeceros al final de liga y nos va a dar el verdadero nivel de la plantilla que hemos confeccionado.<\/p>\n<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/10\/DF0PKGR1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-443\" title=\"DOCU_DVA\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/10\/DF0PKGR1.jpg\" alt=\"\" width=\"1024\" height=\"670\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/10\/DF0PKGR1.jpg 2628w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/10\/DF0PKGR1-300x196.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/10\/DF0PKGR1-768x503.jpg 768w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2015\/10\/DF0PKGR1-1024x671.jpg 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>En f\u00fatbol el aval de los resultados te invita como entrenador a dar continuidad a lo que funciona bien y no cambiarlo. Las dos \u00faltimas alineaciones de <strong>Moyes<\/strong> -ante Athletic y M\u00e1laga- fueron las mismas y se lograron resultados m\u00e1s negativos que positivos:\u00a0 un empate en casa y una derrota fuera. Ahora nos queda la duda de\u00a0 si continuar\u00e1 con el mismo once o cambiar\u00e1, sobre todo, la l\u00ednea por delante de los dos m\u00e9dios centros que forman <strong>Illarra<\/strong> y <strong>Rub\u00e9n Pardo<\/strong>. Esos puestos son los que tiene m\u00e1s preocupado al mister por la poca efectividad cara a gol y por el escaso f\u00fatbol combinativo que ha realizado el equipo.<\/p>\n<p>Estamos ante una semana de inquietudes, ya que todos esperamos ver las intenciones del m\u00edster para un partido muy intenso sobre el papel y que requiere el compromiso y la implicaci\u00f3n de los once futbolistas que salten al verde de Anoeta. El objetivo no es otro que darle a los sufridores aficionados una alegr\u00eda ante un gallito de esta liga y que disfruten de un buen partido de f\u00fatbol y goles. Recuerdo que la temporada anterior tras la destituci\u00f3n de <strong>Arrasate<\/strong> y mientras se esperaba a <strong>Moyes<\/strong>, se le dio la oportunidad en el banquillo a dos hombres de la casa como <strong>Alguacil<\/strong> y <strong>Santana<\/strong>, que contaron con el apoyo en la sombra del staff t\u00e9cnico. En el mejor partido de la temporada la Real Sociedad venci\u00f3 a los colchoneros por dos goles a uno. As\u00ed que los futbolistas ya saben el camino y, adem\u00e1s, tenemos mejor plantilla que la campa\u00f1a pasada. Solo queda por ver si se atrever\u00e1 mister <strong>Moyes<\/strong> a jugar por delante de los dos m\u00e9dios centros con <strong>Vela<\/strong> y <strong>Canales<\/strong> por afuera y con dos atacantes como <strong>Agirretxe<\/strong> y <strong>Jonathas<\/strong>. De lo que s\u00ed estoy seguro es de que el equipo saltar\u00e1 al verde motivad\u00edsimo y muy enchufado. Que llegue ya el d\u00eda del partidazo Real Sociedad &#8211; Atl\u00e9tico de Madrid.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los tres primeros partidos de la Real Sociedad como equipo local est\u00e1n poniendo en duda y en entredicho la fortaleza de los blanquiazules en el coqueto estadio de Anoeta, ya que ante el Sporting, Espa\u00f1ol y Athletic el equipo solo fue capaz de sumar la p\u00edrrica cifra de dos puntos de los posibles nueve puntos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-442","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/comments?post=442"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/442\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/media?parent=442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/categories?post=442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/tags?post=442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}