{"id":86,"date":"2014-12-02T13:16:57","date_gmt":"2014-12-02T12:16:57","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/desde-banquillo\/?p=86"},"modified":"2014-12-02T13:16:57","modified_gmt":"2014-12-02T12:16:57","slug":"el-metodo-moyes","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/2014\/12\/02\/el-metodo-moyes\/","title":{"rendered":"El m\u00e9todo Moyes"},"content":{"rendered":"<p><a href=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2014\/12\/DF0PPA31.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-87\" title=\"DF0PPA31\" src=\"\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2014\/12\/DF0PPA31.jpg\" alt=\"\" width=\"1000\" height=\"680\" srcset=\"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2014\/12\/DF0PPA31.jpg 1000w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2014\/12\/DF0PPA31-300x204.jpg 300w, https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-content\/uploads\/sites\/73\/2014\/12\/DF0PPA31-768x522.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>Jugar es entretenerse, divertirse, actuar, moverse, aventurar, apostar tomando parte en uno de esos juegos sometidos a normas o reglas. Entrenar es ejercitarse, adiestrarse, habituarse, ensayar y prepararse especialmente para la practica de un deporte cualquiera o concreto como lo es el f\u00fatbol. Jugar, entrenar y competir son tres palabras que est\u00e1n \u00edntimamente relacionadas en el deporte rey de nuestros tiempos: el f\u00fatbol profesional. Se entrena para luego competir y despu\u00e9s se compite a trav\u00e9s del juego. No obstante, tiene connotaciones muy diferentes.<\/p>\n<p>Se juega con unas cualidades naturales que son innatas de cada uno a base de talento e intuici\u00f3n. En este apartado no hay m\u00e1s que ver jugar a <strong>L\u00f3pez Ufarte<\/strong>, <strong>Zamora<\/strong>, <strong>Txiki Begiristain<\/strong> o a <strong>Andres Iniesta<\/strong>. Se entrena mediante reflexi\u00f3n y en conocimientos espec\u00edficos de cada entrenador. Tambi\u00e9n es una labor multidisciplinar que implica tener unos conocimientos en todos los aspectos relacionados con la metodolog\u00eda del entrenamiento y en saber dominar los resortes necesarios para la direcci\u00f3n del grupo, adem\u00e1s de coordinar el trabajo cotidiano con los colaboradores o ayudantes, ll\u00e1mense segundo entrenador, entrenador de porteros, preparador f\u00edsico, recuperador de futbolistas lesionados, cuerpo medico, rehabilitadores, fisios y jefe de prensa como le gusta tener a <strong>Joaqu\u00edn Caparr\u00f3s<\/strong> en el Granada. Es fundamental la cohesi\u00f3n de este grupo de trabajo en estar al cien por cien con el jefe de direcci\u00f3n, que no es otro sino el entrenador de nuestro equipo.<\/p>\n<p>Para jugar y competir en el aspecto f\u00edsico se requiere unas cualidades bimotores y en el aspecto t\u00e9cnico hay que saber ejecutar las acciones que se realizan durante un encuentro de f\u00fatbol. Adem\u00e1s, en el aspecto t\u00e1ctico se debe tener un desarrollo del mecanismo de percepci\u00f3n, decisi\u00f3n y ejecuci\u00f3n que nos permita elegir la mejor opci\u00f3n posible ante los problemas que nos encontramos en un partido. Tambi\u00e9n creo muy firmemente en todo esto, ya que el futbolista es el principal y \u00fanico protagonista de este mundo llamado f\u00fatbol.<\/p>\n<p>Para entrenar bien hay que basar el desarrollo de trabajo en el profundo conocimiento de todas las materias que rigen la labor global del entrenamiento. Aunque tambi\u00e9n es fundamental y muy importante que todas las materias que rigen la labor global del entrenamiento tener en cuenta un apartado extraordinario: el ambiente que crea en la conducci\u00f3n del grupo el entrenador, el luego llamado por mas de un medio de informaci\u00f3n, el buen conductor del vestuario. Tiene a todos contentos y el grupo trabaja y compite como ning\u00fan otro equipo. Ese trabajo de puertas hacia adentro da unos resultados fant\u00e1sticos y, que yo sepa por comentarios de personas muy cercanas, tanto <strong>Vicente Del Bosque<\/strong> como <strong>Jabo Irureta<\/strong> o en la actualidad <strong>Ancelotti<\/strong> ten\u00edan y tienen ese don de ser unos conductores de grupos excelentes. Demostrado queda en los trabajos de equipo el entrenador que maneja un vestuario lleno de futbolistas de una calidad individual extraordinaria o los llamados figuras mundiales con solo un poco de sentido com\u00fan, ya que la materia prima la tiene, obtiene unos resultados fant\u00e1sticos que hacen que su equipo consiga los objetivos marcados por el consejo de administraci\u00f3n o los clubes donde entrenan.<\/p>\n<p>Al hilo de este texto bajo mi opini\u00f3n el nuevo entrenador de la Real sociedad el <strong>Sir Moyes<\/strong>, en tono cari\u00f1oso, ha expresado el deseo que su equipo trasmita emoci\u00f3n en el campo y que se divierta con su juego, pero como lo mas importante o lo \u00fanico importante palabras m\u00e1gicas del sabio<strong> Xabier Exposito<\/strong> lo que quiere es ganar. \u00abMi metodolog\u00eda de entrenar es mi punto fuerte, y es lo que creo que hago muy bien\u00bb, dijo en su presentaci\u00f3n. Ah\u00ed fue donde \u00e9l se defini\u00f3 como un entrenador m\u00e1s parecido al estilo Mourinho que al de Guardiola.<\/p>\n<p>Estos d\u00edas cuando los ensayos han sido a puerta abierta me ha acercado a la ciudad deportiva de Zubieta a ver los entrenamientos del <strong>Sir Moyes<\/strong> y me ha venido al recuerdo las sesiones de trabajo &#8216;muy Liverpool&#8217; que hac\u00eda en los a\u00f1os ochenta el manager general <strong>John Toshack<\/strong>. Se trata de entrenamientos de una hora y media, muy intensos y en donde est\u00e1 muy presente el bal\u00f3n. Circula con mucha rapidez y muy pocos toques y nadie est\u00e1 parado, aunque no sea poseedor del esf\u00e9rico. M\u00e1s que nada se ve intensidad y entre ejercicio y ejercicio con bal\u00f3n unas series de velocidad de resistencia o unos ejercicios de frecuencia, skiping y picas en slalom, salidas en velocidad con muchos apoyos y coordinaci\u00f3n. Adem\u00e1s los rondos son muy intensos y tambi\u00e9n hay partidos en campos reducidos con muchas porter\u00edas peque\u00f1as y casi siempre finalizando con un encuentro m\u00e1s real con dos porteros.<\/p>\n<p>Esta metodolog\u00eda de trabajo para los lectores de este blog est\u00e1 m\u00e1s cerca de la que realizaban <strong>JB<\/strong> o <strong>Mart\u00edn Lasarte<\/strong>, que de la que propon\u00edan <strong>Juanma Lillo<\/strong> o <strong>Montanier <\/strong>o, por continuidad, <strong>Jagoba Arrasate<\/strong>. Las dos son muy v\u00e1lidas, pero en lo que no estoy para nada de acuerdo es que para limpiar la cara de decisiones tomadas en su momento digamos que las de unos son muy malas con un f\u00fatbol muy directo y de solo el pelotazo y tente tieso; y las de otros del futbol del tiki taka y posesi\u00f3n son muy, muy buenas. Cada maestrillo tiene su librillo y con jugadores de unas caracter\u00edsticas o de otras, los entrenadores con su metodolog\u00eda de trabajo deben de sacar el m\u00e1ximo rendimiento a ese grupo de profesionales. Esto se reduce, ni m\u00e1s ni menos, a las palabras m\u00e1gicas de nuestro Sir y sabio de siempre, <strong>Xabier Exposito<\/strong>: \u00abLo \u00fanico importante es Ganar\u00bb Que as\u00ed sea y el Consejo de la Real acierte en esta contrataci\u00f3n del nuevo inquilino de la casa realista, el <strong>Sir Moyes<\/strong>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Jugar es entretenerse, divertirse, actuar, moverse, aventurar, apostar tomando parte en uno de esos juegos sometidos a normas o reglas. Entrenar es ejercitarse, adiestrarse, habituarse, ensayar y prepararse especialmente para la practica de un deporte cualquiera o concreto como lo es el f\u00fatbol. Jugar, entrenar y competir son tres palabras que est\u00e1n \u00edntimamente relacionadas en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-86","post","type-post","status-publish","format-standard","hentry","category-real-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/desde-banquillo\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}