{"id":121,"date":"2013-04-16T09:55:15","date_gmt":"2013-04-16T08:55:15","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=121"},"modified":"2013-04-16T09:55:15","modified_gmt":"2013-04-16T08:55:15","slug":"crisis-what-crisis-iii","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2013\/04\/16\/crisis-what-crisis-iii\/","title":{"rendered":"Crisis? What crisis? (III)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Pensemos en el siguiente \u201cjuego\u201d (esto es algo que los economistas suelen hacer, para no aburrirse).<\/p>\n<p>Hay dos depositantes que tienen sus ahorros en una entidad financiera. Cada uno de ellos puede decidir retirar todo su dinero por adelantado (R) o no retirarlo (NR), en cuyo caso la \u00a0entidad financiera lo invierte y obtiene un rendimiento.<\/p>\n<p>Las p\u00e9rdidas y ganancias se pueden representar en la Tabla 1. El primer n\u00famero de cada celda corresponde a la ganancia o p\u00e9rdida del depositante 1 (Asier) y el segundo n\u00famero de cada celda a la ganancia o p\u00e9rdida del depositante 2 (Mikel). (Suponemos que I\u00f1aki o no tiene dinero o lo tiene todo debajo del colch\u00f3n, por lo que ni hablaremos de \u00e9l \u2026 ) Si el banco cuenta con suficiente dinero para afrontar las retiradas de dinero, Asier recibir\u00e1 0\u20ac si retira su dinero por adelantado (R) y 2\u20ac si no lo hace (NR). Lo mismo ocurre con Mikel. Si ambos retiran su dinero por adelantado, entonces, ambos reciben 0\u20ac. Si uno de ellos retira su dinero antes, pero el otro no, el que lo hace por adelantado recibe 0\u20ac y el otro 2\u20ac. Si los dos no retiran su dinero antes, ambos reciben 2\u20ac.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Tabla 1.<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"54\">&nbsp;<\/td>\n<td valign=\"top\" width=\"38\">&nbsp;<\/td>\n<td colspan=\"2\" valign=\"top\" width=\"132\">\n<p align=\"center\"><span style=\"color: #00ff00;\">Mikel<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"54\">&nbsp;<\/td>\n<td valign=\"top\" width=\"38\">&nbsp;<\/td>\n<td valign=\"top\" width=\"66\">\n<p align=\"center\">R<\/p>\n<\/td>\n<td valign=\"top\" width=\"66\">\n<p align=\"center\">NR<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\" width=\"45\"><span style=\"color: #ff0000;\">Asier<\/span><\/td>\n<td colspan=\"2\" width=\"47\">\n<p align=\"center\">R<\/p>\n<\/td>\n<td width=\"66\">\n<p align=\"center\">(0,0)<\/p>\n<\/td>\n<td width=\"66\">\n<p align=\"center\">(0,<span style=\"color: #00ff00;\">2<\/span>)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" width=\"47\">\n<p align=\"center\">NR<\/p>\n<\/td>\n<td width=\"66\">\n<p align=\"center\">(<span style=\"color: #ff0000;\">2<\/span>,0)<\/p>\n<\/td>\n<td width=\"66\">\n<p align=\"center\">(<span style=\"color: #ff0000;\">2<\/span>,<span style=\"color: #00ff00;\">2<\/span>)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"45\"><\/td>\n<td width=\"9\"><\/td>\n<td width=\"38\"><\/td>\n<td width=\"66\"><\/td>\n<td width=\"66\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>\u00bfQu\u00e9 har\u00e1n Asier y Mikel? (De I\u00f1aki, ni hablamos) Volviendo a la Tabla 1, si Mikel retira su dinero (R), Asier no debe hacerlo (NR): el 2 que se indica en <span style=\"color: #ff0000;\">rojo<\/span>. Si Mikel no retira su dinero (NR), Asier no debe hacerlo (NR): el 2 que se indica en rojo. Por tanto, en cualquier caso, Asier no debe retirar su dinero (NR). Lo mismo ser\u00eda aplicable para Mikel. \u00bfCu\u00e1l es su mejor estrategia si Asier retira su dinero? \u00bfY si no lo hace? No retirarlo en cualquier caso (NR): se indica en <span style=\"color: #00ff00;\">verde<\/span>. Por tanto, Asier y Mikel tienen una estrategia dominante: independientemente de lo que haga el otro, su estrategia \u00f3ptima es no retirar el dinero (NR). El equilibrio, donde Asier y Mikel no retiran su dinero (NR), es \u00fanico.<\/p>\n<p>\u00bfPero y si no hay dinero suficiente para los dos?<\/p>\n<p>En ese caso si uno retira su dinero anticipadamente y el otro no, el que lo retira recibir\u00e1 0\u20ac y el que no -1\u20ac. Si ambos lo retiran antes a la vez, las p\u00e9rdidas se reparten y ambos reciben -0,5\u20ac. Si los dos deciden no retirar el dinero por adelantado, entonces ambos logran 2\u20ac. La Tabla 2 recoge los rendimientos correspondientes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tabla 2.<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"54\">&nbsp;<\/td>\n<td valign=\"top\" width=\"38\">&nbsp;<\/td>\n<td colspan=\"2\" valign=\"top\" width=\"161\">\n<p align=\"center\"><span style=\"color: #00ff00;\">Mikel<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"54\">&nbsp;<\/td>\n<td valign=\"top\" width=\"38\">&nbsp;<\/td>\n<td valign=\"top\" width=\"85\">\n<p align=\"center\">R<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">NR<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\" width=\"54\"><span style=\"color: #ff0000;\">Asier<\/span><\/td>\n<td width=\"38\">\n<p align=\"center\">R<\/p>\n<\/td>\n<td width=\"85\">\n<p align=\"center\">(<span style=\"color: #ff0000;\">-1\/2<\/span>,<span style=\"color: #00ff00;\">-1\/2<\/span>)<\/p>\n<\/td>\n<td width=\"76\">\n<p align=\"center\">(0,-1)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"38\">\n<p align=\"center\">NR<\/p>\n<\/td>\n<td width=\"85\">\n<p align=\"center\">(-1,0)<\/p>\n<\/td>\n<td width=\"76\">\n<p align=\"center\">(<span style=\"color: #ff0000;\">2<\/span>,<span style=\"color: #00ff00;\">2<\/span>)<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>\u00bfQu\u00e9 har\u00e1n Asier y Mikel? La Tabla 2 muestra que si Mikel retira su dinero (R), Asier tambi\u00e9n debe hacerlo (R): el -1\/2 que se indica en <span style=\"color: #ff0000;\">rojo<\/span>. Si Mikel no retira su dinero (NR), Asier no debe hacerlo (NR): el 2 que se indica en <span style=\"color: #ff0000;\">rojo<\/span>. Podemos decir lo mismo para Mikel, en <span style=\"color: #00ff00;\">verde<\/span>. Por lo tanto, en este caso, el equilibrio no es \u00fanico; es m\u00faltiple. Se llaman <a href=\"http:\/\/es.wikipedia.org\/wiki\/Equilibrio_de_nash\" rel=\"external nofollow\">equilibrios de Nash<\/a> y son estrat\u00e9gicamente estables: dado lo que Mikel quiere hacer, a Asier no le interesa\u00a0 variar su estrategia, y dado lo que Asier quiere hacer, a Mikel no le interesa variar su estrategia. El equilibrio de Nash se debe a <a href=\"http:\/\/www.nobelprize.org\/nobel_prizes\/economics\/laureates\/1994\/nash-autobio.html\" rel=\"external nofollow\">John Forbes Nash<\/a>, premio Nobel de Econom\u00eda en 1994, junto con John C. Harsanyi, y Reinhard Selten <a href=\"http:\/\/www.nobelprize.org\/nobel_prizes\/economics\/laureates\/1994\/nash-autobio.html\" rel=\"external nofollow\">\u201cpor su pionero an\u00e1lisis del equilibrio en la teor\u00eda de los juegos no cooperativos\u201d<\/a>. Tiene una pel\u00edcula, basada en el libro de Sylvia Nasar, <a href=\"http:\/\/es.wikipedia.org\/wiki\/A_Beautiful_Mind\" rel=\"external nofollow\">\u201cUna mente maravillosa\u201d<\/a>.<\/p>\n<p>Este es un sencillo ejemplo de profec\u00eda autocumplida: el equilibrio \u201cmalo\u201d ocurre porque todo el mundo espera que se cumpla. Se basa en <a href=\"http:\/\/en.wikipedia.org\/wiki\/Diamond%E2%80%93Dybvig_model\" rel=\"external nofollow\">el modelo de Diamond- Dybvig<\/a>, (pincha <a href=\"http:\/\/www.rich.frb.org\/publications\/research\/economic_quarterly\/2007\/spring\/pdf\/diamond.pdf\" rel=\"external nofollow\">aqu\u00ed<\/a> para una versi\u00f3n \u201csencilla\u201d del modelo) y est\u00e1 tomado del libro de texto de <a href=\"http:\/\/www.degregorio.cl\/\" rel=\"external nofollow\">\u201cMacroeconom\u00eda. Teor\u00eda y pol\u00edticas\u201d<\/a> de <a href=\"http:\/\/es.wikipedia.org\/wiki\/Jos%C3%A9_de_Gregorio\" rel=\"external nofollow\">Jos\u00e9 De Gregorio<\/a>.<\/p>\n<p>Este equilibrio malo se conoce como \u201ccorrida bancaria\u201d (<em>bank run)<\/em>: demasiados depositantes intentan retirar su dinero a la vez<em>. <\/em>Ello es debido a que las entidades financieras exhiben un desfase de liquidez (se dice que un activo es l\u00edquido cuando se convierte en efectivo sin apenas coste): los pasivos (deudas) de las entidades financieras (normalmente, dep\u00f3sitos) son m\u00e1s l\u00edquidos que los activos (normalmente, pr\u00e9stamos). Ejemplos cl\u00e1sicos de corridas bancarias se pueden encontrar en la pel\u00edcula <a href=\"http:\/\/www.youtube.com\/watch?v=qu2uJWSZkck\" rel=\"external nofollow\">\u201c\u00a1Qu\u00e9 bello es vivir!\u201d<\/a>, de <a href=\"http:\/\/es.wikipedia.org\/wiki\/Frank_Capra\" rel=\"external nofollow\">Frank Capra<\/a>, o en el muy recomendable libro <a href=\"http:\/\/books.google.es\/books?id=hZtNtofuazAC&#038;printsec=frontcover&#038;dq=libro+manias+panicos+y+cracs&#038;hl=es&#038;sa=X&#038;ei=UyxoUfyxMZOWhQfu_4HQAg&#038;ved=0CD0Q6AEwAA#v=onepage&#038;q&#038;f=false\" rel=\"external nofollow\">\u201cMan\u00edas, p\u00e1nicos y cracs. Historia de las crisis financieras\u201d<\/a>, de <a href=\"http:\/\/economics.mit.edu\/faculty\/kindleberger\/\" rel=\"external nofollow\">Charles P. Kindleberger<\/a> y Robert Z. Aliber:<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: x-small;\">\u201cLa obra de McLeod, <em>Theory and Practice of Banking<\/em>, describe la forma en que se defendi\u00f3 el Banco de Inglaterra en septiembre de 1720 contra un p\u00e1nico precipitado por su retractaci\u00f3n de la promesa de absorber los bonos de la South Sea Company a 400 libras esterlinas. Para evitar la quiebra, el banco coloc\u00f3 a sus amigos al principio de la cola y les fue pagando lentamente en peque\u00f1as monedas de seis peniques. \u00c9stos volvieron a introducir el met\u00e1lico por otra puerta: fue depositado nuevamente, vuelto a contar con la mayor lentitud y dispuesto para realizar el pago una vez m\u00e1s. De esta forma, concluye la historia, se logr\u00f3 evitar el desastre hasta la Feria de San Miguel (Michaelmas Day) (29 de septiembre). Cuando terminaron las vacaciones, tambi\u00e9n habr\u00eda concluido el p\u00e1nico y el banco abri\u00f3 de nuevo sus puertas.\u201d (pp. 189-190 de la edici\u00f3n en espa\u00f1ol y en ingl\u00e9s <a href=\"http:\/\/books.google.es\/books?hl=es&#038;id=nBb-xYi9O-sC&#038;q=mcleod#v=onepage&#038;q&#038;f=false\" rel=\"external nofollow\">aqu\u00ed<\/a>)<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>El \u201ccorralito\u201d se le parece bastante.<\/p>\n<p>Cuando parec\u00eda haber una relativa calma en la eurozona, la situaci\u00f3n y soluci\u00f3n de Chipre ha creado un descomunal desconcierto en las econom\u00edas europeas. La soluci\u00f3n \u201ca la chipriota\u201d ha supuesto un giro transcendental en la configuraci\u00f3n del manual de c\u00f3mo hay que afrontar futuras crisis bancarias, lo que se conoce como \u201c<em>bail-in<\/em>\u201d (normalmente, con cargo de los acreedores), en contraposici\u00f3n al \u201c<em>bail-out<\/em>\u201d (normalmente, con cargo del contribuyente). En efecto, aquellos depositantes con dep\u00f3sitos superiores a los 100.000\u20ac, en caso de surgir problemas, podr\u00edan perder parte de sus ahorros, por la parte que se halle por encima de dicha cifra. Paul De Grauwe, uno de los mayores expertos europeos sobre uniones monetarias, ha sugerido recientemente que la soluci\u00f3n adoptada es negativa por dos razones (pincha <a href=\"http:\/\/www.ceps.eu\/book\/new-bail-doctrine-recipe-banking-crises-and-depression-eurozone\" rel=\"external nofollow\">aqu\u00ed<\/a>). En primer lugar, eleva el riesgo sist\u00e9mico de la eurozona y ser\u00e1 m\u00e1s probable que ocurran crisis bancarias en el futuro. Cada vez que surjan dudas sobre un pa\u00eds o una entidad financiera, los depositantes \u201ccorrer\u00e1n\u201d para retirar sus ahorros por miedo a perderlos. Ello, por supuesto, puede ocasionar mayores corridas bancarias y debilitar a\u00fan m\u00e1s el sistema financiero. Los destinos del pa\u00eds y de las entidades financieras estar\u00edan unidos, de modo que si el gobierno de un pa\u00eds se enfrenta a serios problemas econ\u00f3micos, la posibilidad de que ocurrieran corridas bancarias ser\u00eda mayor. En segundo lugar, impone costes enormes a los pa\u00edses del \u201c<em>bail-in<\/em>\u201d, porque el sistema financiero est\u00e1 altamente interconectado. Por ello, sugiere que es claramente mejor una mayor labor de regulaci\u00f3n y supervisi\u00f3n del sistema financiero.<\/p>\n<p>Junto a ello, se hace cada vez m\u00e1s necesario dar pasos firmes hacia una uni\u00f3n bancaria europea. As\u00ed, Daniel Gros, otro experto europeo en uniones monetarias, sugiere la creaci\u00f3n de un supervisor \u00fanico, una autoridad de resoluci\u00f3n com\u00fan y un sistema cre\u00edble de garant\u00eda de dep\u00f3sitos (pincha <a href=\"http:\/\/www.ceps.eu\/book\/meaning-cyprus-moving-towards-banking-union\" rel=\"external nofollow\">aqu\u00ed<\/a>). Sobre este \u00faltimo conviene recordar que la garant\u00eda de los 100.000\u20ac no es europea, sino nacional. Y esto es claramente insatisfactorio, como se dijo m\u00e1s arriba. El art\u00edculo de Diamond-Dybvig suger\u00eda ya la garant\u00eda de los dep\u00f3sitos como una manera de evitar las corridas bancarias, y de impedir las profec\u00edas autocumplidas. Pasar\u00edamos de la Tabla 2 a la Tabla 1. Ello, por supuesto, origina problemas de riesgo moral: al estar garantizados los dep\u00f3sitos, las entidades financieras pueden tener incentivos para incurrir en mayores riesgos a la hora de invertir para obtener una mayor rentabilidad.<\/p>\n<p>\u00bfCu\u00e1l es la situaci\u00f3n en Espa\u00f1a? Hace poco <a href=\"http:\/\/economia.elpais.com\/economia\/2013\/04\/10\/actualidad\/1365621933_979229.html\" rel=\"external nofollow\">le\u00eda<\/a> que el <a href=\"http:\/\/www.fgd.es\/es\/index.html\" rel=\"external nofollow\">Fondo de Garant\u00eda de Dep\u00f3sitos<\/a> espa\u00f1ol (FGD) apenas tiene fondos, tras haberlos utilizado para recapitalizar las entidades financieras con problemas. Ello, por supuesto, no quiere decir que la garant\u00eda haya desaparecido. En 2011 los dep\u00f3sitos totales que entraban en la garant\u00eda del FGD era de 1.213.650,8 millones de euros, y estaban cubiertos por el FGD 792.281,2 millones de euros (65,28% del total de garantizados) (pincha <a href=\"http:\/\/www.fgd.es\/files\/pdf\/Bancos111web.pdf\" rel=\"external nofollow\">aqu\u00ed<\/a> para el informe de 2011). Minutos antes de publicar este post acabo de leer (pincha <a href=\"http:\/\/www.diariovasco.com\/rc\/20130415\/mas-actualidad\/economia\/rechaza-ventajas-201304151935.html\" rel=\"external nofollow\">aqu\u00ed<\/a> y \u00a0<a href=\"http:\/\/economia.elpais.com\/economia\/2013\/04\/15\/actualidad\/1366046466_331609.html\" rel=\"external nofollow\">aqu\u00ed<\/a>) que el Banco Central Europeo ha dictaminado lo siguiente sobre un nuevo proyecto de ley del gobierno para que el FGD pueda comprar acciones no cotizadas de entidades nacionalizadas, o deuda subordinada (las famosas \u201cpreferentes\u201d), etc., hace poqu\u00edsimos d\u00edas:<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: x-small;\">\u201cPara cumplir su funci\u00f3n principal de proteger los dep\u00f3sitos garantizados en caso de insolvencia bancaria, es preciso que el FGD pueda contar con un patrimonio de elevada liquidez. El BCE considera que la proyectada adquisici\u00f3n por el FGD de acciones de entidades no admitidas a cotizaci\u00f3n es contraria a ese principio prudencial y, por lo tanto, desaconseja modificar las normas de inversi\u00f3n de aplicaci\u00f3n al FGD que permitan esas adquisiciones\u201d (pincha <a href=\"http:\/\/www.ecb.int\/ecb\/legal\/pdf\/es_con_2013_25_f_sign.pdf\" rel=\"external nofollow\">aqu\u00ed<\/a> para el dictamen original)<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>No creo que una corrida bancaria sea un escenario de futuro en nuestro entorno, pero conviene estar atento por aquello de las profec\u00edas autocumplidas.<\/p>\n<p>\u00bfLlegar\u00e1 antes Asier o Mikel, si fuera el caso? \u00a0De I\u00f1aki, ni hablamos, porque &#8230;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Pensemos en el siguiente \u201cjuego\u201d (esto es algo que los economistas suelen hacer, para no aburrirse). Hay dos depositantes que tienen sus ahorros en una entidad financiera. Cada uno de ellos puede decidir retirar todo su dinero por adelantado (R) o no retirarlo (NR), en cuyo caso la \u00a0entidad financiera lo invierte y obtiene [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":69,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-121","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/121\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}