{"id":142,"date":"2013-05-21T06:41:20","date_gmt":"2013-05-21T05:41:20","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=142"},"modified":"2013-05-21T06:41:20","modified_gmt":"2013-05-21T05:41:20","slug":"las-consecuencias-economicas-del-google-car-i","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2013\/05\/21\/las-consecuencias-economicas-del-google-car-i\/","title":{"rendered":"Las consecuencias econ\u00f3micas del Google-Car (I)"},"content":{"rendered":"<p>Seguro que m\u00e1s de una vez os hab\u00e9is preguntado, &#8220;Y a m\u00ed, en los a\u00f1os que todav\u00eda espero vivir \u00bfqu\u00e9 nuevos avances tecnol\u00f3gicos me quedar\u00e1n por ver?,\u00a0 \u00bfropa que no hay que lavar ni planchar?, \u00bfviajar a Australia en menos de un hora?, \u00bfhablar en euskara pero que un chip traduzca autom\u00e1ticamente mi voz al ingl\u00e9s?&#8221;.<\/p>\n<p>Al hacerme esta pregunta, siempre hab\u00eda pensado que una de las cosas que me quedaban por ver eran los coches sin conductor. Al igual que en la serie &#8220;El Coche Fant\u00e1stico&#8221; yo cre\u00eda que en un par de d\u00e9cadas yo tambi\u00e9n podr\u00eda tener un coche al que le pudiera decir &#8220;Kit, ll\u00e9vame a casa&#8221;. Lo que no sab\u00eda era que los coches sin conductor ya son casi una realidad. Y tampoco me hab\u00eda dado cuenta de las enormes consecuencias econ\u00f3micas que los coches sin conductor pueden tener sobre la econom\u00eda.<\/p>\n<p>Ya en <a href=\"http:\/\/googleblog.blogspot.com.es\/2010\/10\/what-were-driving-at.html\" rel=\"external nofollow\">Octubre de 2010<\/a>, Google anunci\u00f3 en su blog que hab\u00eda equipado unos coches con c\u00e1maras de v\u00eddeo, radares, l\u00e1seres para identificar el tr\u00e1fico y el Google Maps, y los hab\u00eda convertido en coches totalmente aut\u00f3nomos. Es m\u00e1s, Google anunciaba que ya hab\u00eda hecho alrededor de 224.000 kil\u00f3metros con estos coches. Para que la gente no se llevase un susto, y para cumplir con las exigencias legales, hab\u00edan sentado una persona en el asiento del conductor, pero en realidad esa persona no conduc\u00eda.<\/p>\n<p>A d\u00eda de hoy, seg\u00fan informaba el semanario <a href=\"http:\/\/www.economist.com\/printedition\/2013-04-20\" rel=\"external nofollow\">The Economist<\/a> en su n\u00famero del 20 de abril, el Google-Car ya lleva m\u00e1s de 700.000 kil\u00f3metros recorridos. Que se sepa, los Google-Car solamente han tenido dos accidentes. En el primero un Google-Car golpe\u00f3 por detr\u00e1s a otro coche. Seg\u00fan afirm\u00f3 un portavoz de Google, en el momento del accidente la persona que estaba sentada en el asiento del conductor s\u00ed estaba conduciendo. En el segundo accidente, el Google-Car fue golpeado por detr\u00e1s por otro coche mientras esperaba que el sem\u00e1foro se pusiese en verde. Tambi\u00e9n el coche que provoc\u00f3 el accidente iba conducido por una persona. Si quer\u00e9is ver el coche en acci\u00f3n, pod\u00e9is pinchar sobre este <a href=\"http:\/\/www.youtube.com\/watch?v=cdgQpa1pUUE\" rel=\"external nofollow\">v\u00eddeo<\/a>. En \u00e9l una persona que ha perdido el 95% de su visi\u00f3n utiliza el Google-Car para ir de su casa a un restaurante, luego a una lavander\u00eda y despu\u00e9s de vuelta a casa. Gracias a la fiabilidad que est\u00e1 demostrando el Google-Car, los Estados de Nevada, Florida y California ya han dado permiso para que circule, en periodo de prueba, en carreteras abiertas.<\/p>\n<p>Supongamos que para dentro de algunos a\u00f1os el Google-Car supera todas las pruebas, los pa\u00edses aprueban una legislaci\u00f3n que permita circular a coches sin conductor, y que los coches que vayan equipados con esta tecnolog\u00eda tengan un precio competitivo. \u00bfCu\u00e1les pueden ser las consecuencias econ\u00f3micas de estos coches sin conductor?<\/p>\n<p>La primera consecuencia es que se reducir\u00edan enormemente los accidentes de tr\u00e1fico. M\u00e1s de un mill\u00f3n de personas pierden la vida por accidentes de tr\u00e1fico en el mundo, y en muchos pa\u00edses, los accidentes de tr\u00e1fico son la primera causa de muerte entre los j\u00f3venes. La mayor\u00eda de los accidentes de tr\u00e1fico se deben a errores humanos. Los coches sin conductor, con una visi\u00f3n de 360 grados, tienen una percepci\u00f3n y una capacidad de reacci\u00f3n mucho m\u00e1s r\u00e1pida que la de los humanos. Adem\u00e1s, los coches sin conductor no se cansan, no se distraen, no beben alcohol y respetan las se\u00f1ales de tr\u00e1fico. De hecho el ingeniero jefe del proyecto del Google-Car, <a href=\"http:\/\/www.ted.com\/talks\/sebastian_thrun_google_s_driverless_car.html\" rel=\"external nofollow\">Sebastian Thrun<\/a>, tom\u00f3 la decisi\u00f3n de dedicar su vida a desarrollar un coche sin conductor tras perder a los 18 a\u00f1os a su mejor amigo en un accidente de tr\u00e1fico.<\/p>\n<p>Como la capacidad de reacci\u00f3n de los coches sin conductor es mucho m\u00e1s grande que el de las personas, la distancia que habr\u00e1 que dejar entre los coches ser\u00e1 mucho m\u00e1s peque\u00f1a. Como los ciclistas, los coches podr\u00e1n ir en pelot\u00f3n, y al ir &#8220;a rueda&#8221; necesitar\u00e1n menos energ\u00eda para moverse. Al ir en pelot\u00f3n las carreteras podr\u00e1n soportar una carga muy superior de coches y se reducir\u00e1n los atascos. Por otra parte, debido a que se reduce enormemente el riesgo de accidentes,\u00a0 los coches se podr\u00e1n fabricar con materiales mucho m\u00e1s ligeros, lo cual, junto con el ir en pelot\u00f3n, permitir\u00e1 una ca\u00edda muy importante en el consumo de gasolina. Sin embargo, como me se\u00f1al\u00f3 mi compa\u00f1ero de blog I\u00f1aki Erauskin, si se reduce el precio de los coches y aumenta el atractivo de viajar en ellos, quiz\u00e1 acabemos teniendo m\u00e1s coches, y otra vez vuelvan los atascos y el consumo excesivo de gasolina.<\/p>\n<p>Una segunda consecuencia de los coches sin conductor es que ya no habr\u00e1 necesidad de sacarse el carnet de conducir, lo cual tendr\u00e1 un impacto muy negativo sobre las autoescuelas. Como la probabilidad de tener un accidente ser\u00e1 mucho menor, seguramente la cuota del seguro del autom\u00f3vil tambi\u00e9n bajar\u00e1. De hecho, es probable que las compa\u00f1\u00edas de seguros penalicen a las personas que no utilicen en sus coches el piloto autom\u00e1tico. Es m\u00e1s, algunos analistas han sugerido que dentro de algunos a\u00f1os, cuando se demuestre que el Google-Car conduce mucho mejor que las personas, algunos pa\u00edses pueden tomar la decisi\u00f3n de prohibir que las personas conduzcan. As\u00ed mismo, como los coches respetar\u00e1n las normas de tr\u00e1fico, ya no habr\u00e1 que pagar multas de tr\u00e1fico (en todo caso, \u00bfqui\u00e9n ser\u00eda el responsable: Google o el due\u00f1o del coche?), y se podr\u00e1 reducir el n\u00famero de polic\u00edas de tr\u00e1fico.<\/p>\n<p>\u00c9stas son algunas de las consecuencias econ\u00f3micas de los coches sin conductor. Pero hay muchas m\u00e1s. Algunas son buenas y otras, quiz\u00e1, no sean tan buenas para ciertos colectivos. Si te interesa conocerlas nos vemos en tres semanas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Seguro que m\u00e1s de una vez os hab\u00e9is preguntado, &#8220;Y a m\u00ed, en los a\u00f1os que todav\u00eda espero vivir \u00bfqu\u00e9 nuevos avances tecnol\u00f3gicos me quedar\u00e1n por ver?,\u00a0 \u00bfropa que no hay que lavar ni planchar?, \u00bfviajar a Australia en menos de un hora?, \u00bfhablar en euskara pero que un chip traduzca autom\u00e1ticamente mi voz al [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":68,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-142","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=142"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/142\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}