{"id":1429,"date":"2020-03-17T08:00:47","date_gmt":"2020-03-17T07:00:47","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=1429"},"modified":"2020-03-12T10:39:31","modified_gmt":"2020-03-12T09:39:31","slug":"niksen","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2020\/03\/17\/niksen\/","title":{"rendered":"\u201cNiksen\u201d: la filosof\u00eda neerlandesa de no hacer nada"},"content":{"rendered":"<p><a href=\"https:\/\/twitter.com\/jonmizabala\" target=\"_blank\" rel=\"noopener external nofollow\">@jonmizabala<\/a><\/p>\n<p>Este cuatrimestre tengo a cuatro alumnos de los Pa\u00edses Bajos en clase. El modelo educativo neerland\u00e9s es muy distinto al nuestro. En los Pa\u00edses Bajos, los alumnos son los que asumen desde muy peque\u00f1os la responsabilidad de c\u00f3mo quieren que sea su clase. Ya desde la educaci\u00f3n primaria las ni\u00f1as y ni\u00f1os neerlandeses escogen lo que quieren estudiar ese d\u00eda. Como recoge <a href=\"https:\/\/es.euronews.com\/2016\/11\/25\/holanda-un-sistema-educativo-que-da-voz-y-apoyo-al-alumno\" target=\"_blank\" rel=\"noopener external nofollow\">Aurora V\u00e9lez<\/a>, los pilares del modelo pedag\u00f3gico neerland\u00e9s son el pensamiento cr\u00edtico, el trabajo en equipo y la responsabilidad.<\/p>\n<p>La din\u00e1mica de trabajo que generan los alumnos neerlandeses y \u201clos nuestros\u201d en el aula es\u2026 dig\u00e1moslo diferente. A pesar de que los nuestros ya se conozcan desde septiembre de 2019, apenas hablan entre s\u00ed, su proactividad sigue siendo baja, y cuando lanzas una pregunta son pr\u00e1cticamente los mismos los que responden. En el caso de estos cuatro alumnos, desde el primer d\u00eda en que llegaron al aula (febrero 2020) han planteado cuestiones que les generan inter\u00e9s (p.e. impacto de las plataformas digitales de la denominada <em>sharing economy<\/em> en la econom\u00eda), participan aunque no les preguntes y tratan de ir un paso m\u00e1s all\u00e1 de la explicaci\u00f3n que se da en el aula, buscando las implicaciones que puede tener el concepto, f\u00f3rmula, modelo o teor\u00eda presentado. Como aquellos que me conocen podr\u00e1n intuir, personalmente me siento mucho m\u00e1s c\u00f3modo con unos que con los otros (dejo a la imaginaci\u00f3n del lector la soluci\u00f3n al enigma) \ud83d\ude09<\/p>\n<p>Hace unos d\u00edas, coincid\u00ed con ellos en la cafeter\u00eda y nos pusimos a charlar: de sidrer\u00edas (ya hab\u00edan estado), del pintxopote (ya hab\u00edan participado), del kalimotxo (todav\u00eda no lo hab\u00edan probado), de la Real (ya sab\u00edan que estaba en semifinales)\u2026 y de cultura neerlandesa, por supuesto. Tengo muchos amigos que viven en los Pa\u00edses Bajos, por lo que les empec\u00e9 a preguntar de qu\u00e9 zona eran, les contaba las experiencias que hab\u00eda tenido en algunas universidades como la de Maastricht, Utrecht, Amsterdam, Twente o Rotterdam, y ellos por su parte me contaban c\u00f3mo se sent\u00edan aqu\u00ed, qu\u00e9 diferencias ve\u00edan respecto a la educaci\u00f3n universitaria de su pa\u00eds, qu\u00e9 aspectos de la cultura vasca les hab\u00edan llamado la atenci\u00f3n, etc. Y entre tema y tema, me preguntaron si conoc\u00eda lo que era la palabra \u201c<em>niksen<\/em>\u201d. Mi respuesta fue negativa y ah\u00ed se vinieron arriba y empezaron a contarme en qu\u00e9 consist\u00eda esta filosof\u00eda neerlandesa.<\/p>\n<p>Seg\u00fan me contaron, \u201c<em>niksen<\/em>\u201d significa no hacer nada o, m\u00e1s espec\u00edficamente, hacer algo sin un prop\u00f3sito, como mirar por la ventana, escuchar m\u00fasica o mirar las estrellas. Eso s\u00ed, sin una finalidad concreta (p.e. mirar por la ventana para cotillear al vecino, escuchar m\u00fasica para salir a correr, o mirar las estrellas para encontrar la constelaci\u00f3n de C\u00e1ncer). Los casos de depresi\u00f3n y ansiedad por estr\u00e9s laboral est\u00e1n en aumento en los Pa\u00edses Bajos. Bien sea por su \u00e9tica de trabajo protestante, por su necesidad de mantenerse activos en todo momento (qui\u00e9n no se ha topado con una familia neerlandesa en el lugar m\u00e1s rec\u00f3ndito del mundo) o por la presi\u00f3n que genera el vivir bajo el nivel del mar y tener que mantenerse alerta en todo momento ante posibles roturas de diques que puedan producir inundaciones, los alumnos me contaban c\u00f3mo los neerlandeses se sienten presionados para llenar su tiempo libre con actividades productivas y orientadas a objetivos. Cuando no est\u00e1n trabajando, est\u00e1n andando en bicicleta, aprendiendo idiomas o socializando con sus amigos, y no, ninguna de estas actividades califica como \u201c<em>niksen<\/em>\u201d, porque el ocio tiene un prop\u00f3sito.<\/p>\n<p>Los Pa\u00edses Bajos han tenido tradicionalmente un fuerte sesgo cultural en contra de no hacer nada, que se ve reflejado incluso en su idioma. El proverbio \u201c<em>niksen is niks<\/em>\u201d, por ejemplo, significa \u201cno hacer nada es bueno para nada\u201d, lo que en la pr\u00e1ctica es una manera de incitar a las personas a ser responsable, productivo, y trabajar duro. Esto es algo que veo claramente reflejado en mis cuatro alumnos neerlandeses.<\/p>\n<p>Sin embargo, algo parece estar cambiando en la cultura neerlandesa, y se est\u00e1 tolerando de manera creciente \u201c<em>niksen<\/em>\u201d como una pr\u00e1ctica orientada a hacernos m\u00e1s felices, m\u00e1s creativos y sobre todo m\u00e1s saludables. Desde que los alumnos me hablaron de esta filosof\u00eda, he estado leyendo al respecto, y efectivamente, el hecho de no hacer nada s\u00ed parece tener una incidencia directa sobre nuestra capacidad creativa e innovadora (puedes ver un estudio publicado sobre este tema <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3743222\/#B60a\" target=\"_blank\" rel=\"noopener external nofollow\">aqu\u00ed<\/a>). Tal y como cuenta <a href=\"https:\/\/time.com\/5622094\/what-is-niksen\/\" target=\"_blank\" rel=\"noopener external nofollow\">Ruut Veenhoven<\/a>, Catedr\u00e1tico en Sociolog\u00eda en la Erasmus University Rotterdam, incluso cuando no hacemos nada nuestro cerebro est\u00e1 procesando informaci\u00f3n, por lo que puede usar la capacidad de procesamiento disponible para resolver problemas pendientes. \u00bfQui\u00e9n no ha tenido una nueva idea o ha encontrado la soluci\u00f3n a un problema durante una caminata o cuando haciendo algo aparentemente no relacionado con el problema en cuesti\u00f3n?<\/p>\n<p>\u201cEn jij? Lekker aan het niksen?\u201d, lo que <a href=\"https:\/\/www.youtube.com\/watch?v=lKKfahj0Z20\" target=\"_blank\" rel=\"noopener external nofollow\">significa<\/a>, \u201c\u00bfy t\u00fa? \u00bfEst\u00e1s disfrutando de no hacer nada?\u201d<\/p>\n<p>Puedes seguirme en Twitter: <a href=\"https:\/\/twitter.com\/jonmizabala\" target=\"_blank\" rel=\"noopener external nofollow\">@jonmizabala<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>@jonmizabala Este cuatrimestre tengo a cuatro alumnos de los Pa\u00edses Bajos en clase. El modelo educativo neerland\u00e9s es muy distinto al nuestro. En los Pa\u00edses Bajos, los alumnos son los que asumen desde muy peque\u00f1os la responsabilidad de c\u00f3mo quieren que sea su clase. Ya desde la educaci\u00f3n primaria las ni\u00f1as y ni\u00f1os neerlandeses escogen [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":70,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1429","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=1429"}],"version-history":[{"count":5,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1429\/revisions"}],"predecessor-version":[{"id":1434,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1429\/revisions\/1434"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=1429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=1429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=1429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}