{"id":153,"date":"2013-06-11T06:29:00","date_gmt":"2013-06-11T05:29:00","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=153"},"modified":"2013-06-11T06:29:00","modified_gmt":"2013-06-11T05:29:00","slug":"las-consecuencias-economicas-del-google-car-ii","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2013\/06\/11\/las-consecuencias-economicas-del-google-car-ii\/","title":{"rendered":"Las consecuencias econ\u00f3micas del Google-Car (II)"},"content":{"rendered":"<p>En la <a href=\"http:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2013\/05\/21\/las-consecuencias-economicas-del-google-car-i\/\">primera entrega<\/a> de este post hace tres semanas, comenzamos a analizar cu\u00e1les podr\u00edan ser las consecuencias econ\u00f3micas de los coches sin conductor. En aquel post coment\u00e1bamos que los coches sin conductor pueden ayudar a que se reduzcan enormemente los accidentes de tr\u00e1fico, los atascos y la demanda de gasolina. Tambi\u00e9n se\u00f1al\u00e1bamos que con los coches sin conductor ya no ser\u00e1 necesario sacarse el carnet de conducir; adem\u00e1s, como los accidentes y las infracciones de tr\u00e1fico ser\u00e1n mucho menos probables, tendremos que pagar una cuota menor por el seguro del autom\u00f3vil, nos olvidaremos de las multas, y los polic\u00edas de tr\u00e1fico se encargar\u00e1n de otras tareas.<\/p>\n<p>Sin embargo, los coches sin conductor pueden tener m\u00e1s consecuencias para la econom\u00eda. El objetivo de esta segunda entrega es identificar estas consecuencias adicionales. Como se\u00f1al\u00e1bamos en el post anterior, en el <a href=\"http:\/\/www.youtube.com\/watch?v=cdgQpa1pUUE\" rel=\"external nofollow\">video promocional del Google-Car<\/a> se puede ver c\u00f3mo una persona que ha perdido el 95% de su visi\u00f3n utiliza el coche para ir de casa a un restaurante, a recoger unas camisas de la lavander\u00eda y de vuelta a casa. El protagonista del video est\u00e1 bien elegido, ya que otras de las consecuencias del Google-Car ser\u00e1 permitir la movilidad, en autom\u00f3vil, de las personas que actualmente no pueden conducir. Por ejemplo, el coche sin conductor puede aumentar mucho la independencia de las personas mayores que no pueden o no quieren conducir. Esta posibilidad es especialmente relevante para sociedades en las cuales las personas vivir\u00e1n m\u00e1s y d\u00f3nde habr\u00e1 un mayor n\u00famero de personas mayores.<\/p>\n<p>Otra de las consecuencias de que el coche conduzca por nosotros es que, probablemente, salgamos m\u00e1s a cenar y, quiz\u00e1, bebamos alguna copa m\u00e1s. L\u00f3gicamente, el hecho de que podamos coger el coche en estas circunstancias ser\u00e1 bueno para restaurantes y bares, pero podr\u00e1 tener un efecto negativo sobre otros servicios, como el de taxi, que nos llevan a casa cuando no estamos en condiciones de conducir. Sin embargo, los taxistas no ser\u00e1n los \u00fanicos perjudicados; en la medida que la tecnolog\u00eda de los coches sin conductor se vaya aplicando a otros veh\u00edculos, puede que veamos en el futuro tambi\u00e9n camiones sin conductor o autobuses sin conductor.<\/p>\n<p>Una consecuencia muy positiva de los coches sin conductor es que dejaremos de preocuparnos por el aparcamiento. Cuando lleguemos a nuestro destino nos bajaremos del coche y le &#8220;diremos&#8221; al coche que se vaya a aparcar. Cuando necesitemos el coche lo llamaremos y le diremos que nos recoja en un sitio determinado a una hora determinada. Eso s\u00ed, no tengo muy claro c\u00f3mo se gestionar\u00e1 el tr\u00e1fico cuando todos llamemos al coche a la vez y queramos que nos recoja a todos en el mismo sitio.<\/p>\n<p>Como el coche conducir\u00e1 por s\u00ed mismo, habr\u00e1 m\u00e1s libertad para organizar el interior de los coches a nuestro gusto. Quiz\u00e1 algunas personas organizar\u00e1n su coche como si fuera una oficina, y otros como si fuera un peque\u00f1o taller. Quiz\u00e1 las personas que viajan mucho en autom\u00f3vil puedan equipar el coche con una cama y aprovechar las noches para viajar de un destino a otro. Por otra parte, como el coche conducir\u00e1 s\u00f3lo, las personas podr\u00e1n dedicar el tiempo de viaje a hacer otras cosas que les pueda apetecer m\u00e1s que conducir, como ver la tele, navegar por Internet o leer un libro. Por ello, en el futuro, las personas dar\u00e1n m\u00e1s importancia al dise\u00f1o interior del coche que a su dise\u00f1o exterior y motorizaci\u00f3n. Es como cuando realizamos viajes largos en avi\u00f3n. Adem\u00e1s del precio del billete, le damos importancia a que tengamos una pantalla en nuestro asiento y haya espacio suficiente entre las butacas. Que el avi\u00f3n sea rojo o verde no nos preocupa mucho.<\/p>\n<p>Como todas las nuevas tecnolog\u00edas, los coches sin conductor traer\u00e1n cosas buenas y quiz\u00e1 otras no tan buenas, y con su desarrollo habr\u00e1 personas que saldr\u00e1n ganando y otras que saldr\u00e1n perdiendo. Creo que la suma de consecuencias positivas ser\u00e1 superior a la suma de consecuencias negativas. Espero vivir lo suficiente para poder verlas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En la primera entrega de este post hace tres semanas, comenzamos a analizar cu\u00e1les podr\u00edan ser las consecuencias econ\u00f3micas de los coches sin conductor. En aquel post coment\u00e1bamos que los coches sin conductor pueden ayudar a que se reduzcan enormemente los accidentes de tr\u00e1fico, los atascos y la demanda de gasolina. Tambi\u00e9n se\u00f1al\u00e1bamos que con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":68,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-153","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=153"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/153\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}