{"id":1617,"date":"2020-11-10T06:56:51","date_gmt":"2020-11-10T05:56:51","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=1617"},"modified":"2020-11-10T06:56:51","modified_gmt":"2020-11-10T05:56:51","slug":"capitalismo","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2020\/11\/10\/capitalismo\/","title":{"rendered":"Algunas caracter\u00edsticas fundamentales del sistema capitalista"},"content":{"rendered":"<p><a href=\"https:\/\/twitter.com\/InakiErauskin\" rel=\"external nofollow\">@InakiErauskin <\/a><\/p>\n<p>&nbsp;<\/p>\n<p>El capitalismo tiene grandes defensores y detractores. Hoy voy a escribir sobre algunas de sus caracter\u00edsticas fundamentales. Para ello me voy a basar en la publicaci\u00f3n reciente del libro \u201cCapitalismo, nada m\u00e1s\u201d (\u201cCapitalism, alone\u201d en el original en ingl\u00e9s), del economista <a href=\"https:\/\/twitter.com\/BrankoMilan\" rel=\"external nofollow\">Branko Milanovic<\/a>, cuya lectura recomiendo.<\/p>\n<p>Capitalismo (siguiendo a Marx y Weber) ser\u00eda aquel sistema econ\u00f3mico en el que la mayor parte de la actividad productiva se lleva a cabo a trav\u00e9s de medios privados de producci\u00f3n, el capital contrata trabajadores libres y las decisiones econ\u00f3micas se toman de forma descentralizada. Milanovic analiza lo que denomina el capitalismo \u201cmeritocr\u00e1tico liberal\u201d actual (derivado de la definici\u00f3n del fil\u00f3sofo John Rawls en su obra \u201cTeor\u00eda de la justicia\u201d) y lo compara con otras manifestaciones anteriores. \u201cMeritocr\u00e1tico\u201d se refiere a que no hay impedimentos para que los individuos lleguen a alcanzar una determinada posici\u00f3n en la sociedad. \u201cLiberal\u201d se refiere a que el sistema incluye impuestos que gravan las herencias y la educaci\u00f3n gratuita para reducir la desigualdad.<\/p>\n<p>La Tabla 1 resume sus caracter\u00edsticas fundamentales y las compara con otros capitalismos hist\u00f3ricos, tales como el capitalismo cl\u00e1sico (antes de la Primera Guerra Mundial) y el capitalismo socialdem\u00f3crata (desde el fin de la Segunda Guerra Mundial hasta 1980 aproximadamente), centr\u00e1ndose en los pa\u00edses protot\u00edpicos de cada modalidad, el Reino Unido para el capitalismo cl\u00e1sico, Europa y Estados Unidos para el capitalismo socialdem\u00f3crata, y Estados Unidos para el capitalismo meritocr\u00e1tico liberal.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tabla 1. Caracter\u00edsticas fundamentales de los capitalismos hist\u00f3ricos.<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"142\"><span style=\"font-size: 10pt;\">Forma de capitalismo<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">Capitalismo cl\u00e1sico<\/span><\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"142\"><span style=\"font-size: 10pt;\">Capitalismo socialdem\u00f3crata<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">Capital meritocr\u00e1tico liberal<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"142\"><span style=\"font-size: 10pt;\">Econom\u00eda representativa<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">Reino Unido antes de 1914<\/span><\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"142\"><span style=\"font-size: 10pt;\">EE.UU. y Europa despu\u00e9s de la 2\u00aa Guerra Mundial<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">EE.UU. a comienzos del siglo XXI<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"142\"><span style=\"font-size: 10pt;\">1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Aumento de la participaci\u00f3n del capital en la renta<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"142\"><span style=\"font-size: 10pt;\">No<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"142\"><span style=\"font-size: 10pt;\">2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Elevada concentraci\u00f3n en \u00a0la propiedad del capital<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"142\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"142\"><span style=\"font-size: 10pt;\">3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Los individuos que tienen abundancia de capital son ricos<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"142\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"142\"><span style=\"font-size: 10pt;\">4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Los ricos por su renta de capital son tambi\u00e9n ricos por las rentas del trabajo<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">No<\/span><\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"142\"><span style=\"font-size: 10pt;\">No<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"142\"><span style=\"font-size: 10pt;\">5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Los ricos se casan entre ellos (homogamia)<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed (hasta cierto punto)<\/span><\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"142\"><span style=\"font-size: 10pt;\">No<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"142\"><span style=\"font-size: 10pt;\">6.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Estrecha correlaci\u00f3n entre renta de padres e hijos<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"142\"><span style=\"font-size: 10pt;\">S\u00ed, pero en algunos casos es baja<\/span><\/td>\n<td width=\"142\">\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">S\u00ed<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Fuente: Branko Milanovic (2020). \u201cCapitalismo, nada m\u00e1s\u201d, Taurus.<\/p>\n<p>&nbsp;<\/p>\n<p>En primer lugar, en el capital meritocr\u00e1tico liberal ha tenido lugar un aumento del peso de las rentas del capital dentro de la renta nacional (neta). De ello, <a href=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2020\/09\/15\/salariosrentadesigualdad\/\">ya hemos hablado<\/a> en este blog.<\/p>\n<p>En segundo lugar, relacionado con lo anterior, la propiedad del capital est\u00e1 muy concentrada o, lo que es lo mismo, repartida de forma desigual. As\u00ed, los \u00edndices de Gini para las rentas del trabajo suelen situarse en torno a la franja de 30-50 (0 equivaldr\u00eda a igualdad total y 100 a desigualdad total) para un amplio n\u00famero de pa\u00edses, mientras que para las rentas del capital el \u00edndice se sit\u00faa cerca de 90 en muchos pa\u00edses.<\/p>\n<p>En tercer lugar, los individuos que tienen abundancia de capital son ricos. As\u00ed, los ricos no s\u00f3lo tienen m\u00e1s patrimonio, sino que su patrimonio en relaci\u00f3n con su renta es mucho mayor y es un patrimonio formado por una cartera diversificada de activos. Por el contrario, la mayor parte de la riqueza de la clase media est\u00e1 concentrada en la vivienda (y la deuda asociada a su compra).<\/p>\n<p>En cuarto lugar, los ricos por su renta de capital son, tambi\u00e9n, ricos por la renta del trabajo. Milanovic llama <em>homoploutia<\/em> (\u201chomo\u201d=igual; \u201cploutia\u201d=riqueza) a este fen\u00f3meno de asociar este hecho en un mismo hogar o individuo. En 1980 el 15% de los individuos en el decil m\u00e1s alto de las rentas de capital correspond\u00eda tambi\u00e9n al decil m\u00e1s alto de las rentas del trabajo en los Estados Unidos. En 2017 este porcentaje se situaba casi en el 30%.<\/p>\n<p>En quinto lugar, las personas del mismo nivel cultural o similar y del mismo nivel de renta o similar se casan entre ellas. A este fen\u00f3meno se le denomina <em>homogamia <\/em>o emparejamiento selectivo. En 1970 el 13% de los j\u00f3venes en el decil m\u00e1s alto de rentas de los varones asalariados se casaba con mujeres de ese mismo decil en los Estados Unidos. En 2017 este porcentaje se situaba casi en el 30%.<\/p>\n<p>En sexto lugar y \u00faltimo lugar, hay una estrecha correlaci\u00f3n entre las rentas de padres e hijos. Las ventajas adquiridas en patrimonio y capital se transmiten de generaci\u00f3n en generaci\u00f3n, salvo en algunos pa\u00edses (los pa\u00edses n\u00f3rdicos, por ejemplo). As\u00ed, la correlaci\u00f3n de rentas entre padres e hijas ha pasado de 0,22 a 0,37 y de padres a hijos de 0,17 a 0,36 (0=correlaci\u00f3n nula; 1=correlaci\u00f3n perfecta), seg\u00fan alguna investigaci\u00f3n.<\/p>\n<p>Todo lo anterior resume sint\u00e9ticamente la configuraci\u00f3n econ\u00f3mico-social actual. Evidentemente, la pandemia puede alterar algunas de las caracter\u00edsticas. Es probable que las agudice. Por ello, es m\u00e1s importante que nunca el reforzamiento de la red de seguridad de nuestro sistema econ\u00f3mico actual para que nadie que quede atr\u00e1s.<\/p>\n<p>Que Joe Biden haya ganado en las elecciones estadounidenses ayudar\u00e1 probablemente a mitigar un poco las derivas hacia una excesiva desigualdad en aquel pa\u00eds y, de paso, al resto del mundo \u2026 Eso espero al menos \u2026<\/p>\n<p>Veremos \u2026<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/twitter.com\/InakiErauskin\" rel=\"external nofollow\">@InakiErauskin <\/a><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>@InakiErauskin &nbsp; El capitalismo tiene grandes defensores y detractores. Hoy voy a escribir sobre algunas de sus caracter\u00edsticas fundamentales. Para ello me voy a basar en la publicaci\u00f3n reciente del libro \u201cCapitalismo, nada m\u00e1s\u201d (\u201cCapitalism, alone\u201d en el original en ingl\u00e9s), del economista Branko Milanovic, cuya lectura recomiendo. Capitalismo (siguiendo a Marx y Weber) ser\u00eda [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":69,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1617","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=1617"}],"version-history":[{"count":2,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1617\/revisions"}],"predecessor-version":[{"id":1619,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1617\/revisions\/1619"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=1617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=1617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=1617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}