{"id":1633,"date":"2020-12-01T06:56:49","date_gmt":"2020-12-01T05:56:49","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=1633"},"modified":"2020-12-01T08:53:15","modified_gmt":"2020-12-01T07:53:15","slug":"que-compren-ellos-y-si-son-los-nuestros-los-que-compran","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2020\/12\/01\/que-compren-ellos-y-si-son-los-nuestros-los-que-compran\/","title":{"rendered":"\u00a1Que compren ellos! Y, \u00bfsi son los nuestros los que compran?"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2020\/12\/Business-for-sale.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1634\" src=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2020\/12\/Business-for-sale.png\" alt=\"\" width=\"262\" height=\"192\" \/><\/a><\/p>\n<p>No he o\u00eddo nunca a un empresario decir de forma dogm\u00e1tica:<\/p>\n<p style=\"text-align: center;\">\u201cNo participamos en las compras de y en fusiones con otras empresas.<\/p>\n<p style=\"text-align: center;\">Esas son cosas para otros: \u00a1que compren ellos!\u201d<\/p>\n<p>(de la misma manera que el adagio de Unamuno \u201c\u00a1que inventen ellos!\u201d tampoco tiene que ser interpretado de forma tan categ\u00f3rica o literal).<\/p>\n<p>No obstante, hay dichos y met\u00e1foras potentes que -cuando llegan a los o\u00eddos de un p\u00fablico- quedan grabados en la mente y empiezan a tener vida propia. Son procesos mentales que generan una imagen (o un estigma) que se impone eclipsando la propia realidad y su l\u00f3gica.<\/p>\n<p>Es un fen\u00f3meno que tambi\u00e9n se puede dar con relaci\u00f3n a lo que venimos llamando \u201c<a href=\"https:\/\/www.orkestra.deusto.es\/images\/investigacion\/publicaciones\/informes\/cuadernos-orkestra\/200012-Lideres-en-nichos-de-mercado-internacionales-presencia-y-relevancia-en-Espa%C3%B1a.pdf\" rel=\"external nofollow\">l\u00edderes en nichos de mercado internacionales<\/a>\u201d (INMLs).<\/p>\n<p>Desde que llevamos estudiando dicho concepto, mucha gente lo ha ido asociando con empresas de tama\u00f1o mediano (o peque\u00f1o), que crecen de forma org\u00e1nica, que basan su negocio internacional en la exportaci\u00f3n, que operan desde zonas perif\u00e9ricas y que se quedan al margen de grandes transacciones financieras (adquirir otras empresas, salir a bolsa, codearse con fondos de inversi\u00f3n, \u2026).<\/p>\n<p>Ciertamente, la gran mayor\u00eda de estos INMLs sentaron sus bases de esta manera y esos rasgos siguen influyendo en su modus operandi y su forma de ser. Sin embargo, al ritmo de su propio crecimiento internacional -as\u00ed como por cambios de los contextos en los que operan- tampoco pueden ser ajenos a c\u00f3mo evoluciona la forma de competir en sus nichos (algunos de considerable tama\u00f1o). Como consecuencia, la realidad de los INMLs es hoy en d\u00eda m\u00e1s pluriforme y din\u00e1mica que nunca y no se puede pensar en un molde \u00fanico.<\/p>\n<p>De la misma manera que las empresas se tienen que ajustar a los tiempos, nuestros marcos de an\u00e1lisis y formas de ver las cosas se tienen que adaptar a la realidad. Cierto es que esto puede quitar idilio y romanticismo a una imagen creada. A la vez, puede que revitalice y refuerce la impresi\u00f3n que tengamos de una especie, as\u00ed como su capacidad de adaptaci\u00f3n.<\/p>\n<p>Respecto al tema de los INMLs y las compras de empresas, en el pasado ya hemos se\u00f1alado que hay una tendencia creciente de ver <a href=\"https:\/\/www.orkestra.deusto.es\/es\/actualidad\/noticias-eventos\/beyondcompetitiveness\/1461-campeones-cotizados\" rel=\"external nofollow\">participaciones extranjeras<\/a> en los l\u00edderes de nicho del Pa\u00eds Vasco, o incluso <a href=\"https:\/\/www.diariovasco.com\/economia\/ventas-decisiones-frivolas-20181111114846-nt.html\" rel=\"external nofollow\">adquisiciones completas<\/a> de los mismos por terceros. Cada vez que salen este tipo de casos, generan inquietud y una preocupaci\u00f3n por un declive de la soberan\u00eda en este tipo de empresas vascas: parec\u00edan representar a esa parte del tejido firme y arraigada, pero de repente, esa imagen parece sufrir \u201cuna abolladura\u201d.<\/p>\n<p>Creo que, para ajustar el prism\u00e1tico y las expectativas, es indicado adoptar una mirada hist\u00f3rica a las trayectorias de algunos INMLs vascos para ver que \u201clos nuestros\u201d tambi\u00e9n compran. A modo de ejemplo, sirven los siguientes casos:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ramondin.es\/\" rel=\"external nofollow\">Ramondin<\/a>: autentico veterano en el paisaje de INMLs vascos y que cuenta con una posici\u00f3n hegem\u00f3nica en el negocio de c\u00e1psulas de esta\u00f1o, forjada en base a varias adquisiciones de competidores por todo el mundo<\/li>\n<li>Danobat: cooperativa donde las haya, que acometi\u00f3 ya en 2002 su primer <em>take-over<\/em> en tierras extranjeras. Concretamente <a href=\"https:\/\/www.danobatgrinding.com\/en\/danobat-overbeck-internal-grinding-machines\" rel=\"external nofollow\">en Alemania<\/a>, epicentro europeo de la industria M\u00e1quina Herramienta, tanto para afianzarse en ese mercado y darse alas fuera<\/li>\n<li>Vicinay Marine: l\u00edder indiscutible en cadenas para <em>deep-sea mooring<\/em>, adquiri\u00f3 al hist\u00f3rico fabricante de cadenas para alta mar \u201cRamn\u00e4s\u201d (de Suecia) <a href=\"https:\/\/www.vicinaymarine.com\/wp-content\/uploads\/vicinaymarine.pdf\" rel=\"external nofollow\">en 2011<\/a>, reforzando as\u00ed su centralidad en el mercado, su capacidad tecnol\u00f3gica y de desarrollo en pro de una ventaja competitiva sostenible<\/li>\n<\/ul>\n<p>De forma m\u00e1s prosaica referimos en <a href=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2018\/02\/06\/euskadi-save-the-last-dance-for-me\/\">este post<\/a> a la idea de \u201ccrecer con frescura\u201d que diferentes INMLs vascos emplean para reforzar su posici\u00f3n en los mercados internacionales. Asimismo, ense\u00f1a que la v\u00eda del crecimiento inorg\u00e1nico tambi\u00e9n est\u00e1 su disposici\u00f3n, y que lo aplican.<\/p>\n<p>Por lo tanto, no s\u00f3lo son las empresas (<a href=\"https:\/\/www.diariovasco.com\/20131202\/economia\/grupo-canadiense-hace-mayoria-201312021230.html\" rel=\"external nofollow\">anglo<\/a>)<a href=\"https:\/\/www.vanbeest.com\/getattachment\/d720180d-5629-4178-8c1e-5784c8584d0e\/Irizar-Forge-sluit-zich-aan-bij-Van-Beest.aspx\" rel=\"external nofollow\">sajonas<\/a> que vienen a comprar por aqu\u00ed o los <a href=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2020\/05\/26\/adquisiciones-chinas-de-campeones-ocultos-alemanes-truco-o-trato\/\">chinos comprando a campeones ocultos alemanes<\/a>. Los nuestros tambi\u00e9n se mueven en este sentido. Es m\u00e1s: puede que ni el contexto actual, muy perturbado por la pandemia, haga que las empresas retrocedan sobre sus pasos. Por lo menos, se ven operaciones entre INMLs vascos que ense\u00f1an una determinaci\u00f3n clara por reforzarse en sus mercados claves a futuro.<\/p>\n<p>De este modo sali\u00f3 el mes pasado la noticia de que <a href=\"https:\/\/www.diariovasco.com\/economia\/salto-systems-desafia-20201015145648-nt.html\" rel=\"external nofollow\">Salto Systems<\/a> adquiri\u00f3 a Gantner, mientras que <a href=\"https:\/\/www.copreci.com\/es\/empresa\/12-noticias\/2308-copreci-adquiere-los-activos-de-fabricacion-y-control-de-valvulas-de-gas-de-defendi-italia\" rel=\"external nofollow\">Copreci<\/a> acaba de anunciar su compra de Defendi. Esta \u00faltima operaci\u00f3n es particularmente llamativa porque se trata de una cooperativa comprando a una empresa privada \u201ccorriente\u201d. Adem\u00e1s, \u00a1adquiri\u00e9ndola de un competidor directo (EGO) que se hab\u00eda apropiado de Defendi previamente!<\/p>\n<p>Para ponerlo en contexto, en su encuentro con <a href=\"https:\/\/www.youtube.com\/watch?v=prBXsHdhlnw\" rel=\"external nofollow\">Deusto Business Alumni<\/a> el 12 de noviembre, el presidente de la Corporaci\u00f3n Mondrag\u00f3n, I\u00f1igo Uc\u00edn, dijo que querr\u00edan optar por m\u00e1s apertura y m\u00e1s cooperaci\u00f3n, a saber, cooperativas con cooperativas, pero tambi\u00e9n con no-cooperativas, incluso v\u00eda participaciones e inversiones.<\/p>\n<p>Pues parece que va(mos) en serio, y me parece una buena se\u00f1al.<\/p>\n<p>&nbsp;<\/p>\n<p>Bart Kamp<\/p>\n<p>Orkestra-IVC<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No he o\u00eddo nunca a un empresario decir de forma dogm\u00e1tica: \u201cNo participamos en las compras de y en fusiones con otras empresas. Esas son cosas para otros: \u00a1que compren ellos!\u201d (de la misma manera que el adagio de Unamuno \u201c\u00a1que inventen ellos!\u201d tampoco tiene que ser interpretado de forma tan categ\u00f3rica o literal). No [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":21288,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1633","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/21288"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=1633"}],"version-history":[{"count":3,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1633\/revisions"}],"predecessor-version":[{"id":1637,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1633\/revisions\/1637"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=1633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=1633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=1633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}