{"id":1650,"date":"2021-01-12T08:00:42","date_gmt":"2021-01-12T07:00:42","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=1650"},"modified":"2021-01-07T12:02:39","modified_gmt":"2021-01-07T11:02:39","slug":"deseospara2021","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2021\/01\/12\/deseospara2021\/","title":{"rendered":"\u00bfMe ayudas a que mi deseo para este 2021 se haga realidad?"},"content":{"rendered":"<p><a href=\"https:\/\/twitter.com\/jonmizabala\" target=\"_blank\" rel=\"noopener external nofollow\">@jonmizabala<\/a><\/p>\n<p>En primer lugar, quisiera comenzar este primer post del a\u00f1o deseando a todos nuestros lectores un Feliz y pr\u00f3spero 2021, dejando atr\u00e1s las zozobras que nos trajo el pasado a\u00f1o 2020, y que sin duda alguna quedar\u00e1 para la historia. Y como se suele decir que hay que comenzar el a\u00f1o pidiendo un deseo, con este post quiero compartir el m\u00edo.<\/p>\n<p>Uno de los da\u00f1os colaterales de la pandemia es que no se pueden organizar eventos de car\u00e1cter social para compartir conocimiento. Para poder paliar esta necesidad, se est\u00e1n organizando una ingente cantidad de seminarios, <em>webinars<\/em> y debates online, en los que personas de referencia ofrecen sus conocimientos acerca de tem\u00e1ticas muy diversas. Son tantos los seminarios que se est\u00e1n ofreciendo, que si uno quisiera, se podr\u00eda pasar el d\u00eda escuchando divulgaci\u00f3n cient\u00edfica.<\/p>\n<p>El pasado 19 de noviembre tuve el placer de poder escuchar a Humberto Bustince en un <a href=\"https:\/\/elpais.com\/economia\/2020-11-18\/el-potencial-economico-de-la-transformacion-digital.html\" target=\"_blank\" rel=\"noopener external nofollow\">encuentro<\/a> en el que hablaba acerca del potencial econ\u00f3mico de la transformaci\u00f3n digital. <a href=\"https:\/\/www.jakiunde.eus\/miembros\/m\/?mid=350&amp;n=Bustince-Sola-Humberto\" target=\"_blank\" rel=\"noopener external nofollow\">Humberto Bustince<\/a> es Catedr\u00e1tico de Computaci\u00f3n e Inteligencia Artificial en la Universidad P\u00fablica de Navarra, y miembro de la Academia Vasca de las Ciencias, Artes y Letras (<a href=\"https:\/\/www.jakiunde.eus\/\" target=\"_blank\" rel=\"noopener external nofollow\">Jakiunde<\/a>). Adem\u00e1s de apuntar los avances que va a traer la inteligencia artificial a m\u00faltiples \u00e1mbitos de la sociedad en los pr\u00f3ximos a\u00f1os, Bustince tambi\u00e9n apunt\u00f3 cuales pueden ser algunas de las consecuencias que se pueden derivar de una mayor robotizaci\u00f3n, como la deslocalizaci\u00f3n, la emergencia y desaparici\u00f3n de algunos tipos de empleo, el tipo de educaci\u00f3n que se demandar\u00e1, el potencial econ\u00f3mico que va a representar el creciente tiempo que vamos a disponer para disfrutar del ocio, la posibilidad que ello va a ofrecer para poder cuidar de nuestros mayores, el potencial de la telemedicina y la medicina personalizada, el potencial de poder volver a las zonas vac\u00edas con su consiguiente resurgimiento (siempre y cuando haya el acceso a Internet adecuado), el acceso de todos a todo en todo el mundo y en tiempo real, y la creciente velocidad a la que van a ocurrir los cambios, con la consiguiente necesidad de adaptaci\u00f3n que ello va a exigir a la formulaci\u00f3n de pol\u00edticas p\u00fablicas, que tambi\u00e9n deber\u00e1n ofrecer respuestas r\u00e1pidas. Fue realmente interesante escuchar sus reflexiones, y es que s\u00ed, estos seminarios pueden resultar ciertamente gratificantes.<\/p>\n<p>Debido a este creciente ritmo de cambio, Bustince apuntaba que para poder ofrecer las <a href=\"https:\/\/blogs.deusto.es\/innovandis\/sorry-for-the-inconvenience-we-are-trying-to-change-the-world\/\" target=\"_blank\" rel=\"noopener external nofollow\">competencias necesarias<\/a> para poder garantizar una adaptaci\u00f3n r\u00e1pida a dichas condiciones cambiantes del entorno, las universidades tambi\u00e9n nos vamos a enfrentar a un cambio sustancial, ya que lo que se va a esperar es que seamos capaces de formar a personas con una elevada capacidad de respuesta y de multidisciplinariedad, de prospectiva tecnol\u00f3gica, etc. En este sentido, reflexionaba que todas las carreras, desde medicina a arquitectura, deber\u00edan tener una formaci\u00f3n m\u00ednima en \u00e9tica y filosof\u00eda, en programaci\u00f3n inform\u00e1tica, en derecho y en actitudes innovadores y emprendedoras, ya que van a ser estas competencias transversales las que van a permitir orientar los proyectos a aquellas direcciones que se demanden en cada momento.<\/p>\n<p>Ahora que estamos a las puertas de que comience la vacunaci\u00f3n masiva, la siguiente reflexi\u00f3n puede parecer ciertamente oportunista, pero en muchas ocasiones, antes incluso que emergiera la pandemia, he solido pensar que las universidades son como las vacunas. Est\u00e1n ah\u00ed para ponerte la \u2018inyecci\u00f3n\u2019 que necesitas para que tu cuerpo sepa responder en el futuro ante \u2018el virus\u2019, que no es sino inculcar una calidad adaptativa para que seas capaz de responder a los retos que depare tu vida profesional. Si ten\u00e9is dudas, les pod\u00e9is preguntar a los alumnos de doctorado, que el primer d\u00eda de clase les suelo decir que les voy a tratar de inocular el virus de la investigaci\u00f3n. Sin embargo, como nuestros lectores ya conocer\u00e1n a estas alturas del partido, la eficacia de toda vacuna tambi\u00e9n depende de un factor colectivo. Y es que las universidades pueden contribuir al progreso econ\u00f3mico y social, pero no pueden lograrlo por s\u00ed mismas. Las universidades formamos parte de un ecosistema que est\u00e1 en constante evoluci\u00f3n, y en la que las actividades que desempe\u00f1an unas organizaciones (p.e. las universidades forman en determinadas competencias), deben ser acompa\u00f1adas por las actividades ejecutadas o las demandas y necesidades de otras organizaciones (p.e. las empresas y la administraciones p\u00fablicas demandan profesionales con dichas competencias).<\/p>\n<p>En este sentido, resulta interesante analizar cu\u00e1les son los principales ecosistemas de innovaci\u00f3n y emprendimiento a nivel global. 2thinknow es una agencia dedicada al an\u00e1lisis de datos fundada en Melbourne (Australia), y que desde 2007 viene realizando un <a href=\"https:\/\/www.innovation-cities.com\/reference\/category\/innovation-cities-index\/indexes-all-years\/\" target=\"_blank\" rel=\"noopener external nofollow\">ranking<\/a> de las ciudades m\u00e1s innovadoras y con mayor nivel de bienestar. Si atendemos a los resultados para el a\u00f1o 2019, podemos observar que las 10 primeras posiciones est\u00e1n ocupadas por: Nueva York, Tokio, Londres, Los \u00c1ngeles, Singapur, Par\u00eds, Chicago, Boston, San Francisco y Toronto. Si nos fijamos en las 10 primeras ciudades europeas, \u00e9stas ser\u00edan: Par\u00eds, Berl\u00edn, Barcelona, Viena, M\u00fanich, Madrid, Mil\u00e1n, Amsterdam, Estocolmo y Oslo. Bilbao, \u00fanica ciudad vasca representada en dicho ranking, ocupar\u00eda el puesto 141 a nivel mundial y el 39 a escala europea. Naturalmente, todas ellas cuentan con universidades de primer nivel, por lo que si hici\u00e9semos una relaci\u00f3n entre la posici\u00f3n en este ranking y la posici\u00f3n relativa que ocupan las (en ocasiones numerosas) universidades que se ubican en dichas ciudades, la correspondencia seguro que ser\u00eda total.<\/p>\n<p>No queda duda de que si queremos ser competitivos, adem\u00e1s de hacer las cosas bien y con un ojo puesto en el futuro de manera permanente, debemos llegar a ser visibles, de forma que empresas, universidades, y pol\u00edticos de todo el mundo conozcan lo que est\u00e1 ocurriendo aqu\u00ed, para que en lugar de querer llevarse a nuestro mejor talento, est\u00e9n interesados en traer el suyo propio, para formarse y para cooperar con nosotros. De todos depende que as\u00ed sea. \u00bfMe ayudas a que mi deseo se haga realidad?<\/p>\n<p>Puedes seguirme en Twitter: <a href=\"https:\/\/twitter.com\/jonmizabala\" target=\"_blank\" rel=\"noopener external nofollow\">@jonmizabala<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>@jonmizabala En primer lugar, quisiera comenzar este primer post del a\u00f1o deseando a todos nuestros lectores un Feliz y pr\u00f3spero 2021, dejando atr\u00e1s las zozobras que nos trajo el pasado a\u00f1o 2020, y que sin duda alguna quedar\u00e1 para la historia. Y como se suele decir que hay que comenzar el a\u00f1o pidiendo un deseo, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":70,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1650","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=1650"}],"version-history":[{"count":5,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1650\/revisions"}],"predecessor-version":[{"id":1655,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/1650\/revisions\/1655"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=1650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=1650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=1650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}