{"id":173,"date":"2013-10-01T06:00:48","date_gmt":"2013-10-01T05:00:48","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=173"},"modified":"2013-10-01T06:00:48","modified_gmt":"2013-10-01T05:00:48","slug":"innovacion-de-la-herejia-a-una-nueva-religion","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2013\/10\/01\/innovacion-de-la-herejia-a-una-nueva-religion\/","title":{"rendered":"Innovaci\u00f3n: de la herej\u00eda a una nueva religi\u00f3n"},"content":{"rendered":"<p>\u00bfA qu\u00e9 nos referimos cuando hablamos de innovaci\u00f3n? La innovaci\u00f3n es una de las palabras que m\u00e1s se emplean en la sociedad actual. Forma parte de nuestro vocabulario habitual, y en la mayor\u00eda de los casos se percibe a la innovaci\u00f3n como una necesidad. La innovaci\u00f3n es a menudo entendida como algo positivo que redunda (o deber\u00eda redundar) en el bienestar, dando soluci\u00f3n a problemas existentes (econ\u00f3micos, sociales, medioambientales, etc.).<\/p>\n<p>Sin embargo, la palabra innovaci\u00f3n no siempre ha tenido connotaciones positivas. El profesor canadiense Beno\u00eet Godin, del Institut National de la Recherche Scientifique, ha desarrollado durante los \u00faltimos a\u00f1os un <a href=\"http:\/\/www.csiic.ca\/innovation.html\" rel=\"external nofollow\">proyecto <\/a>en el cual ha estudiado la evoluci\u00f3n que he llevado a cabo este t\u00e9rmino.<\/p>\n<p>Tal y como recogen en su \u00faltimo <a href=\"http:\/\/editorial.csic.es\/publicaciones\/libros\/12243\/84-00-09665-6\/el-significado-de-innovar-.html\" rel=\"external nofollow\">libro <\/a>Castro y Fern\u00e1ndez de Lucio (2013), la palabra innovaci\u00f3n procede del griego <a href=\"http:\/\/el.wikipedia.org\/wiki\/%CE%9A%CE%B1%CE%B9%CE%BD%CE%BF%CF%84%CE%BF%CE%BC%CE%AF%CE%B1\" rel=\"external nofollow\">\u03ba\u03b1\u03b9\u03bd\u03bf\u03c4\u03bf\u03bc\u03af\u03b1<\/a>, que significaba \u201chacer nuevos esquejes\u201d. El t\u00e9rmino fue empleado por Plat\u00f3n y Arist\u00f3teles con el significado de \u201cintroducir un cambio en el orden establecido\u201d. Seg\u00fan estos pensadores griegos, la innovaci\u00f3n deb\u00eda estar prohibida por ser maligna, ya que incorporaba cambios a las costumbres y al orden existente.<\/p>\n<p>Este criterio fue compartido por fil\u00f3sofos como S\u00e9neca y Lucrecio, poetas como Horacio y Virgilio, moralistas como Cicer\u00f3n y T\u00e1cito, e historiadores como Salustio, quienes consideraron la innovaci\u00f3n como sin\u00f3nimo del mal y lo prohibido. \u201c<em>Ne quid novi fiat contra exempla ataque instituto moiorum<\/em>\u201d, afirm\u00f3 Cicer\u00f3n en su obra <em>De Imperio Cn. Pompei<\/em> (\u201cque no se establezca la innovaci\u00f3n contraria a los precedentes\u201d).<\/p>\n<p>Este sentido peyorativo perdur\u00f3 durante siglos, no s\u00f3lo debido a la influencia de los pensadores griegos y romanos en el pensamiento pol\u00edtico occidental, sino tambi\u00e9n al apadrinamiento religioso de \u00e9ste. Durante el Renacimiento, el concepto de innovaci\u00f3n compart\u00eda el espacio de la herej\u00eda en los discursos religiosos. En 1548, Eduardo VI, rey de Inglaterra, emiti\u00f3 una declaraci\u00f3n \u201c<em>Against Those That Doeth Innouate<\/em>\u201d (contra los que innovan). Incluso el \u00e1mbito cient\u00edfico convino esta interpretaci\u00f3n. Como consecuencia de las revoluciones inglesa (1649) y francesa (1789), el t\u00e9rmino se identific\u00f3 con la revoluci\u00f3n, y por ende con los revolucionarios, asumi\u00e9ndose as\u00ed que toda innovaci\u00f3n era repentina y violenta. El concepto dej\u00f3 as\u00ed de ser empleado durante siglos, debido a sus evocaciones profundamente negativas.<\/p>\n<p>Pudiera parecer que por lo tanto, durante muchos siglos todo lo nuevo fuera mal valorado. Sin embargo, como reflexionaba <a href=\"http:\/\/books.google.es\/books?id=KuEqAAAAMAAJ&#038;printsec=frontcover&#038;source=gbs_ge_summary_r&#038;cad=0#v=onepage&#038;q&#038;f=false\" rel=\"external nofollow\">Bentham <\/a>(1824) decir que todo lo nuevo es negativo es como decir que todo es negativo, ya que de todas aquellas cosas que hayamos visto o de las que hayamos o\u00eddo, no hay ninguna que alguna vez no haya sido nueva. Por lo tanto, todo lo existente, ahora o en el pasado, fue alguna vez una innovaci\u00f3n.<\/p>\n<p>Sobre todo a partir del Renacimiento se apreciaba lo nuevo, lo curioso y lo extra\u00f1o, pero utilizando otras palabras como novedad, reforma o renovaci\u00f3n, ya que implicaban una mejora progresiva, de lo imperfecto, es decir, una b\u00fasqueda lenta y paulatina de la perfecci\u00f3n. Del mismo modo, los avances que acaecieron durante la primera Revoluci\u00f3n Industrial fueron denominados m\u00e1quinas o inventos, pero careciendo de car\u00e1cter innovador.<\/p>\n<p>Esta corriente se mantiene hasta finales del siglo XIX, un per\u00edodo en el cual los cient\u00edficos quer\u00edan destacar el car\u00e1cter revolucionario de su actividad as\u00ed como de sus frutos, es decir, el desarrollo de descubrimientos cient\u00edficos absolutamente nuevos, \u00fanicos y nunca antes llevados a cabo. Ello requer\u00eda del empleo de un t\u00e9rmino que expresara el uso o aplicaci\u00f3n que se deduc\u00eda de dichos avances, para diferenciar las invenciones que no llegaban a ser utilizadas de aquellas que s\u00ed llegaban a serlo. As\u00ed, se empez\u00f3 a emplear el t\u00e9rmino innovaci\u00f3n como sin\u00f3nimo de introducir algo (novedad cient\u00edfica o tecnol\u00f3gica) \u00fatil.<\/p>\n<p>El t\u00e9rmino aparece por primera vez con un sentido econ\u00f3mico positivo en los trabajos del economista <a href=\"http:\/\/es.wikipedia.org\/wiki\/Joseph_Alois_Schumpeter\" rel=\"external nofollow\">Joseph Alois Schumpeter <\/a>(1883-1950), quien describi\u00f3 un paradigma socioecon\u00f3mico en el que la innovaci\u00f3n resulta el motor interno del desarrollo econ\u00f3mico. Schumpeter bautiz\u00f3 el concepto de \u201ccreative destruction\u201d (destrucci\u00f3n creadora), al que defini\u00f3 como un proceso de mutaci\u00f3n industrial que revoluciona la estructura econ\u00f3mica, destruyendo lo antiguo y creando elementos nuevos. Los responsables de dichos procesos ser\u00edan los \u201cemprendedores innovadores\u201d. Con sus trabajos, Schumpeter sent\u00f3 las bases para comprender los efectos de la innovaci\u00f3n como factor determinante del desarrollo empresarial y econ\u00f3mico.<\/p>\n<p align=\"left\">En el primer <a href=\"http:\/\/www.amazon.com\/The-Theory-Economic-Development-Interest\/dp\/0878556982\" rel=\"external nofollow\">libro <\/a>en el que se refiere a la innovaci\u00f3n, Schumpeter (1934) especifica que las nuevas combinaciones de las fuerzas productivas (o innovaciones) pueden ser de cinco tipos: (i) introducci\u00f3n de una nueva mercanc\u00eda (innovaci\u00f3n de producto); (ii) introducci\u00f3n de un nuevo m\u00e9todo de producci\u00f3n (innovaci\u00f3n de proceso); (iii) apertura de nuevos mercados; (iv) nuevas fuentes de materias primas; (v) nuevas formas de organizaci\u00f3n industrial. Desde entonces han sido muchos los estudiosos que, desde varias disciplinas y enfoques, han tratado de definir la innovaci\u00f3n y acotar su significado. Atendiendo a la definici\u00f3n del <a href=\"http:\/\/www.uam.es\/personal_pdi\/economicas\/palomas\/Traduccion%20%20espanola%20del%20Manual%20de%20Oslo.pdf\" rel=\"external nofollow\">Manual de Oslo<\/a> (2005), que es la que se aplica en la elaboraci\u00f3n de las estad\u00edsticas de innovaci\u00f3n, \u201cuna innovaci\u00f3n es la introducci\u00f3n de un producto (bien o servicio) o de un proceso, nuevo o significativamente mejorado, o la introducci\u00f3n de un m\u00e9todo de comercializaci\u00f3n o de organizaci\u00f3n nuevo aplicado a las pr\u00e1cticas de negocio, a la organizaci\u00f3n del trabajo o a las relaciones externas\u201d.<\/p>\n<p>Como se puede observar, la innovaci\u00f3n es un concepto poli\u00e9drico, ya que es a la vez un proceso y su resultado, en el que adem\u00e1s del componente tecnol\u00f3gico, los factores organizacionales y socioculturales tambi\u00e9n desempe\u00f1an un papel fundamental. La cantidad de veces que escuchamos hablar de innovaci\u00f3n, tanto en los medios, como en las organizaciones, el deporte, la alta cocina, etc. no hacen sino ilustrar que la innovaci\u00f3n es un atributo imprescindible en la sociedad actual. Ning\u00fan pa\u00eds puede presumir de no ser innovador, aunque su pol\u00edtica sea absolutamente conservadora. La innovaci\u00f3n determina las acciones (o inacciones) de los gobiernos, que es precisamente lo que se trataba de evitar antiguamente. La sociedad necesita personas innovadoras. Las administraciones requieren tambi\u00e9n personas innovadoras que sepan adaptar las instituciones existentes a las nuevas demandas econ\u00f3micas y sociales. Por ello, los cambios sociales que estamos viviendo en la actualidad, nos abren las puertas a la innovaci\u00f3n social que con toda seguridad, producir\u00e1 en los pr\u00f3ximos a\u00f1os unos cambios si no mayores, comparables a los que dieron lugar al Renacimiento.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfA qu\u00e9 nos referimos cuando hablamos de innovaci\u00f3n? La innovaci\u00f3n es una de las palabras que m\u00e1s se emplean en la sociedad actual. Forma parte de nuestro vocabulario habitual, y en la mayor\u00eda de los casos se percibe a la innovaci\u00f3n como una necesidad. La innovaci\u00f3n es a menudo entendida como algo positivo que redunda [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":70,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-173","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=173"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/173\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}