{"id":182,"date":"2013-10-08T06:00:48","date_gmt":"2013-10-08T05:00:48","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=182"},"modified":"2013-10-08T06:00:48","modified_gmt":"2013-10-08T05:00:48","slug":"a-largo-plazo-todos-muertos-menos-keynes","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2013\/10\/08\/a-largo-plazo-todos-muertos-menos-keynes\/","title":{"rendered":"\u201cA largo plazo, todos muertos\u201d, menos Keynes"},"content":{"rendered":"<p>\u201cIn the long run, we are all dead\u201d es la famosa frase que el economista John Maynard Keynes acu\u00f1\u00f3 en su obra \u201cUn tratado sobre la reforma monetaria\u201d en 1923.<\/p>\n<p>En el post de hoy voy a adentrarme en las profundidades de la macroeconom\u00eda, m\u00e1s concretamente, de la teor\u00eda macroecon\u00f3mica (siendo consciente del riesgo; pincha <a href=\"https:\/\/www.youtube.com\/watch?feature=player_embedded&#038;v=aYp4wcgJbFA#t=34\" rel=\"external nofollow\">aqu\u00ed<\/a> para ver el riesgo). La raz\u00f3n es simple. Se acaba de publicar lo que creo que ser\u00e1 un art\u00edculo \u201chist\u00f3rico\u201d por el qui\u00e9n, cu\u00e1ndo y d\u00f3nde, qu\u00e9, \u2026<\/p>\n<p>\u00bfQui\u00e9n?<\/p>\n<p>Lo ha escrito <a href=\"http:\/\/www.crei.cat\/people\/gali\/\" rel=\"external nofollow\">Jordi Gal\u00ed<\/a>. Sospecho que pocos lectores lo conocer\u00e1n. Resumiendo mucho, se trata del economista catal\u00e1n con m\u00e1s boletos para lograr el <a href=\"http:\/\/www.nobelprize.org\/nobel_prizes\/economic-sciences\/\" rel=\"external nofollow\">Premio Nobel de Econom\u00eda<\/a> (otro que tambi\u00e9n estuvo en las quinielas es <a href=\"http:\/\/www.govern.cat\/pres_gov\/govern\/ca\/govern\/consell-executiu\/mas-colell.html\" rel=\"external nofollow\">Andreu Mas-Colell<\/a>, ahora consejero de Econom\u00eda y Conocimiento en la Generalitat de Artur Mas). Actualmente, es, tambi\u00e9n, uno de los economistas catalanes del <a href=\"http:\/\/wilson.cat\/es\/mitjans-escrits\/itemlist\/user\/700-jordi_gali\" rel=\"external nofollow\">Col-lectiu Wilson<\/a>, del que habl\u00e9 en un <a href=\"http:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2012\/12\/04\/quo-vadis-independentzia-ekonomikoa\/\">post anterior<\/a>: \u201cLa misi\u00f3n del Col\u00b7lectiu Wilson es contribuir al debate sobre la auto-determinaci\u00f3n en Catalu\u00f1a para que sus ciudadanos puedan decidir su futuro libremente, sin miedo ni amenazas\u201d.<\/p>\n<p>\u00bfCu\u00e1ndo y d\u00f3nde?<\/p>\n<p>Es un art\u00edculo publicado muy recientemente en la <a href=\"http:\/\/www.eeassoc.org\/index.php?site=JEEA&#038;trsz=53\" rel=\"external nofollow\">revista de la Asociaci\u00f3n Europea de Econom\u00eda<\/a>, que es una de las revistas de econom\u00eda m\u00e1s importantes del mundo, si bien el documento de trabajo lleva circulando unos cuantos meses (pincha <a href=\"http:\/\/www.crei.cat\/people\/gali\/jg2013jeea.pdf\" rel=\"external nofollow\">aqu\u00ed<\/a> para el documento de trabajo o <a href=\"http:\/\/www.youtube.com\/watch?v=m_YR1eVR-2M\" rel=\"external nofollow\">aqu\u00ed<\/a> para una versi\u00f3n resumida por \u00e9l mismo en video). No es una casualidad, especialmente teniendo en cuenta la Gran Recesi\u00f3n en la que todav\u00eda estamos inmersos. Y la contribuci\u00f3n es plenamente actual y muy relevante.<\/p>\n<p>\u00bfQu\u00e9 es?<\/p>\n<p>Son unas \u201cNotas para una nueva gu\u00eda a Keynes (I): Salarios, demanda agregada y empleo\u201d. M\u00e1s precisamente, analiza el papel de los salarios como un determinante del empleo y, en particular, los beneficios de bienestar y estabilidad que provienen de una mayor flexibilidad salarial. La motivaci\u00f3n de escribir este art\u00edculo surge, entre otras razones, de que Gal\u00ed cree que las virtudes de la flexibilidad salarial y la conveniencia de la moderaci\u00f3n salarial dentro de una situaci\u00f3n de gran desempleo forman parte del pensamiento pol\u00edtico actual. Y \u00e9l los discute desde una versi\u00f3n keynesiana revisada, la de los nuevos keynesianos.<\/p>\n<p><a href=\"http:\/\/es.wikipedia.org\/wiki\/John_Maynard_Keynes\" rel=\"external nofollow\">John Maynard Keynes<\/a> es, probablemente, el economista m\u00e1s importante del siglo XX. Publica su <em>magnum opus<\/em> en 1936, \u201c<a href=\"http:\/\/es.wikipedia.org\/wiki\/Teor%C3%ADa_general_del_empleo,_el_inter%C3%A9s_y_el_dinero\" rel=\"external nofollow\">La teor\u00eda general del empleo, el inter\u00e9s y el dinero<\/a>\u201d. Este libro (dicho sea de paso: est\u00e1 bastante aceptado que no es un libro f\u00e1cil de leer) cambi\u00f3 completamente la teor\u00eda macroecon\u00f3mica imperante hasta ese momento, lo que se conoce como teor\u00eda cl\u00e1sica.\u00a0 Resumiendo mucho, la escuela keynesiana sugiere que los pa\u00edses pueden sufrir crisis econ\u00f3micas a gran escala, y ello provee de una justificaci\u00f3n por la que la intervenci\u00f3n p\u00fablica mejorar\u00eda la situaci\u00f3n econ\u00f3mica.<\/p>\n<p>La teor\u00eda cl\u00e1sica del empleo es la visi\u00f3n m\u00e1s habitual en el pensamiento pol\u00edtico actual. Seg\u00fan esta teor\u00eda el empleo depende de los salarios (reales): a mayores salarios menor empleo, y viceversa. Un supuesto importante es que el mercado de bienes y servicios funciona perfectamente y las empresas no perciben, por tanto, restricciones de demanda agregada. Por tanto, el desempleo surge, seg\u00fan esta teor\u00eda, porque el salario es demasiado alto, debido a los efectos de los convenios colectivos, y otras barreras legales o institucionales. Una soluci\u00f3n \u201cnatural\u201d al desempleo involuntario (trabajadores que quieren trabajar al salario en vigor, pero no encuentran trabajo) ser\u00eda reducir los salarios.<\/p>\n<p>La teor\u00eda keynesiana del empleo le da la vuelta a la teor\u00eda cl\u00e1sica. El salario real viene determinado por el empleo, y no al rev\u00e9s. Y el empleo viene determinado por la cantidad de bienes y servicios que las empresas est\u00e1n dispuestas a producir y vender. Por ello, la \u201csoluci\u00f3n\u201d vendr\u00eda dada por una expansi\u00f3n de la demanda agregada, ya sea reduciendo el tipo de inter\u00e9s y\/o una pol\u00edtica fiscal expansiva (a trav\u00e9s de mayor gasto p\u00fablico o menores impuestos).<\/p>\n<p>Y de todo esto, \u00bf<a href=\"https:\/\/www.youtube.com\/watch?v=rgyQs5-NPic\" rel=\"external nofollow\">qu\u00e9 hay de nuevo, \u201cviejo\u201d<\/a>? (Pincha <a href=\"https:\/\/www.youtube.com\/watch?v=rgyQs5-NPic\" rel=\"external nofollow\">aqu\u00ed<\/a> para ver c\u00f3mo suena esta frase)<\/p>\n<p>El art\u00edculo estudia dos cuestiones fundamentales, pero por razones de espacio, conveniencia y relevancia me centrar\u00e9 en el segundo de ellos (el primero estudia el comportamiento c\u00edclico del salario).<\/p>\n<p>\u201c\u00bfCu\u00e1l es el impacto de una mayor flexibilidad salarial sobre el empleo y el bienestar?\u201d se pregunta Jordi Gal\u00ed. Seg\u00fan la teor\u00eda cl\u00e1sica, la mayor flexibilidad salarial hace que el empleo sea m\u00e1s estable: una reducci\u00f3n de los salarios, cuando las cosas van mal, genera empleo. \u00bfEs eso verdad para los nuevos keynesianos? Como dir\u00eda un buen economista, depende. (Los detalles t\u00e9cnicos importan: Gal\u00ed parte de un modelo nuevo keynesiano est\u00e1ndar, bastante realista, en el que existe alg\u00fan grado de competencia monopol\u00edstica, alguna rigidez en los precios y los salarios y una aproximaci\u00f3n sobre c\u00f3mo se comportan los bancos centrales, lo que se conoce como regla de Taylor). El impacto de la reducci\u00f3n del salario sobre el empleo depende de lo que haga el banco central. As\u00ed, si la bajada de los salarios reduce la inflaci\u00f3n y con ello los tipos de inter\u00e9s (nominal y real), se lograr\u00e1 elevar la producci\u00f3n y el empleo. En suma, si el banco central es \u201cagresivo\u201d, una reducci\u00f3n de los salarios mejorar\u00e1 la situaci\u00f3n, pero si el banco central no es agresivo apenas se mejorar\u00e1. Junto a ello muestra que una mayor flexibilidad salarial no tiene por qu\u00e9 ser buena para el bienestar. \u00a0Otra vez, la respuesta depende de c\u00f3mo se comporta el banco central. Si el banco central es agresivo, la flexibilidad salarial mejorar\u00e1 el bienestar, pero si el banco central no es agresivo, puede que no lo mejore.<\/p>\n<p>Por ello, Jordi Gal\u00ed concluye que no debe darse por sentado que las reducciones de los salarios sean buenas para combatir el desempleo o que sea deseable una mayor flexibilidad salarial. Y ello es justamente, tambi\u00e9n, lo que Keynes dec\u00eda en su \u201cTeor\u00eda General\u201d.<\/p>\n<p>\u00bfTiene todo esto alg\u00fan inter\u00e9s hoy? Creo que es plenamente actual para la crisis, tambi\u00e9n, para la Eurozona.<\/p>\n<p>La gu\u00eda de Gal\u00ed sobre Keynes no es la \u00fanica (tambi\u00e9n est\u00e1n las \u201cantiguas\u201d de <a href=\"https:\/\/www.google.es\/url?sa=t&#038;rct=j&#038;q=&#038;esrc=s&#038;source=web&#038;cd=2&#038;cad=rja&#038;ved=0CEAQFjAB&#038;url=http%3A%2F%2Fweb.econ.unito.it%2Fbagliano%2Fmacro3%2Fhicks_econ37.pdf&#038;ei=eXdOUsXWBKbR7Aacj4CYBQ&#038;usg=AFQjCNHkL-zS7izehYWiTFRyi2iNjo_GSQ&#038;sig2=4g2mGA-lkQIls4SkO4aMdw\" rel=\"external nofollow\">John R. Hicks<\/a>, <a href=\"http:\/\/stevereads.com\/papers_to_read\/review_of_guide_to_keynes.pdf\" rel=\"external nofollow\">Alvin H. Hansen<\/a>, <a href=\"http:\/\/stevereads.com\/papers_to_read\/liquidity_preference_and_the_theory_of_interest_and_money.pdf\" rel=\"external nofollow\">Franco Modigliani<\/a>, <a href=\"http:\/\/public.econ.duke.edu\/~erw\/190\/Klein%201947.pdf\" rel=\"external nofollow\">Lawrence Klein<\/a>, \u2026), pero que creo que marcar\u00e1 un antes y un despu\u00e9s. El tiempo dir\u00e1 si estoy en lo cierto o no.<\/p>\n<p>Todo esto les contar\u00e9 dentro de unos meses a mis alumnos de primer curso en el Grado en Administraci\u00f3n y Direcci\u00f3n de Empresas de <a href=\"http:\/\/www.dbs.deusto.es\/cs\/Satellite\/dbs\/es\/estudiantes-de-grado\" rel=\"external nofollow\">Deusto Business School en San Sebasti\u00e1n &#8230;<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u201cIn the long run, we are all dead\u201d es la famosa frase que el economista John Maynard Keynes acu\u00f1\u00f3 en su obra \u201cUn tratado sobre la reforma monetaria\u201d en 1923. En el post de hoy voy a adentrarme en las profundidades de la macroeconom\u00eda, m\u00e1s concretamente, de la teor\u00eda macroecon\u00f3mica (siendo consciente del riesgo; pincha [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":69,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-182","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=182"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/182\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}