{"id":2954,"date":"2025-02-11T11:34:44","date_gmt":"2025-02-11T10:34:44","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=2954"},"modified":"2025-02-11T11:34:44","modified_gmt":"2025-02-11T10:34:44","slug":"la-inversion-extranjera-directa-que-no-llega-al-pais-vasco","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2025\/02\/11\/la-inversion-extranjera-directa-que-no-llega-al-pais-vasco\/","title":{"rendered":"La inversi\u00f3n extranjera directa que (no) llega al Pa\u00eds Vasco"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/02\/Imagen.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2955\" src=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/02\/Imagen-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/02\/Imagen-300x180.png 300w, https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/02\/Imagen.png 752w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La inversi\u00f3n extranjera directa (IED) que entra en Euskadi ha sido un tema de inter\u00e9s recurrente en la prensa de 2024 y 2025, reflejado en titulares como:<\/p>\n<p>\u201c<a href=\"https:\/\/www.elcorreo.com\/economia\/euskadi-ante-reto-atraer-grandes-proyectos-descuidar-20240618003513-nt.html\" rel=\"external nofollow\">Euskadi, ante el reto de atraer grandes proyectos de fuera intensivos en empleo<\/a>\u201d (2024)<\/p>\n<p>\u201c<a href=\"https:\/\/www.elcorreo.com\/economia\/inversion-extranjera-euskadi-hunde-primer-semestre-solo-20241102003734-nt.html\" rel=\"external nofollow\">La inversi\u00f3n extranjera en Euskadi se hunde en el primer semestre hasta solo 71 millones<\/a>\u201d (2024)<\/p>\n<p>\u201c<a href=\"https:\/\/www.elcorreo.com\/economia\/euskadi-convierte-autonomia-mayor-caida-inversion-extranjera-20250106004137-nt.html\" rel=\"external nofollow\">Euskadi se convierte en la autonom\u00eda con la mayor ca\u00edda de la inversi\u00f3n extranjera<\/a>\u201d (2025)<\/p>\n<p>Como sugieren estos titulares, hay una preocupaci\u00f3n por la escasa magnitud de la IED entrante en Euskadi y el retroceso que ha experimentado en el \u00faltimo ejercicio. Es cierto que las cifras m\u00e1s recientes no son alentadoras. Sin embargo, la inversi\u00f3n extranjera directa entrante nunca ha sido un factor determinante para el desarrollo econ\u00f3mico e industrial de la Comunidad Aut\u00f3noma del Pa\u00eds Vasco (CAPV) en su reciente historia.<\/p>\n<p>Un <a href=\"https:\/\/www.orkestra.deusto.es\/es\/investigacion\/publicaciones\/informes\/cuadernos-orkestra\/2747-240022-analisis-inversion-extranjera-directa-economia-vasca-y-sus-empresas-y-valoracion-efecto-sobre-competitividad\" rel=\"external nofollow\">estudio de Orkestra<\/a>, que analiza los flujos de IED entrante en Euskadi entre 2014 y 2021, evidencia que las cantidades anuales de inversi\u00f3n han seguido un patr\u00f3n err\u00e1tico durante ese periodo y que su peso sobre el PIB regional es muy reducido:<\/p>\n<p><strong><em>IED entrante expresado en porcentaje del PIB<\/em><\/strong><\/p>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td width=\"13%\"><strong>\u00a0<\/strong><\/td>\n<td width=\"8%\"><strong>2014<\/strong><\/td>\n<td width=\"8%\"><strong>2015<\/strong><\/td>\n<td width=\"8%\"><strong>2016<\/strong><\/td>\n<td width=\"8%\"><strong>2017<\/strong><\/td>\n<td width=\"8%\"><strong>2018<\/strong><\/td>\n<td width=\"8%\"><strong>2019<\/strong><\/td>\n<td width=\"8%\"><strong>2020<\/strong><\/td>\n<td width=\"8%\"><strong>2021<\/strong><\/td>\n<td width=\"16%\"><strong>Media 2014-2021<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"13%\">CAPV<\/td>\n<td width=\"8%\">4,14<\/td>\n<td width=\"8%\">2,37<\/td>\n<td width=\"8%\">3,19<\/td>\n<td width=\"8%\">2,47<\/td>\n<td width=\"8%\">2,77<\/td>\n<td width=\"8%\">1,21<\/td>\n<td width=\"8%\">2,42<\/td>\n<td width=\"8%\">2,16<\/td>\n<td width=\"16%\">2,59<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>Fuente: Elaboraci\u00f3n propia con datos de DataInvex.<\/em><\/p>\n<p>En los a\u00f1os posteriores, esta (falta de) tendencia se ha mantenido.<a href=\"https:\/\/www.elcorreo.com\/economia\/inversion-extranjera-euskadi-remonta-reduce-septiembre-2023-20240117004031-nt.html\" rel=\"external nofollow\"> En 2022, la IED experimento un incremento significativo, alcanzando el 6,85% del PIB vasco.<\/a> No obstante, en 2023 descendi\u00f3 al 1,77 %, y para 2024 se espera un porcentaje a\u00fan menor (ver link anterior y los dos primeros de arriba).<\/p>\n<p><a href=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/02\/Imagen.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2955\" src=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/02\/Imagen-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/02\/Imagen-300x180.png 300w, https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/02\/Imagen.png 752w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Fuente: Elaboraci\u00f3n propia con datos de DataInvex.<\/em><\/p>\n<p>En su conjunto, no se observa una pauta clara ni una tendencia positiva o negativa sostenida. M\u00e1s bien, la IED entrante en Euskadi parece un fen\u00f3meno vol\u00e1til, sin una direcci\u00f3n definida ni un impulso local que logra canalizarlo de forma deliberada o intencionada. Obviamente, en un contexto global donde los inversores tienen m\u00faltiples opciones geogr\u00e1ficas, Euskadi es solo un destino m\u00e1s cuyas probabilidades (estad\u00edsticas) de captar inversiones son limitadas. Por lo tanto, la CAPV debe intentar mejorar su posicionamiento dentro de este contexto. En este sentido, es comprensible que el lehendakari Pradales se haya referido a la <a href=\"https:\/\/www.elcorreo.com\/economia\/empresas\/pradales-pone-reto-atraer-inversiones-extranjeras-garantizar-20240919144220-nt.html\" rel=\"external nofollow\">obligaci\u00f3n de que Euskadi sea atractiva para la inversi\u00f3n extranjera<\/a>.<\/p>\n<p>A la vista de los resultados de 2024, empezar a obtener mejores resultado debe ser factible. Sin embargo, existen dos factores que pueden obstaculizar o distorsionar esta mejor\u00eda.<\/p>\n<p>El primero es que Euskadi compite en un escenario global y nacional en el que algun(as) regi\u00f3n(es) cuentan con ventajas estructurales. Dentro de Espa\u00f1a, un caso evidente es la Comunidad de Madrid. Como sucede con muchas capitales, Madrid se beneficia del denominado <em>headquarters effect<\/em>, que lleva a muchas empresas a establecer sus sedes en la capital del pa\u00eds, generando un efecto de arrastre para nuevas inversiones. Entre 2014 y 2021, la proporci\u00f3n de inversi\u00f3n extranjera captada por Madrid estuvo muy por encima de su peso en el PIB nacional:<\/p>\n<p><a name=\"_Toc149916095\"><\/a>Comparaci\u00f3n entre la contribuci\u00f3n al PIB nacional y a la IED entrante nacional por Comunidad Aut\u00f3noma durante el periodo 2014-2021<\/p>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td width=\"36%\"><strong>Medida<\/strong><\/td>\n<td width=\"14%\"><strong>Catalunya<\/strong><\/td>\n<td width=\"14%\"><strong>CAPV<\/strong><\/td>\n<td width=\"18%\"><strong>Madrid<\/strong><\/td>\n<td width=\"15%\"><strong>Navarra<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"36%\"><strong>% de IED entrante sobre total<\/strong><\/td>\n<td width=\"14%\">15<\/td>\n<td width=\"14%\">4,75<\/td>\n<td width=\"18%\">65<\/td>\n<td width=\"15%\">0,6<\/td>\n<\/tr>\n<tr>\n<td width=\"36%\"><strong>% de PIB sobre total<\/strong><\/td>\n<td width=\"14%\">19<\/td>\n<td width=\"14%\">6<\/td>\n<td width=\"18%\">20<\/td>\n<td width=\"15%\">1,8<\/td>\n<\/tr>\n<tr>\n<td width=\"36%\"><strong>Ratio<\/strong><\/td>\n<td width=\"14%\">0,79<\/td>\n<td width=\"14%\">0,79<\/td>\n<td width=\"18%\">3,25<\/td>\n<td width=\"15%\">0,33<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>Fuente: Elaboraci\u00f3n propia con datos basados en DataInvex y Eurostat.<\/em><\/p>\n<p>Por ello, un mayor esfuerzo en la captaci\u00f3n de proyectos empresariales para poder competir mejor con regiones como Madrid, a trav\u00e9s de actividades diplom\u00e1ticas y relaciones con inversores a nivel paraestatal, parece una v\u00eda necesaria para mejorar la posici\u00f3n de Euskadi.<\/p>\n<p>El segundo factor es la composici\u00f3n de la IED que llega a Euskadi. La mayor parte de estas inversiones entra en forma de adquisici\u00f3n de empresas ya existentes, en lugar de <em>greenfield investment<\/em> (inversiones destinadas a la creaci\u00f3n de nuevas empresas). Independientemente de la fuente de datos utilizada (FDI Intelligence, DataInvex, Orkestra o Invest in the Basque Country), el porcentaje de <em>greenfield investment<\/em> sobre el total de la IED en Euskadi ha sido ciertamente bajo entre 2014 y 2024. Esta situaci\u00f3n deber\u00eda revertirse, dado que la inversi\u00f3n en nuevas iniciativas empresariales suele generar m\u00e1s empleo y el crecimiento econ\u00f3mico que las adquisiciones. En este sentido, es fundamental evitar que los esfuerzos por atraer IED refuercen m\u00e1s a la compra de empresas existentes que a la creaci\u00f3n de nuevas compa\u00f1\u00edas.<\/p>\n<p>&nbsp;<\/p>\n<p>Bart Kamp<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La inversi\u00f3n extranjera directa (IED) que entra en Euskadi ha sido un tema de inter\u00e9s recurrente en la prensa de 2024 y 2025, reflejado en titulares como: \u201cEuskadi, ante el reto de atraer grandes proyectos de fuera intensivos en empleo\u201d (2024) \u201cLa inversi\u00f3n extranjera en Euskadi se hunde en el primer semestre hasta solo 71 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":21288,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2954","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/2954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/21288"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=2954"}],"version-history":[{"count":1,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/2954\/revisions"}],"predecessor-version":[{"id":2956,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/2954\/revisions\/2956"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=2954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=2954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=2954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}