{"id":3151,"date":"2025-11-25T08:22:48","date_gmt":"2025-11-25T07:22:48","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=3151"},"modified":"2025-11-25T08:22:48","modified_gmt":"2025-11-25T07:22:48","slug":"huevos","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2025\/11\/25\/huevos\/","title":{"rendered":"\u00bfEst\u00e1n los huevos m\u00e1s caros que nunca?"},"content":{"rendered":"<p><a href=\"http:\/\/@inakierauskin.bsky.social\" rel=\"external nofollow\"><u>@inakierauskin.bsky.social <\/u><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.diariovasco.com\/gipuzkoa\/cocinas-400-tortillas-patata-consumen-3000-huevos-20251119163446-nt.html\" rel=\"external nofollow\">Parece que hay cierta alarma con el precio de los huevos.<\/a> Por ejemplo, la docena de huevos que sol\u00eda comprar en el s\u00faper cercano a 2,85\u20ac hacia 2022 ahora est\u00e1 en 4,29\u20ac. Mi baserritarra favorito (\u00bfy el \u00fanico?) de Lasarte-Oria, al que le compro casi todas las verduras todas las semanas, subi\u00f3 la docena de huevos de 3\u20ac a 3,50\u20ac hace tres a\u00f1os (a \u00e9l le subieron el precio del pienso de las gallinas una barbaridad, por la invasi\u00f3n de Ucrania y la crisis del precio del gas) y hace un par de semanas a 3,80\u20ac (la gripe aviar, supongo). Es verdad que el precio nominal de la docena de huevos est\u00e1 m\u00e1s alto que nunca. Se comen m\u00e1s huevos y parece que la gripe aviar tambi\u00e9n est\u00e1 afectando ya negativamente a la oferta. Tal como se\u00f1ala el <a href=\"https:\/\/www.mapa.gob.es\/es\/alimentacion\/temas\/consumo-tendencias\/panel-de-consumo-alimentario\/ultimos-datos\" rel=\"external nofollow\"><strong>Consumo alimentario en Espa\u00f1a <\/strong>Informe anual del consumo alimentario en Espa\u00f1a 2024 del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n (MAPA)<\/a>, \u201cEstos productos alimentarios representan el 1,62 % del presupuesto total destinado a la compra de alimentos de los hogares, con una correspondencia en volumen del 1,56 % de las compras totales. En promedio, cada residente en Espa\u00f1a consume alrededor de 8,95 kilos de huevos [unos 142 huevos] por a\u00f1o, una cantidad mayor en un 1,6 % respecto al a\u00f1o anterior. El gasto medio aproximado por individuo al cierre de 2024 asciende a 28,88\u20ac.\u201d<\/p>\n<p>Pero, \u00bfest\u00e1 el precio de la docena de huevos m\u00e1s alto que nunca teniendo en cuenta la inflaci\u00f3n? Una docena de huevos al por mayor val\u00eda 0,22\u20ac (36,15 pesetas) en diciembre de 1964, seg\u00fan el INE (contrastado con los datos en papel de aquella \u00e9poca en nuestra nueva CRAI en la Universidad de Deusto en Donostia). Los precios medios de hoy son 11,82 veces mayores que los de entonces (los precios han subido 1.082%, por tanto) seg\u00fan el INE. Si se encareciera el precio de los huevos como el nivel medio de precios, los huevos al por mayor deber\u00edan valer 2,57\u20ac. Seg\u00fan los datos del <a href=\"https:\/\/www.mapa.gob.es\/dam\/mapa\/contenido\/estadisticas\/temas\/publicaciones\/informe-semanal-de-coyuntura\/2025\/informesemanaldecoyuntura2025s-23.pdf\" rel=\"external nofollow\">MAPA<\/a>, el precio medio en origen de huevos L de gallinas enjauladas es de 1,81\u20ac. Eso implica que el precio real del huevo ha bajado un 30% aproximadamente, si bien seguramente estos dos precios no sean comparables directamente porque las fuentes, m\u00e9todos, etc., no son las mismas, pero nos da una idea inicial (curiosamente, los c\u00e1lculos de m\u00e1s abajo salen muy parecidos).<\/p>\n<p>Se puede hacer un an\u00e1lisis m\u00e1s completo y riguroso observando la evoluci\u00f3n de los precios mes a mes desde que tenemos todos los datos del IPC general y de los huevos en 1976 (he tenido que enlazar varias bases y he cometido alg\u00fan \u201cpecado\u201d en el proceso, pero peque\u00f1o). El comienzo de las series lo he transformado en enero de 1976=100. La l\u00ednea naranja (eje izquierdo) se\u00f1ala que la cesta de la compra del IPC, si val\u00eda 100 en enero de 1976 vale 1.400 ahora aproximadamente, esto es, el precio medio de la cesta de la compra se multiplic\u00f3 por 14 en estos 50 a\u00f1os. La l\u00ednea roja (eje izquierdo) se\u00f1ala que el IPC del huevo, si val\u00eda 100 en enero de 1976 vale ahora 1.000 aproximadamente, esto es, el precio medio del huevo multiplic\u00f3 por 10 en estos 50 a\u00f1os. Dado que el precio de los huevos ha subido menos que la media general, hoy d\u00eda los huevos son claramente m\u00e1s baratos. \u00bfPero cu\u00e1nto? La l\u00ednea verde (eje derecho) es la ratio entre el IPC del huevo y el IPC general, que comienza en 100 obviamente. En los primeros a\u00f1os, a pesar del comportamiento err\u00e1tico, la tendencia es claramente descendente y la ratio entre el IPC del huevo y el IPC general se sit\u00faa ligeramente por encima de 40 aproximadamente: el huevo es casi un 60% m\u00e1s barato en t\u00e9rminos reales en esos a\u00f1os que en 1976. A mediados de 2003 sube la ratio hasta el entorno de 50, con muchos altibajos, esto es, el huevo es un 50% m\u00e1s barato en t\u00e9rminos reales en esos a\u00f1os que en 1976. Y es comenzando en abril de 2021 y meses siguientes primero, subiendo la ratio hasta algo m\u00e1s de 60, y m\u00e1s recientemente en marzo de 2025 cuando comienza la subida hasta algo m\u00e1s de 70, donde la ratio entre el IPC del huevo y el IPC general ha aumentado mucho. Ahora el huevo es \u201csolo\u201d un 28,31% m\u00e1s barato en t\u00e9rminos reales que en 1976.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gr\u00e1fico 1. Evoluci\u00f3n del IPC de los huevos y del IPC general (enero de 1976=100), y de su ratio.<\/strong><\/p>\n<p><a href=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/11\/2025_Huevos.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3152\" src=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/11\/2025_Huevos.png\" alt=\"\" width=\"568\" height=\"307\" srcset=\"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/11\/2025_Huevos.png 568w, https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-content\/uploads\/sites\/41\/2025\/11\/2025_Huevos-300x162.png 300w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/a><\/p>\n<p>Fuente: INE.<\/p>\n<p>&nbsp;<\/p>\n<p>En suma, hay dos per\u00edodos muy claros en el precio real de los huevos: baj\u00f3 mucho hasta mediados de 2003, y ha ido subiendo a partir de entonces. Los huevos siguen siendo un 30% m\u00e1s baratos que en 1976 en t\u00e9rminos reales (aproximadamente), poco despu\u00e9s de fallecer el dictador Francisco Franco, pero los huevos se han encarecido realmente un 75% desde mediados de 2003.<\/p>\n<p>Esto es lo que les he contado a mis alumnos\/as de macroeconom\u00eda la semana pasada, como primicia. Espero que lo tengan en cuenta de cara al examen que viene \u2026<\/p>\n<p>&nbsp;<\/p>\n<p><u>@inakierauskin.bsky.social <\/u><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>@inakierauskin.bsky.social &nbsp; Parece que hay cierta alarma con el precio de los huevos. Por ejemplo, la docena de huevos que sol\u00eda comprar en el s\u00faper cercano a 2,85\u20ac hacia 2022 ahora est\u00e1 en 4,29\u20ac. Mi baserritarra favorito (\u00bfy el \u00fanico?) de Lasarte-Oria, al que le compro casi todas las verduras todas las semanas, subi\u00f3 la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":69,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3151","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/3151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=3151"}],"version-history":[{"count":1,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/3151\/revisions"}],"predecessor-version":[{"id":3153,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/3151\/revisions\/3153"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=3151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=3151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=3151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}