{"id":567,"date":"2016-11-08T07:54:48","date_gmt":"2016-11-08T06:54:48","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=567"},"modified":"2016-11-08T07:54:48","modified_gmt":"2016-11-08T06:54:48","slug":"panoramica","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2016\/11\/08\/panoramica\/","title":{"rendered":"Una panor\u00e1mica de la econom\u00eda espa\u00f1ola (vasca) desde 1850 (1955)"},"content":{"rendered":"<p><span style=\"font-size: medium;\"><a href=\"https:\/\/twitter.com\/InakiErauskin\" rel=\"external nofollow\"><span style=\"color: #0000ff; font-family: Calibri;\">@InakiErauskin <\/span><\/a><\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">Recientemente, Jordi Maluquer de Motes, Catedr\u00e1tico de Historia e Instituciones Econ\u00f3micas en la Universitat Aut\u00f2noma de Barcelona, ha publicado las series largas de la econom\u00eda espa\u00f1ola, desde 1850 hasta 2015, en su obra \u201cEspa\u00f1a en la econom\u00eda mundial\u201d (Instituto de Estudios Econ\u00f3micos). Ello ofrece una buena oportunidad para echar la vista hacia atr\u00e1s y ver la evoluci\u00f3n de la econom\u00eda espa\u00f1ola desde hace m\u00e1s de 150 a\u00f1os (en la vasca, y parcialmente, desde 1955). Es una tarea enorme y compleja por la falta de datos y porque se combinan, cuando hay datos, distintas series de datos y distintas metodolog\u00edas. El Producto Interior Bruto (PIB) cumple un papel central en las series largas. <\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">La Tabla 1 proporciona las tasas medias anuales de crecimiento del PIB real y del PIB real por habitante en euros del a\u00f1o 2010 en Espa\u00f1a, por per\u00edodos largos. Se observa que, durante todo el per\u00edodo, la tasa de crecimiento media anual del PIB y del PIB real por habitante fue del 2,27% y 1,56%, respectivamente. Ello implica que el PIB se multiplic\u00f3 aproximadamente por 40 (de 25.422 a 1.020.792 millones de euros) y el PIB por habitante por 12,8 (de 1.716\u20ac a 21.974\u20ac) durante este per\u00edodo. En la primera \u201cmitad\u201d de todo este per\u00edodo (columna 1, correspondiente a 1850-1935) las cifras fueron notablemente menores, pero en la segunda (columna 2, correspondiente a 1950-2014) el comportamiento fue mucho mejor.\u00a0 \u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">Tabla 1. Tasas medias anuales de crecimiento, por per\u00edodos largos.<\/span><\/strong><\/span><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"144\"><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/td>\n<td valign=\"top\" width=\"144\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1850-1935<\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"144\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1950-2014<\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"144\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1850-2014<\/span><\/strong><\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"144\"><span style=\"font-family: Calibri; font-size: medium;\">PIB real<\/span><\/td>\n<td valign=\"top\" width=\"144\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1,67<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"144\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,71<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"144\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,27<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"144\"><span style=\"font-family: Calibri; font-size: medium;\">PIB real por habitante<\/span><\/td>\n<td valign=\"top\" width=\"144\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1,03<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"144\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,89<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"144\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1,56<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0Fuente: Jordi Maluquer de Motes (2016). \u201cEspa\u00f1a en la econom\u00eda mundial. Series largas para la econom\u00eda espa\u00f1ola (1850-2015)\u201d. Instituto de Estudios Econ\u00f3micos.<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">Las mejores \u00e9pocas de crecimiento de la renta se pueden observar en la Tabla 2. La de mayor crecimiento fue la que va desde 1960 a 1973. Es la famosa \u201ctreintena gloriosa\u201d de mayor crecimiento mundial en la historia, que en el caso espa\u00f1ol fue un per\u00edodo m\u00e1s corto (comenz\u00f3 un poco antes de los a\u00f1os 60) debido al per\u00edodo aut\u00e1rquico franquista postguerracivilista. Llama la atenci\u00f3n el per\u00edodo 1919-1929, de la \u201cBelle Epoque\u201d o los \u201cfelices a\u00f1os 20\u201d previo al Crac de 1929, que es poco conocido en la literatura econ\u00f3mica. Conviene se\u00f1alar y recordar as\u00ed mismo que el reciente per\u00edodo de expansi\u00f3n 1997-2007, a pesar de todos los elogios que recibe como \u00e9poca singularmente positiva, no fue un ejemplo espectacular de\u00a0 mejora, con una tasa de crecimiento media del PIB per c\u00e1pita de 2,55%.\u00a0\u00a0 <\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">Tabla 2. Tasas medias anuales de crecimiento, en los per\u00edodos de mayor crecimiento.<\/span><\/strong><\/span><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1919-1929<\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1960-1973<\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"108\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1985-1992<\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"106\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1997-2007<\/span><\/strong><\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">PIB real<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">4,38<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">7,73<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"108\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">4,04<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"106\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,81<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">PIB real por habitante<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,42<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">6,59<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"108\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,73<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"106\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,55<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0Fuente: Jordi Maluquer de Motes (2016). \u201cEspa\u00f1a en la econom\u00eda mundial. Series largas para la econom\u00eda espa\u00f1ola (1850-2015)\u201d. Instituto de Estudios Econ\u00f3micos.<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">Los per\u00edodos de menor crecimiento se muestran en la Tabla 3. La m\u00e1s negativa de la historia econ\u00f3mica espa\u00f1ola desde 1850 ha sido el per\u00edodo reciente 2007-2014, exceptuando, claro est\u00e1, el per\u00edodo de la guerra civil durante julio de 1936 y marzo de 1939. Sorprende que la evoluci\u00f3n negativa del per\u00edodo reciente 2007-2014 haya sido peor que el per\u00edodo 1929-1935 correspondiente al Crac del 29.<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">Tabla 3. Tasas medias anuales de crecimiento, en los per\u00edodos de menor crecimiento.<\/span><\/strong><\/span><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1929-1935<\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1935-1950<\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"108\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">1974-1985<\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"106\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">2007-2014<\/span><\/strong><\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">PIB real<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">0,10<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">-0,07<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"108\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1,58<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"106\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">-1,09<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">PIB real por habitante<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">-1,30<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"117\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">-1,06<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"108\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">0,78<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"106\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">-1,47<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0Fuente: Jordi Maluquer de Motes (2016). \u201cEspa\u00f1a en la econom\u00eda mundial. Series largas para la econom\u00eda espa\u00f1ola (1850-2015)\u201d. Instituto de Estudios Econ\u00f3micos.<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: medium;\"><span style=\"font-family: Calibri;\">Sobre las comunidades aut\u00f3nomas se dice bastante menos en este trabajo. Se muestran \u201cs\u00f3lo\u201d las tasas de crecimiento del PIB real (pero no per c\u00e1pita) y los PIB nominales de las comunidades aut\u00f3nomas desde 1955 a 2014. Para tener una visi\u00f3n m\u00e1s amplia de la evoluci\u00f3n de las comunidades aut\u00f3nomas me centrar\u00e9 en el valor a\u00f1adido bruto (VAB) total (como aproximaci\u00f3n al PIB) y en el VAB total por ocupado (como \u201caproximaci\u00f3n\u201d al PIB per c\u00e1pita) para el per\u00edodo 1955-2011, tomados de la base de datos BD-MORES del Ministerio de Hacienda y Administraciones P\u00fablicas (pincha <\/span><a href=\"http:\/\/www.sepg.pap.minhap.gob.es\/sitios\/sepg\/es-ES\/Presupuestos\/Documentacion\/Paginas\/Basesdatosestudiosregionales.aspx\" rel=\"external nofollow\"><span style=\"color: #0000ff; font-family: Calibri;\">aqu\u00ed<\/span><\/a><span style=\"font-family: Calibri;\"> para acceder a la base de datos). \u00a0La Tabla 4 extrae algunos datos b\u00e1sicos sobre varias comunidades aut\u00f3nomas, con un desempe\u00f1o relativamente mejor. El VAB total para Espa\u00f1a creci\u00f3 un 3,60% durante el per\u00edodo y el VAB total por ocupado un 2,60%, que son cifras cercanas a las ofrecidas por Maluquer en la Tabla 1 (arriba) para 1950-2014. Las comunidades que m\u00e1s crecen en este per\u00edodo son las mismas que en el trabajo de Maluquer, si bien difieren en el orden. El VAB total del Pa\u00eds Vasco creci\u00f3 por debajo de la media durante este per\u00edodo y Navarra casi en la media, a semejanza de los resultados de Maluquer. Es en el comportamiento del VAB total por ocupado donde las cifras \u201dsorprenden\u201d m\u00e1s: las comunidades aut\u00f3nomas con menor crecimiento del VAB total (las que est\u00e1n por debajo de la media) tienden a crecer m\u00e1s en el VAB total por ocupado (las que est\u00e1n por encima de la media). Tal es el caso del Pa\u00eds Vasco y de las comunidades aut\u00f3nomas que crecen m\u00e1s en t\u00e9rminos del VAB total por ocupado, como son Extremadura, Galicia y Castilla La Mancha. Sin embargo, no es as\u00ed en el caso de Navarra.<\/span><\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">Tabla 4. Tasas medias anuales de crecimiento, 1955-2011.<\/span><\/strong><\/span><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">VAB total<\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">VAB total por ocupado<\/span><\/strong><\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Madrid<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">4,42<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,11<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Canarias<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">4,35<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,78<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Murcia<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">4,12<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,83<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Baleares<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">4,10<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1,87<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Media<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,60<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,60<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Navarra<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,55<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,14<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Castilla La Mancha<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,32<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,09<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Galicia<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,31<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,12<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Pa\u00eds Vasco<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,17<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,71<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Extremadura<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,06<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">3,48<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"138\"><span style=\"font-family: Calibri; font-size: medium;\">Asturias<\/span><\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,61<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"153\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">2,56<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-size: medium;\"><span style=\"font-family: Calibri;\">\u00a0Fuente: <\/span><a href=\"http:\/\/www.sepg.pap.minhap.gob.es\/sitios\/sepg\/es-ES\/Presupuestos\/Documentacion\/Paginas\/Basesdatosestudiosregionales.aspx\" rel=\"external nofollow\"><span style=\"color: #0000ff; font-family: Calibri;\">Base de datos BD-Mores (Ministerio de Hacienda y Administraciones P\u00fablicas<\/span><\/a><\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">Dejamos para el final el comportamiento reciente de la econom\u00eda espa\u00f1ola. La Tabla 5 muestra los datos del PIB y del PIB per c\u00e1pita, ambos en euros de 2010, desde 2005. Por un lado, se observa que el PIB de 2014 todav\u00eda no ha alcanzado el de 2008, el mayor de la historia, en t\u00e9rminos reales: es un 6,7% menor. Sin embargo, la diferencia es incluso mayo si miramos el PIB per c\u00e1pita, que se halla un 8,3% por debajo del mayor valor en 2008. <\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">Tabla 5. PIB y PIB per c\u00e1pita, en euros de 2010.<\/span><\/strong><\/span><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">PIB <\/span><\/strong><\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-size: medium;\"><strong><span style=\"font-family: Calibri;\">PIB per c\u00e1pita<\/span><\/strong><\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2005<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.006.083<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">23.042<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2006<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.047.106<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">23.604<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2007<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.083.532<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">23.953<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2008<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.093.188<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">23.774<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2009<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.051.077<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">22.668<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2010<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.045.620<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">22.456<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2011<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.046.237<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">22.386<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2012<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.028.000<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">21.982<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2013<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.006.124<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">21.594<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"85\"><span style=\"font-family: Calibri; font-size: medium;\">2014<\/span><\/td>\n<td valign=\"top\" width=\"93\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">1.020.792<\/span><\/p>\n<\/td>\n<td valign=\"top\" width=\"94\">\n<p align=\"center\"><span style=\"font-family: Calibri; font-size: medium;\">21.974<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0Fuente: Jordi Maluquer de Motes (2016). \u201cEspa\u00f1a en la econom\u00eda mundial. Series largas para la econom\u00eda espa\u00f1ola (1850-2015)\u201d. Instituto de Estudios Econ\u00f3micos.<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">Desde luego hay camino por recorrer \u2026<\/span><\/p>\n<p><span style=\"font-family: Calibri; font-size: medium;\">\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-size: medium;\"><a href=\"https:\/\/twitter.com\/InakiErauskin\" rel=\"external nofollow\"><span style=\"color: #0000ff; font-family: Calibri;\">@InakiErauskin<\/span><\/a><\/span><\/p>\n<p><span style=\"font-family: Calibri;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: Calibri;\">\u00a0<\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>@InakiErauskin \u00a0 Recientemente, Jordi Maluquer de Motes, Catedr\u00e1tico de Historia e Instituciones Econ\u00f3micas en la Universitat Aut\u00f2noma de Barcelona, ha publicado las series largas de la econom\u00eda espa\u00f1ola, desde 1850 hasta 2015, en su obra \u201cEspa\u00f1a en la econom\u00eda mundial\u201d (Instituto de Estudios Econ\u00f3micos). Ello ofrece una buena oportunidad para echar la vista hacia atr\u00e1s [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":69,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-567","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=567"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/567\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}