{"id":655,"date":"2017-05-09T06:39:03","date_gmt":"2017-05-09T05:39:03","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/?p=655"},"modified":"2017-05-09T06:39:03","modified_gmt":"2017-05-09T05:39:03","slug":"ha-muerto-la-distancia","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/2017\/05\/09\/ha-muerto-la-distancia\/","title":{"rendered":"\u00bfHa muerto la distancia?"},"content":{"rendered":"<p>Como <a href=\"http:\/\/www.cepii.fr\/PDF_PUB\/wp\/2013\/wp2013-26.pdf\" rel=\"external nofollow\">escrib\u00edan<\/a> Keith Head y Thierry Mayer hace algunos a\u00f1os, si uno se pasea por la secci\u00f3n de empresa de una librer\u00eda se encuentra con t\u00edtulos como \u201cEl Mundo sin fronteras\u201d o \u201cLa distancia ha muerto\u201d. Estos libros defienden que las nuevas tecnolog\u00edas de la comunicaci\u00f3n han eliminado las distancias y, ahora, podemos trabajar y comunicarnos desde cualquier parte del mundo.<\/p>\n<p>Sin embargo, algunas tendencias que observamos en nuestras sociedades no casan bien con esta conclusi\u00f3n. Por ejemplo, las ciudades han crecido en poblaci\u00f3n durante los \u00faltimos a\u00f1os y las personas est\u00e1n dispuestas a pagar precios muy altos por el alquiler o la compra de una vivienda en algunas ciudades. Asimismo, la introducci\u00f3n de las nuevas tecnolog\u00edas de la informaci\u00f3n no ha hecho descender los viajes de negocio.<\/p>\n<p>Estas tendencias se explican si la comunicaci\u00f3n cara a cara todav\u00eda tiene un efecto muy positivo sobre la productividad. Un <a href=\"https:\/\/docs.google.com\/viewer?a=v&#038;pid=sites&#038;srcid=ZGVmYXVsdGRvbWFpbnxqb3JkaWJsYW5lc3ZpZGFsfGd4OjU4Njk0ZDFhNDU2OWM5\">trabajo<\/a> reciente, realizado por Diego Battiston, Jordi Blanes i Vidal y Tom Kirchmaier, utiliza las llamadas a la polic\u00eda de Manchester para comprobar si realmente la comunicaci\u00f3n cara a cara mejora la productividad. Cuando una persona llama a la polic\u00eda de Manchester, un operador recibe la llamada y abre un parte de incidente en el que describe cu\u00e1l es el problema. Este parte aparece en la pantalla del coordinador de la polic\u00eda de la zona en que se ha producido el suceso. El coordinador de zona, tras leer el parte, decide a qu\u00e9 agente o agentes asignar el suceso. La productividad se mide por el tiempo que transcurre entre el momento en que el coordinador de zona recibe el parte y se produce la asignaci\u00f3n del agente. Cuanto menor sea el tiempo transcurrido, mayor ser\u00e1 la productividad del servicio.<\/p>\n<p>Un elemento interesante de este estudio es que en algunas ocasiones el operador que recibe la llamada y el coordinador de zona est\u00e1n en la misma sala. En esos casos, existe la posibilidad de que el coordinador de zona se acerque al operador para recabar cara a cara una mayor informaci\u00f3n sobre el incidente. Los autores muestran que cuando el operador de la llamada y el coordinador de zona est\u00e1n en la misma sala el tiempo necesario para asignar un agente es menor; es decir, poder comunicarse cara a cara mejora la productividad.<\/p>\n<p>\u00bfPor qu\u00e9 el poder hablar cara a cara mejora la productividad? Los autores apuntan diferentes motivos. En primer lugar, como todos sabemos, hablar es una forma muy eficiente de comunicarnos. En segundo lugar, el lenguaje no verbal a\u00f1ade informaci\u00f3n al lenguaje verbal, informaci\u00f3n que en muchos casos ser\u00eda dif\u00edcil de transmitir por escrito. En tercer lugar, al hablar podemos utilizar t\u00e9rminos coloquiales que ofrecen mucha informaci\u00f3n sobre lo que est\u00e1 ocurriendo, que necesitar\u00edan de m\u00e1s desarrollo si los tuvi\u00e9semos que explicar con t\u00e9rminos m\u00e1s formales (los autores se\u00f1alan, adem\u00e1s, que no est\u00e1 bien visto utilizar t\u00e9rminos coloquiales por escrito). Los autores confirman estas ideas al comprobar que la productividad de la comunicaci\u00f3n cara a cara es mayor cuando el incidente es m\u00e1s complejo de explicar, cuando es m\u00e1s urgente, y cuando los coordinadores de zona tienen m\u00e1s carga de trabajo.<\/p>\n<p>Por tanto, si tienen que decir algo importante a su compa\u00f1ero de trabajo, olv\u00eddense del correo y del whatsapp, y comun\u00edquenlo cara a cara. Ser\u00e1 mucho m\u00e1s eficiente.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Como escrib\u00edan Keith Head y Thierry Mayer hace algunos a\u00f1os, si uno se pasea por la secci\u00f3n de empresa de una librer\u00eda se encuentra con t\u00edtulos como \u201cEl Mundo sin fronteras\u201d o \u201cLa distancia ha muerto\u201d. Estos libros defienden que las nuevas tecnolog\u00edas de la comunicaci\u00f3n han eliminado las distancias y, ahora, podemos trabajar y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":68,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-655","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/comments?post=655"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/posts\/655\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/media?parent=655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/categories?post=655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/ekonomiaren-plaza\/wp-json\/wp\/v2\/tags?post=655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}