{"id":1206,"date":"2010-07-15T09:16:24","date_gmt":"2010-07-15T09:16:24","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1206"},"modified":"2010-07-15T09:16:24","modified_gmt":"2010-07-15T09:16:24","slug":"nacho_cano_anunciaba_la_boda_de_pe_y_ja","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2010\/07\/15\/nacho_cano_anunciaba_la_boda_de_pe_y_ja\/","title":{"rendered":"Nacho Cano anunciaba la boda de Pe y Ja"},"content":{"rendered":"<p><P>Para alguien que sepa leer el lenguaje corporal estaba claro que los ojos de alfiler de Nacho Cano en el set de Cuatro anunciaban que Pe y Ja ya se hab\u00edan casado. Los dem\u00e1s nos confundimos porque no supimos ver m\u00e1s que a un&nbsp;na\u00fafrago de Ibiza donde lo que hab\u00eda era un heraldo del desamor.<\/P><br \/>\n<P>Y Pe y Ja&nbsp;se han casado siguiendo las \u00faltimas tendencias que en materia sentimental ha introducido en Espa\u00f1a el mundo de la far\u00e1ndula, esto es, mediante la deslocalizaci\u00f3n del amor a territorio extranjero. Ellos fueron los pioneros con la c\u00e9lebre declaraci\u00f3n de Cannes, pero desde Johannesburgo Casillas y Carbonero se sumaron con entusiasmo a esta moda. <\/P><br \/>\n<P>Los cin\u00e9filos han querido ver en la boda de las Bahamas el preludio de un nuevo&nbsp;rodaje conjunto de la pareja. Al fin y al cabo, recorrer la filmograf\u00eda de Pe es pasear a trav\u00e9s de su vida sentimental. De Tom Cruise a Matt Damon, pasando por Mathew Mcconaughey o Nicholas Cage, reales o imaginarias, sus relaciones sentimentales se cuentan por estrenos cinematogr\u00e1ficos. En este sentido, cabe leer su matrimonio con Bardem en clave de remake hollywoodiense.<\/P><br \/>\n<P>La pareja, que no aguanta la presi\u00f3n a la que le somete la prensa del coraz\u00f3n espa\u00f1ola, soportar\u00eda a\u00fan menos que \u00e9sta no informara de sus \u00faltimos acontecimientos. Por eso, se ha apresurado a comunicar su boda en las Bahamas por mucho de que la validez jur\u00eddica en Espa\u00f1a de la ceremonia est\u00e9 a\u00fan por ver.<\/P><br \/>\n<P>Para su desgracia, el&nbsp;ex m\u00fasico de Mecano se anticip\u00f3 en 24 horas al anuncio oficial. Por cierto, si esa especie de tren el\u00e9ctrico que, bajo el nombre de Nacho Cano, pas\u00f3 el lunes por la tele es el resultado de sus seis a\u00f1os de noviazgo con la actriz, ya puede ir despidi\u00e9ndose Javier Bardem de su sistema nervioso central.&nbsp;Si le llega a ver la madre Teresa&#8230;<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Para alguien que sepa leer el lenguaje corporal estaba claro que los ojos de alfiler de Nacho Cano en el set de Cuatro anunciaban que Pe y Ja ya se hab\u00edan casado. Los dem\u00e1s nos confundimos porque no supimos ver m\u00e1s que a un&nbsp;na\u00fafrago de Ibiza donde lo que hab\u00eda era un heraldo del desamor. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1206","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1206"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1206\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}