{"id":1228,"date":"2010-08-11T10:25:50","date_gmt":"2010-08-11T10:25:50","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1228"},"modified":"2010-08-11T10:25:50","modified_gmt":"2010-08-11T10:25:50","slug":"maria_la_portuguesa_tipologia_y_personal","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2010\/08\/11\/maria_la_portuguesa_tipologia_y_personal\/","title":{"rendered":"Mar\u00eda la Portuguesa: tipolog\u00eda y personalidad"},"content":{"rendered":"<p>Dada nuestra situaci\u00f3n geogr\u00e1fica y tras descartarse que fuera euskoaut\u00f3ctona -demasiado sociable-, hab\u00eda varias posibles opciones en cuanto a su nacionalidad. Pod\u00eda ser la t\u00edpica &#8216;carabela francesa&#8217;, pero su desd\u00e9n por los pintxos hizo descartar esa posibilidad. La hip\u00f3tesis de los &#8216;piratas somal\u00edes&#8217; se descart\u00f3 desde un principio. Finalmente, se determin\u00f3 que era portuguesa por descarte, una vez que colocada frente a la placa de la Diputaci\u00f3n Foral, los expertos observaron que no reaccionaba.<\/p>\n<p>La &#8216;carabela portuguesa&#8217; no ha venido a nuestras costas a hacer el trabajo que las alima\u00f1as marinas del pa\u00eds se niegan a realizar, esto es, picar al personal latinoamericano del servicio dom\u00e9stico y a los menores magreb\u00edes en r\u00e9gimen de acogida.<\/p>\n<p>Al contrario. Desde el primer d\u00eda se ha sentido como en casa, repartiendo abrazos el\u00e9ctricos entre propios y extra\u00f1os, con especial querencia por los primeros, bien debido a las propiedades de su carne -fruto de una dieta exquisita-, bien por motivos de oportunidad, dado nuestro car\u00e1cter intr\u00e9pido en todo lo relacionado con la mar.<\/p>\n<p>Las hay a cientos. Los expertos pronto no tendr\u00e1n otra explicaci\u00f3n razonable que recurrir al argumento del efecto llamada. Por el momento, adem\u00e1s de unos cuantos atendidos por picaduras, el fen\u00f3meno &#8216;carabelas portuguesas&#8217; ya nos han dejado unas cuantas estampas para el futuro reportaje &#8216;Aquel verano del 2010&#8217;.<\/p>\n<p>Ah\u00ed est\u00e1 hoy en la prensa el alcalde, Od\u00f3n Elorza. Ante la plaga, podr\u00eda haber adoptado varias posiciones, todas ellas explicadas con todo detalle en &#8216;Tibur\u00f3n&#8217;. Primero, imitar al alcalde de Amity y negar que ba\u00f1arse en la playa conlleve riesgo alguno, luego, ofrecer una recompensa por la captura de la bestia. En lugar de todo eso, prefiri\u00f3 ayer enfundarse la gorra de Quint -el due\u00f1o del barco- y embarcarse en el &#8216;Antxeta&#8217;, qui\u00e9n sabe si al grito de: &#8220;\u00a1Hooper, aguante el tim\u00f3n!&#8221;. No iba solo: le acompa\u00f1aba Alberto Rodr\u00edguez.<\/p>\n<p>Fue una jornada aventurera, con sabor a viento del norte y salitre. Con todo, una vez concluida la traves\u00eda, la conclusiones era definitivas: liderazgo compartido -entre los municipios afectados por la plaga- y colaboraci\u00f3n interinstitucional- entre todo el que pueda poner un duro-. Que la broma amenaza con salir por un pico, valga la expresi\u00f3n. <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Dada nuestra situaci\u00f3n geogr\u00e1fica y tras descartarse que fuera euskoaut\u00f3ctona -demasiado sociable-, hab\u00eda varias posibles opciones en cuanto a su nacionalidad. Pod\u00eda ser la t\u00edpica &#8216;carabela francesa&#8217;, pero su desd\u00e9n por los pintxos hizo descartar esa posibilidad. La hip\u00f3tesis de los &#8216;piratas somal\u00edes&#8217; se descart\u00f3 desde un principio. Finalmente, se determin\u00f3 que era portuguesa por [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1228","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1228"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1228\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}