{"id":1240,"date":"2010-08-27T10:41:21","date_gmt":"2010-08-27T10:41:21","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1240"},"modified":"2010-08-27T10:41:21","modified_gmt":"2010-08-27T10:41:21","slug":"la_liga_en_el_ojo_ajeno_y_la_caja_en_el_","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2010\/08\/27\/la_liga_en_el_ojo_ajeno_y_la_caja_en_el_\/","title":{"rendered":"La Liga en el ojo ajeno y la caja, en el propio"},"content":{"rendered":"<p>Ha llegado el momento de estar alerta porque no podemos permitir que el Gobierno utilice Afganist\u00e1n y las pensiones para distraernos de los temas realmente enjundiosos, por encima de todos ellos, el f\u00fatbol. Y la Liga est\u00e1 a punto de arrancar. Lo s\u00e9 porque he visto que los peri\u00f3dicos deportivos ya andan regalando el preservativo oficial del F\u00fatbol Club Barcelona.<\/p>\n<p>La vida \u00fatil del ciudadano medio consiste en perorar entre semana sobre las alineaciones m\u00e1s adecuadas, las estrategias m\u00e1s id\u00f3neas y las trayectorias m\u00e1s acreditadas para, una vez llegado el domingo, pulverizar con rabia el boleto de la Quiniela, que rar\u00edsima vez supera los cinco resultados acertados.<\/p>\n<p>No cabe esperar grandes cosas de esta Liga empobrecida: el \u00fanico equipo que se ha permitido un gran desembolso en materia de fichajes rutilantes ha sido el de Deportes de la Cope. El resto deber\u00e1 conformarse con las habituales incorporaciones ignotas disfrazadas de hip\u00e9rbole.<\/p>\n<p>En el centro de toda esta tormenta se sit\u00faan la infancia. Desde un punto de vista puramente local, la temporada comienza al parecer con el objetivo absurdo de que a su t\u00e9rmino los ni\u00f1os guipuzcoanos hayan cambiado sus camisetas del Bar\u00e7a por las de la Real, una quimera porque si hay algo que cautiva a los enanos es ganar siempre y si hay algo que aborrecen es perder por costumbre. Al menos, contamos en el banquillo con un hombre que, seg\u00fan propia confesi\u00f3n, cay\u00f3 en Paulo Coelho y, sin embargo, demostr\u00f3 que tambi\u00e9n de ah\u00ed se puede salir.<\/p>\n<p>Y si resulta inevitable que el f\u00fatbol sea una escuela de vida, hay que evitar por todos los medios el mal ejemplo que supone la supuesta compra-venta de partidos a final de temporada. \u00bfPor qu\u00e9 dejarlo todo para el final? \u00bfAcaso no ser\u00eda mucho m\u00e1s pr\u00e1ctico hacerlo al principio? Y luego hablaremos de la importancia de arrancar con un buen colch\u00f3n de puntos&#8230;  <\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ha llegado el momento de estar alerta porque no podemos permitir que el Gobierno utilice Afganist\u00e1n y las pensiones para distraernos de los temas realmente enjundiosos, por encima de todos ellos, el f\u00fatbol. Y la Liga est\u00e1 a punto de arrancar. Lo s\u00e9 porque he visto que los peri\u00f3dicos deportivos ya andan regalando el preservativo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1240","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1240"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1240\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}