{"id":1244,"date":"2010-09-01T08:56:31","date_gmt":"2010-09-01T08:56:31","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1244"},"modified":"2010-09-01T08:56:31","modified_gmt":"2010-09-01T08:56:31","slug":"gitanos_en_transito_es_una_redundancia","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2010\/09\/01\/gitanos_en_transito_es_una_redundancia\/","title":{"rendered":"Gitanos en tr\u00e1nsito"},"content":{"rendered":"<p>La vieja escuela marxista nos ense\u00f1\u00f3 que la \u00e9tica no es nada, sino es una \u00e9tica aplicada. La frase &#8220;todos los pol\u00edticos son unos ladrones&#8221; no implica su deportaci\u00f3n, si no el refrendo mediante sufragio universal de todos ellos en sus cargos, en algunos casos, incluyendo entre el meritaje de su CV su historial judiciall, mejor cuanto m\u00e1s turbio y abigarrado, v\u00e9ase el caso Fabra. Y si por alg\u00fan error en el normal desarrollo del proceso judicial dan con sus huesos en la c\u00e1rcel, nada que no pueda solucionar una fianza millonaria, saldr\u00e1n entre las ovaciones de sus vecinos.<\/p>\n<p>En cambio, el enunciado &#8220;todos los gitanos son unos ladrones&#8221; puede conllevar su expulsi\u00f3n de cualquier&nbsp;pa\u00eds europeo, seg\u00fan la nueva doctrina de pogromo para tiempos de Espacio Schengen. Italia, cuna de tantas tendencias art\u00edsticas, inaugur\u00f3 esta pr\u00e1ctica de la mano de Berlusconi, harto de contemplar desde Villa Certosa a tanto gitano indolente. Y Sarkozy ha continuado en Francia con su personal forma de entender aquello del efecto llamada -llamada a la expulsi\u00f3n, cabr\u00eda matizar-. Todo esto, en un espacio judicial europeo que garantiza la libre circulaci\u00f3n de las personas, las mercanc\u00edas y los capitales.<\/p>\n<p>El hecho de que la medida se lleve por delante de forma palmaria las leyes de la UE constituye apenas una ligera molestia. De hecho, cazar roman\u00edes a lazo&nbsp;y expulsarlos sin mediar mayores acusaciones, m\u00e1s all\u00e1 de su molesta condici\u00f3n \u00e9tnica,&nbsp;constituye una arraigada pr\u00e1ctica europea que se remonta a la noche de los tiempos.<\/p>\n<p>Han sido las coartadas las que m\u00e1s han evolucionado. A las acusaciones de robar ni\u00f1os les siguieron diversas&nbsp;leyes, en Espa\u00f1a, la de&nbsp;de vagos y&nbsp;maleantes. As\u00ed, hemos llegado hoy al argumento de&nbsp;los asentamientos ilegales, un&nbsp;rapto de humor en una Europa que ha convertido todas sus costas en una sucesi\u00f3n de urbanizaciones infames levantadas a golpe de soborno. Si alguien quiere ver asentamientos humanos ilegales&nbsp;y a mansalva, ah\u00ed est\u00e1 la Costa mediterr\u00e1nea espa\u00f1ola, ah\u00ed est\u00e1 Google Earth.<\/p>\n<p>Aqu\u00ed hay una gran tolerancia hacia el diferente siempre que su renta per c\u00e1pita le alcance como&nbsp;para comprarse la condici\u00f3n de exc\u00e9ntrico. El resto permanecer\u00e1 al socaire de los vaivenes del mercado y, luego, ya buscaremos el aparato te\u00f3rico que arropen las medidas a adoptar: los africanos son ilegales, los magreb\u00edes pasan sus d\u00edas deliquiendo, los latinoamericanos empiezan a contarnos sus penas apenas han terminado de hacer las tareas de casa -de la nuestra, se entiende-, y los chinos, bueno, \u00e9stos s\u00f3lo trabajan, lo que demuestra que algo ocultan.<\/p>\n<p>Vivimos en un mundo muy perro en el que los argumentos est\u00e1n muy bien, pero cuya cotizaci\u00f3n tiende a subir en Bolsa si les respalda una cierta fuerza coercitiva. Israel, ese invento pol\u00edtico considerado por tantos europeos como &#8220;la entidad sionista&#8221;,&nbsp;acab\u00f3 milagrosamente, casi se dir\u00eda que m\u00e1gica, con siglos de persecuciones, expulsones&nbsp;y matanzas&nbsp;de jud\u00edos, precisamente -iron\u00edas de la Historia-, en toda esta Europa, la misma que ahora tanto se calla.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La vieja escuela marxista nos ense\u00f1\u00f3 que la \u00e9tica no es nada, sino es una \u00e9tica aplicada. La frase &#8220;todos los pol\u00edticos son unos ladrones&#8221; no implica su deportaci\u00f3n, si no el refrendo mediante sufragio universal de todos ellos en sus cargos, en algunos casos, incluyendo entre el meritaje de su CV su historial judiciall, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1244","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1244"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1244\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}