{"id":1246,"date":"2010-09-03T10:22:32","date_gmt":"2010-09-03T10:22:32","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1246"},"modified":"2010-09-03T10:22:32","modified_gmt":"2010-09-03T10:22:32","slug":"september_song","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2010\/09\/03\/september_song\/","title":{"rendered":"September Song"},"content":{"rendered":"<p>1) \u00c9ste es el mes en el que los cr\u00edos reaparecen como &#8216;sherpas&#8217; de s\u00ed mismos en su expedici\u00f3n de vuelta a la escuela. All\u00ed adquirir\u00e1n los conocimientos necesarios para manejarse en la vida: defensa y ataque, aprendizaje y olvido, ensayo y resignaci\u00f3n. El resto -para entendernos, lo que no sirve para nada-, ir\u00e1 en la descomunal mochila, un fetiche m\u00e1gico que al menos tranquiliza la conciencia de quienes pagan las facturas de todo esto, normalmente, los padres.<\/p>\n<p>2) En el caso de los adolescentes, la mochila ya ha reducido su tama\u00f1o y, sobre todo, su peso. Su lugar lo ocupan los equipamientos deportivos, que \u00faltimamente siempre incluyen alg\u00fan tipo de casco, con los que llenan su abigarrado programa de actividades extraescolares, m\u00e1s all\u00e1 del aprendizaje de idiomas y las clases de solfeo, entre otras actividades. En todas ellas tratar\u00e1n de despertar la admiraci\u00f3n de sus compa\u00f1eros, aunque en la mayor\u00eda de los casos deber\u00e1n conformarse con les admitan, les acepten o incluso les toleren. Alguno no conseguir\u00e1 ninguna de las cuatro cosas.<\/p>\n<p>3) Los bancos seguir\u00e1n restringiendo el cr\u00e9dito -pero el Gobierno dir\u00e1 que el ciclo ha cambiado-, los parados aumentar\u00e1n a raz\u00f3n de 2.000 al d\u00eda -y la ministra leer\u00e1 signos positivos en los gr\u00e1ficos- y los comerciantes se quejar\u00e1n de que no se vende nada -pero se publicar\u00e1 que la recaudaci\u00f3n emite se\u00f1ales de franca recuperaci\u00f3n-. Y si los conocimientos adquiridos por los estudiantes de los puntos 1 y 2 no les alcanzar\u00e1n como para entender algo, al menos les ser\u00e1n enormemente \u00fatiles a la hora de aceptarlo sin rechistar.<\/p>\n<p>4) De entre las masas alienadas, emerger\u00e1n los nuevos l\u00edderes sociales que, para sorpresa de todos, ser\u00e1n los mismos de siempre. De ellos admiraremos su manejo de las situaciones de riesgo, su forma de gestionar las crisis, la optimizaci\u00f3n de los recursos y el pastoreo de grupos humanos. En efecto, ser\u00e1n Guardiola y Mourinho, que adem\u00e1s impartir\u00e1n desde sus respectivas ruedas de prensa unas sencillas lecciones de etiqueta al alcance de cualquiera.<\/p>\n<p>5) Y todo culminar\u00e1 a final de mes en una traca final digna de Caballer: Festival de Cine con relevo en la direcci\u00f3n. Al d\u00eda siguiente, recala en el Estadio de Anoeta la nueva gira de U2, que si bien no acabar\u00e1 con el hambre en el mundo, al menos s\u00ed que combatir\u00e1 el apetito. <\/p>\n<p>6) Y para rematar, un jurado internacional especialista en capitalidades europeas decidir\u00e1 qu\u00e9 ciudades de las diecis\u00e9is candidatas se merecen a Od\u00f3n de alcalde, qui\u00e9n sabe, si entre ellas estar\u00e1 San Sebasti\u00e1n. Por cierto, la decisi\u00f3n se anunciar\u00e1 el d\u00eda 29, convocatoria de una huelga general que se antoja tan descontextualizada como gritar \u00a1\u00a1\u00a1goooool!!! y abrazar a todo el mundo en el bar cuando Iniesta meta gol durante la redifusi\u00f3n de la final de Espa\u00f1a por alg\u00fan canal deportivo.<br \/>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>1) \u00c9ste es el mes en el que los cr\u00edos reaparecen como &#8216;sherpas&#8217; de s\u00ed mismos en su expedici\u00f3n de vuelta a la escuela. All\u00ed adquirir\u00e1n los conocimientos necesarios para manejarse en la vida: defensa y ataque, aprendizaje y olvido, ensayo y resignaci\u00f3n. El resto -para entendernos, lo que no sirve para nada-, ir\u00e1 en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1246","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1246"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1246\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}