{"id":1252,"date":"2010-09-12T11:00:18","date_gmt":"2010-09-12T11:00:18","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1252"},"modified":"2010-09-12T11:00:18","modified_gmt":"2010-09-12T11:00:18","slug":"nunca_te_creas_al_servidor","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2010\/09\/12\/nunca_te_creas_al_servidor\/","title":{"rendered":"Nunca te creas al servidor"},"content":{"rendered":"<p><P>La tecnolog\u00eda est\u00e1 aqu\u00ed para facilitarnos la existencia y agilizar los tr\u00e1mites. Dicho lo cual, si afrontas un problema que requiere soluci\u00f3n inmediata lo mejor&nbsp;sigue siendo personarse en el lugar&nbsp;porque ante cada conflicto de intereses -y todos lo son-, el contacto humano es irremplazable, aunque s\u00f3lo sea por la coacci\u00f3n f\u00edsica impl\u00edcita. <\/P><br \/>\n<P>Nuestra obligaci\u00f3n como consumidores es proveernos de un pack m\u00ednimo compuesto por tel\u00e9fono m\u00f3vil, ordenador port\u00e1til y libro electr\u00f3nico, siempre desde la certeza de que llegado el momento crucial, no habr\u00e1 cobertura, el m\u00f3dem habr\u00e1 fallecido y la bater\u00eda estar\u00e1 agotada. <\/P><br \/>\n<P>Internet, de hecho, lo puede todo, desde buscarte pareja hasta venderte entradas. A cambio, s\u00f3lo exige una confianza ciega, con&nbsp;ese encantador&nbsp;puntillo de insensatez. La primera cita puede que certifique que la persona que te cibersedujo es en realidad un calvo con barriga que, sin embargo, insiste en presentarse con una ce\u00f1ida camiseta de la Real&nbsp;o una ex reina de la belleza poligonera que antes de&nbsp;la cita,&nbsp;se pinta las u\u00f1as y&nbsp;durante el encuentro,&nbsp;se las come.&nbsp;Tambi\u00e9n puede que acontezca todo lo contrario y la experiencia resulte maravillosamente gratificante.<\/P><br \/>\n<P>En el otro supuesto, el&nbsp;de la venta de entradas, no hay margen para la sorpresa: el servidor&nbsp;se ha ca\u00eddo. Siempre lo hace. Con tanta&nbsp;frecuencia, que cualquiera sospechar\u00eda que se tira.&nbsp;El festival de m\u00fasica m\u00e1s multitudinario de la historia ser\u00e1 aqu\u00e9l que re\u00fana frente a un gran escenario a todas las personas que un d\u00eda se perdieron el concierto de su vida porque&nbsp;intentaron comprar la entrada por internet.&nbsp;<\/P><br \/>\n<P>Ahora mismo, el servidor que tramita las entradas del Zinemaldia est\u00e1 por los suelos y, como a la cantante de Mecano, no hay quien lo levante. Ante el luctuoso suceso 2.0, se podr\u00e1n comentar muchas cosas, salvo aquello de &#8220;\u00bfqui\u00e9n lo iba a decir?&#8221; <\/P><br \/>\n<P>Frente a la opci\u00f3n de quedarte&nbsp;maldiciendo en soledad ante&nbsp;el teclado y la pantalla, una actividad que multiplica la ansiedad, est\u00e1 la de hacer cola frente a las taquillas del Kursaal. No es descartable que el servidor tambi\u00e9n se haya ca\u00eddo all\u00ed, pero al menos, te proporciona un desahogo en forma de explosi\u00f3n de ira mucho m\u00e1s personalizada, entablar una relaci\u00f3n con los compa\u00f1eros de infortunio y, llegado el caso, hacer nuevos enemigos.<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La tecnolog\u00eda est\u00e1 aqu\u00ed para facilitarnos la existencia y agilizar los tr\u00e1mites. Dicho lo cual, si afrontas un problema que requiere soluci\u00f3n inmediata lo mejor&nbsp;sigue siendo personarse en el lugar&nbsp;porque ante cada conflicto de intereses -y todos lo son-, el contacto humano es irremplazable, aunque s\u00f3lo sea por la coacci\u00f3n f\u00edsica impl\u00edcita. Nuestra obligaci\u00f3n como [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1252","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1252"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1252\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}