{"id":1277,"date":"2010-10-11T10:05:41","date_gmt":"2010-10-11T10:05:41","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1277"},"modified":"2010-10-11T10:05:41","modified_gmt":"2010-10-11T10:05:41","slug":"no_hay_peor_ciego_que_el_nobel","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2010\/10\/11\/no_hay_peor_ciego_que_el_nobel\/","title":{"rendered":"No hay peor ciego que el Nobel"},"content":{"rendered":"<p><P>Hay premios que se prestigian, no por los nomobres que luce en su palmar\u00e9s, sino por las ausencias que exhibe. Aqu\u00ed se podr\u00eda citar el Planeta, pero por motivos de actualidad, habr\u00e1 que centrarse en el Nobel.<\/P><br \/>\n<P>Que a estas alturas, haya articulistas que consideren que&nbsp;con el Nobel de Literatura, Mario Vargas Llosa se garantiza&nbsp;la &#8220;inmortalidad&#8221; (\u00bf?),&nbsp;resulta de una ingenuidad rayana con lo lerdo y obliga a indicar en qu\u00e9 librer\u00edas&nbsp;se pueden encontrar disponibles las obras -siquiera incompletas- de otros ilustres galardonados, tipo Jos\u00e9 de&nbsp;Echegaray o&nbsp;Gao Xingjian, por citar a dos de los decenas de escritores premiados en su d\u00eda y hoy, olvidados.<\/P><br \/>\n<P>El reconocimiento que se acaba de llevar Vargas Llosa ha desatado la previsible oleada de art\u00edculos de opini\u00f3n sobre lo grande que fue cuando era de izquierdas, y lo diminuto que se hizo al convertirse al neoliberalismo. Est\u00e1s cr\u00edticas est\u00e1n lastradas en su credibilidad por el silencio, cuando no aplauso, con el que se acogieron las distinciones cuando reca\u00edan en derivados del opio -como Saramago- o directamente en insectos -como Dar\u00edo Fo-.<\/P><br \/>\n<P>Y por supuesto, tambi\u00e9n se ha dado el fen\u00f3meno contrario: abundan estos d\u00edas&nbsp;los art\u00edculos en los que se&nbsp;ejemplifica en la persona de Vargas Llosa&nbsp;la posibilidad real de salir del infierno izquierdista para convertirse en un ciudadano de provecho, como si hubiera escrito el grueso de&nbsp;su obra tras licenciarse en un Proyecto Hombre para &#8216;rojos&#8217; en proceso de rehabilitaci\u00f3n. <\/P><br \/>\n<P>Sirvan como ejemplo de lo uno y de lo otro los art\u00edculos de Anson y del cr\u00edtico de &#8216;Gara&#8217;, empe\u00f1ados ambos de rebautizar por error&nbsp;la novela de Vargas Llosa como &#8216;Conversaciones en la catedral&#8217; -en plural la primera, en min\u00fasculas, la segunda-.<\/P><br \/>\n<P>Por cierto, en torno a todo esto hay mucha confusi\u00f3n. Por un lado se nos asegura que la literatura es una actividad anacr\u00f3nica llamada a desaparecer en la sociedad de la imagen a manos de nuevos formatos -de los que la publicidad entendida como la poes\u00eda del siglo XXI ser\u00eda la punta de lanza-, pero, por otro, a\u00fan hay quien califica al escritor peruano de &#8220;peligroso derechista&#8221;. Derechista, puede, pero \u00bfpeligroso? \u00bfAcaso cabe&nbsp;a estas alturas del iPad, del Iphone y del Ipod mayor elogio para alguien que finalmente tan s\u00f3lo se dedica&nbsp;a escribir?<\/P><br \/>\n<P>En la misma l\u00ednea se sit\u00faan las autoridades chinas, que en lugar de acudir a las mazmorras en las que cumple condena el disidente premiado para informarle de que ha ganado el mismo galard\u00f3n&nbsp;que Henry Kissinger, se dedican a organizarle un encuentro con su mujer para que se lo susurre, justo antes de incomunicar a ambos,&nbsp;no vaya a ser que los otros mil millones de&nbsp;chinos se enteren de la noticia y, lo que ser\u00eda a\u00fan peor, se enteren de que su protagonista tambi\u00e9n se ha enterado.&nbsp;<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay premios que se prestigian, no por los nomobres que luce en su palmar\u00e9s, sino por las ausencias que exhibe. Aqu\u00ed se podr\u00eda citar el Planeta, pero por motivos de actualidad, habr\u00e1 que centrarse en el Nobel. Que a estas alturas, haya articulistas que consideren que&nbsp;con el Nobel de Literatura, Mario Vargas Llosa se garantiza&nbsp;la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1277","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1277"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1277\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}