{"id":1286,"date":"2010-10-21T10:04:31","date_gmt":"2010-10-21T10:04:31","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1286"},"modified":"2010-10-21T10:04:31","modified_gmt":"2010-10-21T10:04:31","slug":"jose_luis_cesa_a_rodriguez_y_nombra_a_za","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2010\/10\/21\/jose_luis_cesa_a_rodriguez_y_nombra_a_za\/","title":{"rendered":"Jos\u00e9 Luis cesa a Rodr\u00edguez y nombra a Zapatero"},"content":{"rendered":"<p>Tras su encontronazo con los mercados en general y con Standard &#038; Poor&#8217;s en particular, Zapatero se ha visto obligado a remodelar su maltrecho gobierno. Recapitulemos: ZP, gran aficionado al basket -antes, baloncesto-, revolucion\u00f3 el panorama pol\u00edtico al ser el primero en jugar con cheerleaders -de ambos sexos-, en detrimento de los titulares, que han estado calentando el banquillo.<\/p>\n<p>La experiencia se ha saldado con resultados nefastos, as\u00ed que el presidente ha echado mano de la tradici\u00f3n, en este caso, de \u00e9sa que en la que Espa\u00f1a fue vanguardia y que consiste en que el titular de Interior sea siempre el ministro mejor valorado por la ciudadan\u00eda. <\/p>\n<p>De esta extra\u00f1a pulsi\u00f3n, ins\u00f3lita en Europa durante los a\u00f1os sententa, ochenta y noventa, se beneficiaron personajes como Barrionuevo, Corcuera o Acebes. S\u00f3lo la utilizaci\u00f3n de los fondos reservados para alimentar la ludopat\u00eda de Amedo pudo con los dos primeros, mientras que las mentiras flagrantes en tiempo real pulverizaron el prestigio del segundo. <\/p>\n<p>En cualquier caso, la tendencia ha hecho fortuna en todo el continente y ah\u00ed tenemos hoy a Sarkozy, cuyo antiguo espiritu antidisturbios se manifiesta hoy en d\u00eda en su decisi\u00f3n de reprimir a los huelguistas recurriendo si fuera necesario a cualquier medio a su disposici\u00f3n, incluida la discograf\u00eda de Carla Bruni. <br \/>&nbsp;<br \/>Ahora se encarama hasta lo m\u00e1s alto el propio P\u00e9rez Rubalcaba, el \u00fanico ministro que cuenta con su propia banda tributo, Eduardo Madina. Al parecer, Alfredo hace cima de la mano del interminable conflicto vasco, inopinadamente llamado a ocupar otra vez el epicentro de la pugna electoral, una vez descartada cualquier la opci\u00f3n de recuperaci\u00f3n econ\u00f3mica a medio plazo.<\/p>\n<p>Los cambios ministeriales dejan otras perlas: Rosa Aguilar ocupar\u00e1 la cartera de Medio Ambiente tras acreditar su infinita capacidad de sobrevivir en cualquier h\u00e1bitat, por hostil que \u00e9ste sea. Probablemente, su versatilidad le permitir\u00e1 continuar en el Gobierno, incluso una vez que lo presida Rajoy.<\/p>\n<p>El sindicalista Valeriano G\u00f3mez se sit\u00faa al frente de Trabajo. Ya nos hab\u00edamos acostumbrado a ver a ex etarras militar en el Constitucionalismo, pero se supon\u00eda que la evoluci\u00f3n era fruto de un largo proceso de reflexi\u00f3n. G\u00f3mez, sin embargo, ha pasado de manifestarse en contra de las reformas laborales y a tener que gestionarlas en tan s\u00f3lo un mes. Un b\u00f3lido pol\u00edtico.<\/p>\n<p>De Leire Paj\u00edn ha llamado la atenci\u00f3n su afici\u00f3n a la &#8216;power balance&#8217;, aparentemente, incompatible con el cargo de ministra de Sanidad, aunque s\u00f3lo lo ser\u00eda si se demostra que la utiliza como sustitutivo de su tratamiento. En cuanto a Ram\u00f3n J\u00e1uregui, su aparici\u00f3n sorpresa en el Ministerior de Presidencia debe ser interpretada m\u00e1s en clave anacr\u00f3nica que &#8216;vintage&#8217;, como cuando en una peli de romanos aparece un centuri\u00f3n luciendo un R\u00f3lex en la mu\u00f1eca.<\/p>\n<p>El PP se ha cansado en los \u00faltimos a\u00f1os de manifestar su a\u00f1oranza por el &#8216;felipismo&#8217;. El PSOE ha decidido saciar esa nostalgia. No ser\u00e1 suficiente. Rajoy ya ha reiterado su exigencia&nbsp; de que se disuelva el pueblo y se convoquen comicios de inmediato para elegir a otro nuevo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tras su encontronazo con los mercados en general y con Standard &#038; Poor&#8217;s en particular, Zapatero se ha visto obligado a remodelar su maltrecho gobierno. Recapitulemos: ZP, gran aficionado al basket -antes, baloncesto-, revolucion\u00f3 el panorama pol\u00edtico al ser el primero en jugar con cheerleaders -de ambos sexos-, en detrimento de los titulares, que han [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1286","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1286"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1286\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}