{"id":1292,"date":"2010-10-27T09:49:53","date_gmt":"2010-10-27T09:49:53","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1292"},"modified":"2010-10-27T09:49:53","modified_gmt":"2010-10-27T09:49:53","slug":"sanchez_drago_en_japon_v_o_s","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2010\/10\/27\/sanchez_drago_en_japon_v_o_s\/","title":{"rendered":"S\u00e1nchez-Drag\u00f3, en Jap\u00f3n (V.O.S.)"},"content":{"rendered":"<p>&#8220;En Tokio, un d\u00eda, me top\u00e9 con unas lolitas. Corr\u00eda el a\u00f1o 1967&#8221;.<br \/><i>&#8220;Cuando estuve en Tokio en 1967, me pas\u00e9 el d\u00eda m\u00e1s solo que la una. Desesperado, termine por intentar entablar conversaci\u00f3n con dos damas&#8221;.<\/p>\n<p><\/i>&#8220;Pero no eran una lolitas cualesquiera, sino de \u00e9sas que se visten como zorritas, con los labios pintados, carm\u00edn, r\u00edmel, tacones, minifalda&#8230;&#8221;<i><br \/>&#8220;Eran unas se\u00f1ora ya entradas en a\u00f1os y escuetas de carnes. Iban con la cara lavada, la depilaci\u00f3n sin hacer, unas cejas poblad\u00edsimas y ataviadas con sendos kimonos de los de cuerpo entero&#8221;.<\/p>\n<p><\/i>&#8220;Tendr\u00edan unos trece a\u00f1os&#8221;.<i><br \/>&#8220;Tendr\u00edan unos 113 a\u00f1os, quiz\u00e1s 112, es <\/i><i>que soy muy malo calculando la edad de la gente. En todo caso, los japoneses son muy longevos&#8221;.<\/p>\n<p><\/i>&#8220;Sub\u00ed con ellas y las muy putas se pusieron a turnarse. Mientras una se iba al v\u00e1ter, la otra me trajinaba&#8221;.<i><br \/>&#8220;Les entr\u00e9 a las dos. &#8216;\u00bfBailas?&#8217;, le pregunt\u00e9 a la una. &#8216;\u00bfEstudias o trabajas?&#8217;, interrogu\u00e9 a la otra. <\/i><i> &#8216;Desaparece de mi vista, mamarracho&#8217;, replic\u00f3 la primera. &#8216;Que te pires&#8217;, recalc\u00f3 la segunda. Ante mi insistencia en entablar conversaci\u00f3n, se fueron juntas al v\u00e1ter, a vomitar, creo&#8221;.<\/p>\n<p><\/i>&#8220;El crimen ha prescrito, as\u00ed que puedo contarlo, aparte de que las delincuentes eran ellas, no yo. Es una an\u00e9cdota trivial y sin mucha chicha convertida en literatura&#8221;.<i><br \/>&#8220;Suelo adornar esta an\u00e9cdota trivial y, para qu\u00e9 negarlo, ligeramente bochornosa, para convertirla en literatura. La \u00faltima vez que lo hice fue para un libro de Boadella, que se lo traga todo. En todo caso, la mentira ha prescrito porque se la cont\u00e9 ya hace unos meses. Adem\u00e1s, al salir del v\u00e1ter, las dos ancianas depositaron sus dentaduras postizas en mi vaso de sake, as\u00ed que las delincuentes fueron ellas. Por cierto, estaba riqu\u00edsimo&#8221;.<br \/>&nbsp;<\/p>\n<p>&nbsp;<\/i><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&#8220;En Tokio, un d\u00eda, me top\u00e9 con unas lolitas. Corr\u00eda el a\u00f1o 1967&#8221;.&#8220;Cuando estuve en Tokio en 1967, me pas\u00e9 el d\u00eda m\u00e1s solo que la una. Desesperado, termine por intentar entablar conversaci\u00f3n con dos damas&#8221;. &#8220;Pero no eran una lolitas cualesquiera, sino de \u00e9sas que se visten como zorritas, con los labios pintados, carm\u00edn, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1292","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1292"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1292\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}