{"id":1494,"date":"2011-07-22T09:34:42","date_gmt":"2011-07-22T09:34:42","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1494"},"modified":"2011-07-22T09:34:42","modified_gmt":"2011-07-22T09:34:42","slug":"los_tiempos_estan_cambiando_de_anticiclo","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2011\/07\/22\/los_tiempos_estan_cambiando_de_anticiclo\/","title":{"rendered":"Los tiempos est\u00e1n cambiando: de anticicl\u00f3n a borrasca"},"content":{"rendered":"<p>El calentamiento global no est\u00e1 re\u00f1ido con el enfriamiento local. Desde que en el hemisferio norte empez\u00f3 el verano, las temperaturas se han desplomado debido a la p\u00e9rdida de confianza de los mercados en la meteorolog\u00eda, reducida a un mon\u00f3tono sistema binario en el que las previsiones se reducen a adivinar si har\u00e1 un tiempo oto\u00f1al o simplemente uno invernal.<\/p>\n<p>Todo este fen\u00f3meno est\u00e1 dejando en evidencia a los negacionistas del cambio clim\u00e1tico. \u00c9ste se ha producido, si bien es cierto que no en la direcci\u00f3n prevista. La mutaci\u00f3n ha sorprendido a los expertos en climatolog\u00eda impartiendo cursos de verano ante un alumnado en chubasquero al que, pese a todas las evidencias, insisten en instruir en en el correcto uso de cremas protectoras factor 40, en lugar de ilustrar sobre las prestaciones de buen paraguas chino.<\/p>\n<p>No disfrut\u00e1bamos de un verano tan intempestivo desde el pasado mes de enero. Expresiones de toda la vida, como &#8220;esto son cuatro gotas&#8221; o &#8220;parece que quiere levantar&#8221; se han convertido en un anacronismo de lujo. En cuanto a &#8220;esto va a acabar en galerna&#8221; ya es tan s\u00f3lo una forma de expresar la nostalgia. Y qu\u00e9 decir de la polemica sobre los toldos, que vista con la perspectiva que da el paso del tiempo, se antoja una variaci\u00f3n del cuento de los calvos que se pelearon por un peine.<\/p>\n<p>El fen\u00f3meno abre las puertas a m\u00faltiples lecturas pol\u00edticas. De hecho, con Od\u00f3n languidec\u00eda la iluminaci\u00f3n navide\u00f1a, tambi\u00e9n pero las temperaturas estivales invitaban al solaz playero. Con Bildu ha llegado la inestabilidad barom\u00e9trica, todo un reto para el observatorio de Igeldo. <\/p>\n<p>En efecto, los tiempos est\u00e1n cambiando y donde antes hab\u00eda anticicl\u00f3n, ahora hay borrasca. De las suaves temperaturas y cielos despejados que cabr\u00eda esperar de un<br \/>\nverano sometido a los rigores de un proceso de normalizaci\u00f3n no queda ni rastro.<\/p>\n<p>El PSE podr\u00e1 cambiar el mapa del tiempo, pero se ha demostrado que el clima es competencia exclusiva de la izquierda abertzale. Dig\u00e1moslo claramente: Bildu se ha cargado de un plumazo el verano donostiarra, seguramente, por su raigambre mon\u00e1rquica y su aroma espa\u00f1ol. <\/p>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El calentamiento global no est\u00e1 re\u00f1ido con el enfriamiento local. Desde que en el hemisferio norte empez\u00f3 el verano, las temperaturas se han desplomado debido a la p\u00e9rdida de confianza de los mercados en la meteorolog\u00eda, reducida a un mon\u00f3tono sistema binario en el que las previsiones se reducen a adivinar si har\u00e1 un tiempo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1494","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1494"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1494\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}