{"id":1497,"date":"2011-07-26T12:26:16","date_gmt":"2011-07-26T12:26:16","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1497"},"modified":"2011-07-26T12:26:16","modified_gmt":"2011-07-26T12:26:16","slug":"diez_cosas_que_hacer_en_donostia_sin_par","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2011\/07\/26\/diez_cosas_que_hacer_en_donostia_sin_par\/","title":{"rendered":"Diez cosas que hacer en Donostia sin paraguas"},"content":{"rendered":"<p><P>1) Quedarte en el hotel viendo todos los cap\u00edtulos de &#8216;Verano azul&#8217; como quien visita &#8216;Las edades del hombre&#8217;.<\/P><br \/>\n<P>2) Llevar a los ni\u00f1os al Aquarium para que vean a la duquesa de Alba y amenazarles con volver ma\u00f1ana si no se portan bien.<\/P><br \/>\n<P>3) Leer a los ni\u00f1os el programa cultural de Donostia 2016 para que aprendan que en la vida no todo es pas\u00e1rselo bien.<\/P><br \/>\n<P>4) Escuchar la discograf\u00eda entera de los Beach Boys como quien oye psicofon\u00edas procedentes de una \u00e9poca remota.<\/P><br \/>\n<P>5) Comentar lo bonito y embarrado que sol\u00eda estar&nbsp;Chillida-Leku en d\u00edas como \u00e9stos.<\/P><br \/>\n<P>6) Escuchar &#8216;Summertime&#8217; para elevar la &#8216;saudade&#8217;&nbsp;a los niveles superiores a los de cualquier&nbsp;fado.<\/P><br \/>\n<P>7) Llevar a los ni\u00f1os al Ayuntamiento para que lo peinen en busca del retrato del rey.<\/P><br \/>\n<P>8) Debatir con la familia durante largas horas en torno a cu\u00e1l ha posido ser la causa de la muerte de Amy Winehouse.<\/P><br \/>\n<P>9) Ir de tiendas toda la tarde por el campamento de los &#8216;indignados&#8217;, compartiendo todo lo que tengan, y&nbsp;huir a la carrera en el momento en el que empiecen con&nbsp;las asambleas.<\/P><br \/>\n<P>10) Hacer la reserva en el hotel para volver en navidades, esta vez, con la sombrilla y el traje de ba\u00f1o.<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>1) Quedarte en el hotel viendo todos los cap\u00edtulos de &#8216;Verano azul&#8217; como quien visita &#8216;Las edades del hombre&#8217;. 2) Llevar a los ni\u00f1os al Aquarium para que vean a la duquesa de Alba y amenazarles con volver ma\u00f1ana si no se portan bien. 3) Leer a los ni\u00f1os el programa cultural de Donostia 2016 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5],"class_list":["post-1497","post","type-post","status-publish","format-standard","hentry","category-2","tag-703_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1497"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1497\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}