{"id":1736,"date":"2012-02-15T09:35:48","date_gmt":"2012-02-15T08:35:48","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1736"},"modified":"2012-02-15T09:35:48","modified_gmt":"2012-02-15T08:35:48","slug":"el-rey-revela-a-nadal-que-los-guinoles-son-munecos-de-mentira","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2012\/02\/15\/el-rey-revela-a-nadal-que-los-guinoles-son-munecos-de-mentira\/","title":{"rendered":"El rey revela a Nadal que los gui\u00f1oles son mu\u00f1ecos de mentira"},"content":{"rendered":"<p>En una nueva demostraci\u00f3n de que no hay manera de que el Rey permanezca ajeno a los desvelos de los espa\u00f1oles, expresados formalmente en conversaciones de tasca y oficina, don Juan Carlos alumbr\u00f3 ayer a Rafa Nadal con una de sus habituales revelaciones: &#8220;Estos de los gui\u00f1oles son tontos&#8221;, anunci\u00f3 el monarca al campe\u00f3n de la raqueta.<\/p>\n<p>Lo hizo en una conversaci\u00f3n privada captada por un micr\u00f3fono abierto,\u00a0 un formato que en estos tiempos de sobreinformaci\u00f3n lleva camino de convertirse en el m\u00e1s apropiado para lograr que tu mensaje llegue con nitidez a todo el mundo.<\/p>\n<p>En su infinita campechan\u00eda, el rey, que nunca ha ocultado su admiraci\u00f3n por Nadal tanto en su faceta deportiva como tributaria, acostumbra a realizar este tipo de declaraciones. As\u00ed, tras salvar la democracia en repetidas ocasiones, recientemente anunci\u00f3 que la ley es igual para todos. O quiz\u00e1s lo que dijo fue que todos somos iguales ante la ley, tanto da, ya que es la t\u00edpica frase-calzoncillo a la que se le puede dar la vuelta cuando se mancha por un lado.<\/p>\n<p>El rey tampoco olvid\u00f3 advertir al tenista de que los gui\u00f1oles son mu\u00f1ecos sin vida propia. El desliz estuvo en la elecci\u00f3n del adjetivo &#8220;tonto&#8221; en alguien que, m\u00e1s pronto que tarde, tendr\u00e1 que hacer acopio de todo su aplomo para sostener p\u00fablicamente que su hija ignoraba por completo las actividades econ\u00f3micas perpetradas por su marido.<\/p>\n<p>En cualquier caso, el soberano habl\u00f3 con la autoridad que le otorga el hecho de llevar 37 a\u00f1os ininterrumpidos en antena, con gran \u00e9xito de cr\u00edtica y p\u00fablico, por cierto, una longevidad cat\u00f3dica que los gui\u00f1oles franceses ni sue\u00f1an con alcanzar, menos en un pa\u00eds que retir\u00f3 a la monarqu\u00eda de sus parrillas televisivas all\u00e1 por 1789.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En una nueva demostraci\u00f3n de que no hay manera de que el Rey permanezca ajeno a los desvelos de los espa\u00f1oles, expresados formalmente en conversaciones de tasca y oficina, don Juan Carlos alumbr\u00f3 ayer a Rafa Nadal con una de sus habituales revelaciones: &#8220;Estos de los gui\u00f1oles son tontos&#8221;, anunci\u00f3 el monarca al campe\u00f3n de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1736","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1736"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1736\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}