{"id":1808,"date":"2012-04-13T08:32:36","date_gmt":"2012-04-13T07:32:36","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1808"},"modified":"2012-04-13T08:32:36","modified_gmt":"2012-04-13T07:32:36","slug":"ares-no-asume-responsabilidades-sino-que-las-absorbe","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2012\/04\/13\/ares-no-asume-responsabilidades-sino-que-las-absorbe\/","title":{"rendered":"Ares absorbe todas las responsabilidades"},"content":{"rendered":"<p>Al eslogan propagand\u00edstico que asegura que &#8220;quien no es de izquierdas a los veinte a\u00f1os no tiene coraz\u00f3n y quien lo sigue siendo a los cuarenta no tiene cerebro&#8221; cabr\u00eda a\u00f1adirle que el PSOE ofrece una inmejorable oportunidad de cubrir la totalidad de este circuito vital en el seno de un mismo partido. <\/p>\n<p>Cuesta sobreponerse al estupor, pero hay que asumir la posiblidad de que Rodolfo Ares fuera en tiempos un joven airado. Ayer, en su actual condici\u00f3n de consejero de Interior, compareci\u00f3 ante la correspondiente comisi\u00f3n del Parlamento Vasco para explicar las circunstancias que rodearon la muerte de I\u00f1igo Cabacas. Ares pidi\u00f3 perd\u00f3n y asumi\u00f3 todas las responsabilidades pol\u00edticas. Sin embargo, una vez descartada la posibilidad de presentar la dimisi\u00f3n, la expresi\u00f3n queda reducida a una mera f\u00f3rmula de cortes\u00eda eviscerada de cualquier significado. Esto se traduce en que Ares no asume responsabilidad alguna, pero de ser necesario las absorber\u00e1 todas. <\/p>\n<p>Como aqu\u00ed todo se pega, tras entonar esta suerte de &#8216;lepoan hartu ta segi aurrera, el responsable m\u00e1ximo de la Ertzaintza apel\u00f3 a la teor\u00eda del contexto. Al parecer, los agentes fueron recibidos con una lluvia de vasos y botellas. Que amainara el temporal cost\u00f3 una vida.  <\/p>\n<p>M\u00e1s inquietante a\u00fan si cabe fue la intervenci\u00f3n del jefe de la Ertzaintza, Jos\u00e9 Antonio Varela, qui\u00e9n asegur\u00f3 que el disparo se efectu\u00f3 a una distancia no inferior a 22 metros, que no fue dirigido directamente a la v\u00edctima y que la trayectoria de este material &#8220;es err\u00e1tica&#8221;. Como no cabe dudar de sus palabras, resulta obligado preguntarse qu\u00e9 clase de armamento ha estado utilizando la Polic\u00eda Auton\u00f3mica en las \u00faltimas d\u00e9cadas, as\u00ed como qui\u00e9n y bajo qu\u00e9 criterios consider\u00f3 que era el m\u00e1s adecuado.<\/p>\n<p>Al menos, en el haber de Ares y Varela cabe apuntar que, por vez primera en estos casos, no se han registrado intentos de culpabilizar a la v\u00edctima de su propia muerte, m\u00e1s all\u00e1 de que algunos medios madrile\u00f1os sirvieron la tentaci\u00f3n en bandeja al interrogarse sobre la presencia de Cabacas en las inmediaciones de una herriko taberna, una l\u00ednea de razonamiento que recuerda poderosamente a aquellas &#8216;invitaciones&#8217; a no pasar cerca de cuarteles y comisar\u00edas. <\/p>\n<p>En el barullo vasco, cada una de las partes enfrentadas se ha encargado de cumplir a rajatabla las profec\u00edas m\u00e1s apocal\u00edpticas de sus enemigos. Ya lo dijo Nietzsche: &#8220;Cuando miras al abismo, el abismo te mira tambi\u00e9n a ti&#8221;. C\u00f3mo estar\u00e1n las cosas que uno de los agentes implicados en el letal &#8216;operativo&#8217; se ha visto obligado a declarar: &#8220;No somos asesinos&#8221;, una cuesti\u00f3n fuera de toda duda. Lo que toca investigar es si alguno de ellos es un homicida. La reconciliaci\u00f3n resulta un tanto complicada si ni siquiera se sabe con qui\u00e9n toca hacerlo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Al eslogan propagand\u00edstico que asegura que &#8220;quien no es de izquierdas a los veinte a\u00f1os no tiene coraz\u00f3n y quien lo sigue siendo a los cuarenta no tiene cerebro&#8221; cabr\u00eda a\u00f1adirle que el PSOE ofrece una inmejorable oportunidad de cubrir la totalidad de este circuito vital en el seno de un mismo partido. Cuesta sobreponerse [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1808","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1808"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1808\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}