{"id":1813,"date":"2012-04-18T08:33:21","date_gmt":"2012-04-18T07:33:21","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1813"},"modified":"2012-04-18T08:33:21","modified_gmt":"2012-04-18T07:33:21","slug":"un-impero-en-el-que-nunca-se-pone-el-show","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2012\/04\/18\/un-impero-en-el-que-nunca-se-pone-el-show\/","title":{"rendered":"Un imperio en el que nunca se pone el show"},"content":{"rendered":"<p>Los tiempos en los que los chistes comenzaban con la frase &#8220;van un espa\u00f1ol, un franc\u00e9s, un alem\u00e1n y un ingl\u00e9s&#8230;&#8221; ya quedaron atr\u00e1s. El emparejamiento estaba por encima de nuestras posibilidades. Ahora Espa\u00f1a se ha convertido en esa naci\u00f3n que el 80% de los estadounidenses siempre sospech\u00f3, con buen tino, que fue: un pa\u00eds centroamericano. La vieja sentencia de C\u00e1novas del Castillo -&#8220;espa\u00f1ol es el que no puede ser otra cosa&#8221;- sigue m\u00e1s vigente que nunca. Estamos en un pa\u00eds que s\u00f3lo resulta cre\u00edble cuando se toma a si mismo a la ligera. En estos momentos, el gesto severo de Rajoy desata la carcajada global.<\/p>\n<p>Hoy en d\u00eda, no eres nadie en el mundo del humor si no mencionas al menos un par de veces la palabra &#8216;Espa\u00f1a&#8217; en tus mon\u00f3logos. Ni Rajoy y Rubalcaba hablaron tanto del pa\u00eds antes del 20-N como los cancidatos franceses a la Presidencia de la Rep\u00fablica. Debimos sospechar que algo raro pasaba cuando los gui\u00f1oles franceses convert\u00edan en objeto de chanzas los \u00e9xitos deportivos de nuestros campeones, la \u00fanica disciplina en la que la &#8216;marca Espa\u00f1a&#8217; a\u00fan despunta, bien es cierto que bajo m\u00e1s sospechas de tongo que los propios Presupuestos Generales del Estado. En este punto, constatar que la reacci\u00f3n del Gobierno de Rajoy fue en aquella ocasi\u00f3n mucho m\u00e1s r\u00e1pida y contundente que frente a la expropiaci\u00f3n de YPF, aunque igual de est\u00e9ril.<\/p>\n<p>Las chuflas se acumulan. Se levanta el tel\u00f3n y aparece la Casa Real anunciando que el monarca est\u00e1 al tanto de todo lo que se est\u00e1 diciendo sobre sus correr\u00edas -circunstancia incompatible con su fren\u00e9tica recuperaci\u00f3n-, a la vez que infanta Elena asegura con gesto severo que no se ha enterado de nada porque esta trabajando, lo cual si bien no justifica por s\u00ed misma nuestra dantesca situaci\u00f3n econ\u00f3mica, ayuda al menos a comprenderla en toda su magnitud.<\/p>\n<p>La reina, por su parte, protagoniza el lunes la vuelta m\u00e1s r\u00e1pida al hospital en el que yace su marido, almuerza con \u00e9l el martes en un picnic cl\u00ednica de tres horas que a su majestad debieron antoj\u00e1rsele interminables -dado el salafismo de estricta observancia vegetariana de Sof\u00eda de Grecia- y anuncia para hoy que saldr\u00e1 con neum\u00e1ticos para lluvia y el dep\u00f3sito medio lleno, lo que le obligar\u00e1 a ir tres paradas.<\/p>\n<p>M\u00e1s: estaban Rajoy y su banda -antes, su gobierno- persuadiendo al resto del mundo de la cat\u00e1strofe que la decisi\u00f3n de Cristina Fern\u00e1ndez supondr\u00e1 para la econom\u00eda mundial, cuando en esto que va el ministro de Exteriores y asegura que el pa\u00eds suramericano &#8220;se ha pegado un tiro en el pie&#8221;. Se espera que Froil\u00e1n replique en breve mediante un escueto comunicado: &#8220;Margassho, sos un pelotudo&#8221;. Como tel\u00f3n de fondo, TVE suprime el &#8216;Espa\u00f1oles en el mundo&#8217; dedicado a La Patagonia, abochorna imaginar el estupor con el que ser\u00e1 acogida la noticia en el Cono Sur.  <\/p>\n<p>Y para colmo, el Fondo Monetario Internacional irrumpe inopinadamente en medio de todo este guirigay para advertir que al PP quiz\u00e1s se le haya ido la mano en los recortes, dado que en cualquier caso su objetivo de d\u00e9ficit para 2013 no se alcanzar\u00e1 antes de 2018. Esto significa que Espa\u00f1a, aquel imperio en el que nunca se pon\u00eda el sol, pasar\u00e1 alg\u00fan tiempo en r\u00e9gimen de colonia alemana antes de convertirse, qui\u00e9n sabe cuando, en un pa\u00eds emergente.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los tiempos en los que los chistes comenzaban con la frase &#8220;van un espa\u00f1ol, un franc\u00e9s, un alem\u00e1n y un ingl\u00e9s&#8230;&#8221; ya quedaron atr\u00e1s. El emparejamiento estaba por encima de nuestras posibilidades. Ahora Espa\u00f1a se ha convertido en esa naci\u00f3n que el 80% de los estadounidenses siempre sospech\u00f3, con buen tino, que fue: un pa\u00eds [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1813","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1813"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1813\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}