{"id":1814,"date":"2012-04-19T07:29:51","date_gmt":"2012-04-19T06:29:51","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1814"},"modified":"2012-04-19T07:29:51","modified_gmt":"2012-04-19T06:29:51","slug":"disculpen-las-muletas","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2012\/04\/19\/disculpen-las-muletas\/","title":{"rendered":"Disculpen las muletas"},"content":{"rendered":"<p>Para su debut en la petici\u00f3n de disculpas, el rey ha optado por echar mano de la tradici\u00f3n hispano-\u00e1rabe y del infame refr\u00e1n que aconseja que &#8220;al llegar a casa, dale una paliza a tu mujer si t\u00fa no sabes por qu\u00e9, ella s\u00ed lo sabe&#8221; y le ha dado la vuelta cual calcet\u00edn sudado para reconocer que se he equivocado y que no volver\u00e1 a ocurrir. No ha necesitado entrar en los escabrosos detalles que rodean su equivocaci\u00f3n y su prop\u00f3sito de la enmienda ya que da por hecho que nosotros s\u00ed lo sabemos.<\/p>\n<p>Espa\u00f1a no es un pa\u00eds de mon\u00e1rquicos, sino de s\u00fabditos. Por eso, la opini\u00f3n p\u00fablica ya se ha apresurado a absolverle de todos sus pecados. No todos los d\u00edas un lacayo est\u00e1 en disposici\u00f3n de perdonar a su rey. De hecho, se sab\u00eda que el acto de contricci\u00f3n p\u00fablica llegar\u00eda ya que los m\u00e1s entusiastas hab\u00edan introducido un espoiler en la trama al anticiparse con su perd\u00f3n a la petici\u00f3n de disculpas. Le han perdonado incluso los escasos ciudadanos que a\u00fan conservan su puesto de trabajo y que, al igual que la infanta Elena, a\u00fan no saben ni el qu\u00e9.<\/p>\n<p>Borb\u00f3n y Borb\u00f3n ha demostrado que el viejo lema de &#8220;haz el amor y no la guerra&#8221; planteaba una falsa disyuntiva por cuanto es posible dedicar las noches a lo primero y los d\u00edas a lo segundo o viceversa. Incluso es probable que, forzando indecisos, se pueda practicar ambas actividades a la vez, bien es cierto que quiz\u00e1s ya no a los 74 a\u00f1os.<\/p>\n<p>Por segunda vez en un mismo reinado, el monarca ha salvado la democracia del embrollo en el que \u00e9l mismo la hab\u00eda metido. Su comportamiento ser\u00e1 disculpable, pero su persona es inimputable, por lo tanto, sus errores son imperdonables. Se dir\u00e1 que todo esto es tremendamente injusto y arbitrario, pero qu\u00e9 sistema levantado sobre una monarqu\u00eda no lo es. <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Para su debut en la petici\u00f3n de disculpas, el rey ha optado por echar mano de la tradici\u00f3n hispano-\u00e1rabe y del infame refr\u00e1n que aconseja que &#8220;al llegar a casa, dale una paliza a tu mujer si t\u00fa no sabes por qu\u00e9, ella s\u00ed lo sabe&#8221; y le ha dado la vuelta cual calcet\u00edn sudado [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1814","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1814"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1814\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}