{"id":1830,"date":"2012-04-29T19:24:54","date_gmt":"2012-04-29T18:24:54","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/eljukebox\/?p=1830"},"modified":"2012-04-29T19:24:54","modified_gmt":"2012-04-29T18:24:54","slug":"otro-maldito-articulo-sobre-guardiola","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/eljukebox\/2012\/04\/29\/otro-maldito-articulo-sobre-guardiola\/","title":{"rendered":"Otro maldito art\u00edculo sobre Guardiola"},"content":{"rendered":"<p>Cuando el pasado viernes Guardiola convocaba al Planeta Tierra para anunciarle eso de &#8220;me he vaciado, necesito volver a llenarme&#8221;, el universo entero se puso de pie para saludar la noticia con id\u00e9ntica ovaci\u00f3n a la que le hubiera dedicado si hubiera dicho &#8220;me he llenado, necesito volver a vaciarme&#8221;. No obstante, todos hemos acabado por asumir que esa frase reversible oculta una revelaci\u00f3n de gran calado. Ya no es que el mensaje sea el medio, si no que el primero ha devorado al segundo cort\u00e9smente en un men\u00fa de plato \u00fanico. <\/p>\n<p>A partir de ese momento, se abrieron las puertas del Parnaso -que es algo casi peor que las del infierno- y no hubo rapsoda, ni vate que no glosara las virtudes del catal\u00e1n. Han pasado 72 horas y Asurancet\u00farix a\u00fan contin\u00faa ta\u00f1endo la lira. Se han llegado a publicar art\u00edculos cuyos autores desentra\u00f1aban la biograf\u00eda de Guardiola a trav\u00e9s de un pormenorizado recuento de los pelos que ha perdido en estos \u00faltimos cuatro a\u00f1os, no digo m\u00e1s. Estoy dispuesto a aceptar resignadamente que el f\u00fatbol sea una met\u00e1fora de la vida o incluso al rev\u00e9s, pero empiezo a considerar un acto de abierta hostilidad la lectura de los santos evangelios de Guardiola, seg\u00fan cualquiera. <\/p>\n<p>Lo m\u00e1s probable es que Pep tan s\u00f3lo haya actuado durante todo este tiempo dej\u00e1ndose llevar por el dictado de su car\u00e1cter, pero ya se sabe, siempre hay gente agazapada dispuesta a convertirte, a la que te descuidas, en un ejemplo a seguir. El entrenador del Bar\u00e7a se retira despu\u00e9s de haber agotado todos los adjetivos, ahora toca que todos los adjetivos nos agoten a nosotros.<\/p>\n<p>Hace alg\u00fan tiempo, pongamos por caso, un tal Alberto Ormaetxea pod\u00eda ganar con el m\u00e1s modesto de los equipos un par de Ligas y llegar a semifinales de esa cosa que ahora llaman pomposamente la Champions, sin convertirse de inmediato de v\u00edctima de los buscadores de Brians. Sin embargo, ahora empiezas a ver descuidadamente un partido de f\u00fatbol y al finalizar, no s\u00f3lo conoces los nombres y apellidos de todos los jugadores, sino que durante el descanso has visto a sus madres anunciar yogures, has abrazado la filosof\u00eda vital del entrenador y hasta te has formado una opini\u00f3n acabada sobre su segundo, ya sea Tito Vilanova o Karanka. En este punto, me pregunto si el mundo supo de la existencia de Boronat, me respondo que no y a\u00f1ado que es lo normal.  <\/p>\n<p>La retirada de Guardiola constituye, sin duda, un drama, pero no tanto para los amantes del buen f\u00fatbol, que tambi\u00e9n, como para el resto de los mortales. Mientras trabajaba para Qatar, al menos se manten\u00eda ocupado preparando un partido del siglo tras otro. Ahora, nada le impide entregarse de cuerpo y alma a la actividad criminal de moda, esto es, propinar charlas y conferencias sobre la gesti\u00f3n de grupos, el \u00e9xito en la crisis o el liderazgo convulso. Cruyff ya lo hizo antes.<\/p>\n<p>Si estamos condenados a vivir en una sociedad an\u00f3nima deportiva de la que no es posible apostatar, quisiera reivindicar el derecho inalienable a ser un asocial, consciente de que ni a\u00fan as\u00ed me liberar\u00e9 de las obligaciones inherentes a la condici\u00f3n de accionista involuntario del club de tus amores. No es que no sienta los colores, es que soy dalt\u00f3nico. En cuanto a las camisetas, las veo en blanco y negro por entero, si exceptuamos el nombre del patrocinador. <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cuando el pasado viernes Guardiola convocaba al Planeta Tierra para anunciarle eso de &#8220;me he vaciado, necesito volver a llenarme&#8221;, el universo entero se puso de pie para saludar la noticia con id\u00e9ntica ovaci\u00f3n a la que le hubiera dedicado si hubiera dicho &#8220;me he llenado, necesito volver a vaciarme&#8221;. No obstante, todos hemos acabado [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1830","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/comments?post=1830"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/posts\/1830\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/media?parent=1830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/categories?post=1830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/eljukebox\/wp-json\/wp\/v2\/tags?post=1830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}