{"id":1285,"date":"2019-05-16T09:00:54","date_gmt":"2019-05-16T07:00:54","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/fotograma\/?p=1285"},"modified":"2019-06-07T10:14:35","modified_gmt":"2019-06-07T08:14:35","slug":"kutsidazu-bidea-ixabel","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/fotograma\/2019\/05\/16\/kutsidazu-bidea-ixabel\/","title":{"rendered":"&#8216;Kutsidazu bidea, Ixabel&#8217;: menos es m\u00e1s"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1822\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2018\/08\/kutsidazu-bidea-ixabel-cartel.jpg\" alt=\"Kutsidazu bidea, Ixabel\" width=\"307\" height=\"453\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2018\/08\/kutsidazu-bidea-ixabel-cartel.jpg 307w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2018\/08\/kutsidazu-bidea-ixabel-cartel-203x300.jpg 203w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/>KUTSIDAZU BIDEA, IXABEL<\/strong><\/p>\n<p><strong>T\u00edtulo original<\/strong>: Kutsidazu bidea, Ixabel<\/p>\n<p><strong>A\u00f1o<\/strong>: 2006<\/p>\n<p><strong>Duraci\u00f3n<\/strong>: 100 minutos<\/p>\n<p><strong>Pa\u00eds<\/strong>:\u00a0Espa\u00f1a<\/p>\n<p><strong>Direcci\u00f3n<\/strong>:\u00a0<span class=\"director\">Fernando Bernu\u00e9s,<\/span>\u00a0<span class=\"director\">Mireia Gabilondo<\/span><\/p>\n<p><strong>Guion<\/strong>:\u00a0<span class=\"nb\">Carlos Zabala,<\/span>\u00a0<span class=\"nb\">Fernando Bernu\u00e9s,<\/span>\u00a0<span class=\"nb\">Mireia Gabilondo,<\/span>\u00a0<span class=\"nb\">Nagore Aranburu (Novela: Joxean Sagastizabal)<\/span><\/p>\n<p><strong>M\u00fasica<\/strong>:\u00a0<span class=\"nb\">I\u00f1aki Salvador<\/span><\/p>\n<p><strong>Fotograf\u00eda<\/strong>:\u00a0<span class=\"nb\">Gaizka Bourgeaud<\/span><\/p>\n<p><strong>Reparto<\/strong>:\u00a0<span class=\"cast\">Mikel Losada,<\/span>\u00a0<span class=\"cast\">Ainere Tolosa,<\/span>\u00a0<span class=\"cast\">I\u00f1ake Irastorza,<\/span>\u00a0<span class=\"cast\">Mireia Gabilondo,<\/span>\u00a0<span class=\"cast\">I\u00f1aki Zapirain,<\/span><span class=\"cast\">Xabier Zapirain,<\/span>\u00a0<span class=\"cast\">Anjel Alkain,<\/span>\u00a0<span class=\"cast\">Joseba Apaolaza,<\/span>\u00a0<span class=\"cast\">Maite Arrese,<\/span>\u00a0<span class=\"cast\">Josean Bengoetxea,<\/span><span class=\"cast\">Asier Hormaza\u00a0y<\/span>\u00a0<span class=\"cast\">Lierni Fresnedo<\/span><\/p>\n<p><strong>Productora<\/strong>:\u00a0<span class=\"nb\">Tentazioa<\/span><\/p>\n<p><strong>G\u00e9nero<\/strong>:\u00a0Comedia<\/p>\n<p>Juan Mart\u00edn, un joven de San Sebasti\u00e1n, decide pasar el verano en un caser\u00edo perdido en el monte para mejorar su nivel de euskera. En el caser\u00edo comprobar\u00e1 que el euskera que manejan sus habitantes difiere bastante del que ha aprendido en las aulas. La familia del caser\u00edo la forman el padre, la abuela y cuatro hijos. Por una parte est\u00e1n los problemas ling\u00fcisticos y por otra el desconocimiento que tiene el protagonista del entorno rural en el que ha desembarcado. La sensual Ixabel, la hija peque\u00f1a de la familia, despertar\u00e1 sentimientos desconocidos hasta ahora para \u00e9l. (<a href=\"https:\/\/www.filmaffinity.com\/es\/film390971.html\" target=\"_blank\">FilmAffinity<\/a>)<\/p>\n<p>A mediados de la primera d\u00e9cada de los 2000 despunt\u00f3 un poco la industria cinematogr\u00e1fica vasca con un par de peque\u00f1as joyitas.\u00a0<strong>&#8216;Aupa Etxebeste&#8217;<\/strong> sent\u00f3 las bases de la comedia en euskera, y\u00a0<strong>&#8216;Kutsidazu bidea, Ixabel&#8217;<\/strong> sigui\u00f3 la estela con un resultado m\u00e1s desigual.<\/p>\n<p>Basada en una novela y una obra de teatro del mismo nombre,\u00a0<strong>&#8216;Kutsidazu bidea, Ixabel&#8217;\u00a0<\/strong>narra la historia de un joven donostiarra que a principios de los 80 decide aprender euskera y lo hace march\u00e1ndose durante\u00a0unos d\u00edas a un caser\u00edo guipuzcoano. El choque social y los malos entendidos son el motor sobre el que se sustenta esta comedia que, para su adaptaci\u00f3n al cine, decidi\u00f3 ampliar la historia mucho m\u00e1s all\u00e1 y se adentr\u00f3 un poco m\u00e1s en la situaci\u00f3n socio-pol\u00edtica del Pa\u00eds Vasco en la \u00e9poca, aumentar el n\u00famero de personajes y estirar el chicle, tal vez\u00a0demasiado.<\/p>\n<p>Lo que en teatro o en la novela era una historia muy sencilla, aqu\u00ed se convierte en m\u00e1s grande. Se reduce el humor en favor del drama. Se sacrifica la luz por la oscuridad. Aunque al final, la historia simp\u00e1tica principal sigue siendo el motor principal de la pel\u00edcula.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1821\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2018\/08\/kutsidazu-bidea-ixabel-1.jpg\" alt=\"Kutsidazu bidea, Ixabel\" width=\"628\" height=\"353\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2018\/08\/kutsidazu-bidea-ixabel-1.jpg 628w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2018\/08\/kutsidazu-bidea-ixabel-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/p>\n<p>Todo lo que no ocurre en el caser\u00edo funciona regular. Ni ETA, ni los Guardias Civiles en el monte, ni las prostitutas, ni las verbenas de pueblo&#8230; ninguno de estos pasajes consigue enganchar tanto como las idas y venidas de un pobre Juan Mart\u00edn (<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/03\/06\/el-guardian-invisible\/\" target=\"_blank\"><strong>Mikel Losada<\/strong><\/a>) enfrent\u00e1ndose de t\u00fa a t\u00fa a un entorno rural que le es completamente ajeno. El trabajo en el campo, con el ganado o su relaci\u00f3n con los familiares de Ixabel (<strong>Ainere Tolosa<\/strong>) es el verdadero punto \u00e1lgido de la cinta, lo que despierta carcajadas y dinamiza la cinta.<\/p>\n<p>Cuanto m\u00e1s sencillo y cotidiano es\u00a0<strong>&#8216;Kutsidazu bidea, Ixabel&#8217;<\/strong> mejor. La relaci\u00f3n entre Ixabel y Juan Martin, es prueba de ello, funciona bien, ellos est\u00e1n bien, no es nada memorable, pero consigue sostener el peso de la cinta con solvencia. Esto se desmorona cuando a la historia central se le van a\u00f1adiendo variables que poco o nada aportan. De acuerdo, el tema de ETA o la Guardia Civil sirven para contextualizar mejor que en la novela, igual que suced\u00eda con ciertos elementos en la reciente adaptaci\u00f3n de\u00a0<strong>&#8216;<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2017\/09\/25\/call-me-by-your-name-la-mejor-pelicula-del-ano\/\" target=\"_blank\">Call Me By Your Name<\/a>&#8216;<\/strong>, pero el problema est\u00e1 en dedicarles a esos detalles demasiado tiempo y no dejarlos como lo que son, algo pasajero, un gui\u00f1o.<\/p>\n<p>En cuanto a las actuaciones, bien, correctas. A excepci\u00f3n de <strong><a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/03\/06\/el-guardian-invisible\/\" target=\"_blank\">Mikel Losada<\/a><\/strong>, ninguno destaca, ninguno sobresale, ninguno es memorable. Se trata de un nutrido grupo de actores conocidos en el Pa\u00eds Vasco, especialmente por teleseries y programas. El grueso del reparto del programa de humor Wazemak, salvando las distancias fue el equivalente en euskera de Vaya Semanita, sale de esta pel\u00edcula. Cada una de sus apariciones o cameos, despierta una sonrisa c\u00f3mplice del espectador familiarizado con ellos.<\/p>\n<p>Antes de terminar, me gustar\u00eda abordar ese final que nos saca completamente de la pel\u00edcula. El coche que gira alrededor del caser\u00edo y va a toparse con todo el equipo t\u00e9cnico (sonidistas, c\u00e1maras, t\u00e9cnicos de luz, maquilladores, peluqueros&#8230;). Este recurso, muy \u00fatil para sacar al equipo t\u00e9cnico en pantalla, es fallido por derribar el cuarto muro de forma tan poco sutil y sin venir a cuento. Entiendo este recurso en otro tipo de pel\u00edcula, pero aqu\u00ed no, pierde todo el sentido. Un palito importante.<\/p>\n<p><strong>Lo mejor<\/strong>: La m\u00fasica y las escenas de\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/03\/06\/el-guardian-invisible\/\" target=\"_blank\"><strong>Mikel Losada<\/strong><\/a> en el caser\u00edo.<\/p>\n<p><strong>Lo peor<\/strong>: Entiendo la raz\u00f3n de ampliar la historia, pero lo extra aporta poco y lastra a lo verdaderamente importante. Y ese final, por favor.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-92\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/65-300x30.png\" alt=\"Kutsidazu bidea, Ixabel\" width=\"300\" height=\"30\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/65-300x30.png 300w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/65.png 564w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><iframe loading=\"lazy\" title=\"Kutsidazu bidea, Ixabel  (Subtitulos Espa\u00f1ol)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Rvf5bInlHv8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Kutsidazu bidea, Ixabel&#8217; narra la historia de un joven donostiarra que a principios de los 80 decide aprender euskera y lo hace march\u00e1ndose durante el verano a un caser\u00edo guipuzcoano. El choque social es el motor sobre el que se sustenta esta comedia que, para su adaptaci\u00f3n al cine, decidi\u00f3 ampliar la historia mucho m\u00e1s all\u00e1 y decidi\u00f3 adentrarse un poco m\u00e1s en la situaci\u00f3n socio-pol\u00edtica del Pa\u00eds Vasco en la \u00e9poca, aumentar el n\u00famero de personajes y estirar el chicle, tal vez en exceso.<\/p>\n","protected":false},"author":101,"featured_media":1820,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[4524,4528,4531,4522,4525,4526,3583,4529,4533,4532,4530,3881,4523,4527],"class_list":["post-1285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comedia","tag-ainere-tolosa","tag-anjel-alkain","tag-asier-hormaza","tag-fernando-bernues","tag-inake-irastorza","tag-inaki-zapirain","tag-josean-bengoetxea","tag-joseba-apaolaza","tag-kutsidazu-bidea-ixabel","tag-lierni-fresnedo","tag-maite-arrese","tag-mikel-losada","tag-mireia-gabilondo","tag-xabier-zapirain"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/1285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/comments?post=1285"}],"version-history":[{"count":4,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/1285\/revisions"}],"predecessor-version":[{"id":1888,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/1285\/revisions\/1888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media\/1820"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media?parent=1285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/categories?post=1285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/tags?post=1285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}