{"id":2075,"date":"2019-07-11T09:00:34","date_gmt":"2019-07-11T07:00:34","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/fotograma\/?p=2075"},"modified":"2019-07-07T12:10:37","modified_gmt":"2019-07-07T10:10:37","slug":"consequences","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/fotograma\/2019\/07\/11\/consequences\/","title":{"rendered":"&#8216;Consequences&#8217;: \u00bfno hay otra salida para los j\u00f3venes problem\u00e1ticos?"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2079\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2019\/07\/consequences-cartel.jpg\" alt=\"Consequences Posledice\" width=\"307\" height=\"453\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2019\/07\/consequences-cartel.jpg 307w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2019\/07\/consequences-cartel-203x300.jpg 203w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/>CONSEQUENCES<\/strong><\/p>\n<p><strong>T\u00edtulo original<\/strong>: Posledice<\/p>\n<p><strong>A\u00f1o<\/strong>: 2018<\/p>\n<p><strong>Duraci\u00f3n<\/strong>: 93 minutos<\/p>\n<p><strong>Pa\u00eds<\/strong>: Eslovenia<\/p>\n<p><strong>Direcci\u00f3n<\/strong>: Darko Stante<\/p>\n<p><strong>Guion<\/strong>: Darko Stante<\/p>\n<p><strong>Fotograf\u00eda<\/strong>: Rok Nagode<\/p>\n<p><strong>Reparto<\/strong>: Matej Zemljic, Timon Sturbej, Gasper Markun, Blaz Setnikar y Lovro Zafred<\/p>\n<p><strong>Productora<\/strong>: NuFrame \/ Temporama \/ 100 \/ Zwinger Film<\/p>\n<p><strong>G\u00e9nero<\/strong>: Drama<\/p>\n<p><strong>Sinopsis<\/strong>:\u00a0El problem\u00e1tico Andrej ha acabado su adolescencia, y con la paciencia de sus progenitores. Es llamado a declarar en un juicio por su ira, violencia y actos. Sentenciado, y con la aprobaci\u00f3n de sus padres, es llevado a un correccional para j\u00f3venes delincuentes. (<a href=\"https:\/\/www.filmaffinity.com\/es\/film441537.html\" target=\"_blank\" rel=\"nofollow\">FilmAffinity<\/a>)<\/p>\n<p><strong>&#8216;Consequences&#8217;<\/strong> es mi primera experiencia con el cine esloveno. La cinta de\u00a0<strong>Darko Stante<\/strong> ha sido una de las pel\u00edculas que han pasado con m\u00e1s cr\u00edticas positivas por diferentes festivales. Los aplausos se han centrado especialmente en el trabajo actoral de su protagonista,\u00a0<strong>Matej Zemljic<\/strong>, y el coprotagonista\u00a0<strong>Timon Sturbej<\/strong>.<\/p>\n<p><strong>&#8216;Consequences&#8217;<\/strong>,\u00a0<strong>&#8216;Posledice<\/strong> en su idioma original, nos cuenta la historia de un joven esloveno problem\u00e1tico que es encerrado en un centro para j\u00f3venes problem\u00e1ticos. Cuando sus padres no pueden hacer m\u00e1s con \u00e9l lo llevan ante un juez que dictamina que debe quedarse en este centro donde van &#8220;otros j\u00f3venes como \u00e9l&#8221;. All\u00ed entrar\u00e1 en la pandilla de varios matones, y despu\u00e9s lo que todos podemos imaginar.<\/p>\n<p><strong>Darko Stante<\/strong> nos sit\u00faa en un momento donde los padres pueden deshacerse de sus hijos cuando no pueden hacer nada con ellos. Los hijos como un elemento del que desquitarse cuando se salen de tu control.\u00a0<strong>&#8216;Consequences&#8217;<\/strong> apoya en todo momento la tesis de que trasladar a Andrej (<strong>Matej Zemljic<\/strong>) no es buena idea. El \u00fanico lugar donde este chico es \u00e9l es cuando est\u00e1 con su rata en su habitaci\u00f3n. Por muy problem\u00e1tico que es, la pel\u00edcula solo nos muestra que llega tarde una vez, no va al cole y tira un plato de lentejas al suelo, el despojarle de lo poco que le hace estar en su lugar no tiene mejores consecuencias.<\/p>\n<p>La rata, que m\u00e1s adelante recuperar\u00e1, es ese t\u00f3tem al que se agarra el personaje, el que le hace volver a la cordura, a un punto de equilibrio. Tanto director como actor muestran muy bien estos cambios de personalidad de un adolescente cuyo principal problema es estar encerrado, dejarse llevar por la gente equivocada.<\/p>\n<p>No creo que el problema sea la sexualidad del protagonista, sobre el que se pone un importante foco en la segunda parte de la pel\u00edcula, pero no se puede dejar de lado. Este joven encerrado en el armario exterioriza su frustraci\u00f3n mediante la violencia. La mirada triste de\u00a0<strong>Zemljic<\/strong> resume bien ese sentimiento de encierro de quien es de una manera pero no puede decirlo por vivir en una sociedad profundamente hom\u00f3foba. Esto le lleva a exteriorizar su frustraci\u00f3n mediante la violencia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2077\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2019\/07\/consequences-2.jpg\" alt=\"Consequences Posledice\" width=\"628\" height=\"353\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2019\/07\/consequences-2.jpg 628w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2019\/07\/consequences-2-300x169.jpg 300w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/p>\n<p><strong>&#8216;Consequences&#8217;<\/strong>, que tiene varios giros cuestionables, no falla a la hora de dar cuenta del doble problema que vive su protagonista. En cuanto se sabe de su condici\u00f3n sexual unos se aprovechan para sacar beneficio y otros le apartan. Entonces Andrej queda obligado a esconderse, a no ser \u00e9l, pero su manera de mostrarse en esa situaci\u00f3n es mediante la violencia, lo que tambi\u00e9n es censurado en su entorno.<\/p>\n<p>Tome el camino que tome sabe que tendr\u00e1 que perder y que esto le obligar\u00e1 a pagar un precio, las consecuencias de las que habla. Este es el punto m\u00e1s brillante del guion. Es realmente consciente de que un acto tiene sus consecuencias. Que nada queda indemne y que las decisiones que tomas tienen su respuesta. Por esto la segunda parte de la pel\u00edcula adelanta al espectador a la posici\u00f3n del protagonista. Como espectadores lo pasamos mal por este mat\u00f3n de barrio. Es tambi\u00e9n por esto que el final, por muy doloroso que sea, es altamente satisfactorio.<\/p>\n<p><strong>&#8216;Consequences&#8217;<\/strong> es una pel\u00edcula que podr\u00edamos partir en dos. La primera parte -el encierro y primeras tomas de contacto- flaquea porque no se entiende. Me explico. Por mucho que nos digan que Andrej es problem\u00e1tico y est\u00e1 fuera de control, no vemos realmente que sea ese t\u00edo tan problem\u00e1tico que deba estar encerrado en un centro donde se deja a los j\u00f3venes que no tienen soluci\u00f3n. \u00bfRealmente no hab\u00eda otra salida para \u00e9l? El guion est\u00e1 plagado de agujeros en esta parte que se solucionan en su parte final, mucho m\u00e1s compacta y cre\u00edble. Cuando todas las piezas se ponen sobre el tablero podemos implicarnos m\u00e1s en la pel\u00edcula.<\/p>\n<p>Gran parte del buen regusto final que deja\u00a0<strong>&#8216;Consequences&#8217;<\/strong> recae en los protagonistas,\u00a0<strong>Matej Zemljic<\/strong> y\u00a0<strong>Timon Sturbej<\/strong>.\u00a0<strong>Sturbej<\/strong> da buena r\u00e9plica como el &#8220;villano&#8221; de la cinta, un chico problem\u00e1tico de verdad y la t\u00edpica mala influencia. Pero es\u00a0<strong>Matej Zemljic<\/strong> el verdadero protagonista. Este chico dice m\u00e1s en la pel\u00edcula por sus silencios que por sus l\u00edneas de di\u00e1logo. No me atrevo a valorarlo como un gran actor, porque solo he visto esta pel\u00edcula donde sale \u00e9l, pero tiene hechuras de buen actor.<\/p>\n<p><strong>&#8216;Consequences&#8217;<\/strong> es una buena pel\u00edcula de cine social. Con unas interpretaciones solventes y un final dur\u00edsimo, pero extra\u00f1amente satisfactorio. Una buena manera de entrar en el cine esloveno.<\/p>\n<p><strong>Lo mejor<\/strong>: La interpretaci\u00f3n de\u00a0<strong>Matej Zemljic<\/strong>.<\/p>\n<p><strong>Lo peor<\/strong>: La primera mitad de la pel\u00edcula tiene agujeros de guion y giros dif\u00edciles de sostener.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-94\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75-300x30.png\" alt=\"Consequences Posledice\" width=\"300\" height=\"30\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75-300x30.png 300w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75.png 564w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><iframe loading=\"lazy\" title=\"CONSEQUENCES Trailer | TIFF 2018\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/6W8v3feKptE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gran parte del buen regusto final que deja &#8216;Consequences&#8217; recae en los protagonistas, Matej Zemljic y Timon Sturbej<\/p>\n","protected":false},"author":101,"featured_media":2078,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[5626,5629,5628,5625,5627,5623,5630,5624],"class_list":["post-2075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-drama","tag-blaz-setnikar","tag-consequences","tag-darko-stante","tag-gasper-markun","tag-lovro-zafred","tag-matej-zemljic","tag-posledice","tag-timon-sturbej"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/2075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/comments?post=2075"}],"version-history":[{"count":2,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/2075\/revisions"}],"predecessor-version":[{"id":2080,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/2075\/revisions\/2080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media\/2078"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media?parent=2075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/categories?post=2075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/tags?post=2075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}