{"id":241,"date":"2015-12-21T13:49:25","date_gmt":"2015-12-21T12:49:25","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/fotograma\/?p=241"},"modified":"2015-12-21T13:49:25","modified_gmt":"2015-12-21T12:49:25","slug":"star-wars-episodio-v-el-imperio-contraataca-luke-soy-tu-padre","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/21\/star-wars-episodio-v-el-imperio-contraataca-luke-soy-tu-padre\/","title":{"rendered":"&#039;Star Wars. Episodio V: El imperio contraataca&#039;, &#8220;Luke, soy tu padre&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"El imperio contraataca\" src=\"\/\/pics.filmaffinity.com\/La_guerra_de_las_galaxias_Episodio_V_El_imperio_contraataca-314829878-large.jpg\" alt=\"\" width=\"302\" height=\"454\" \/><\/p>\n<p><strong>STAR WARS. EPISODIO V: EL IMPERIO CONTRAATACA<\/strong><\/p>\n<p><strong>T\u00edtulo original<\/strong>: Star Wars. Episode V: The Empire Strikes Back<\/p>\n<p><strong>A\u00f1o<\/strong>: 1980<\/p>\n<p><strong>Duraci\u00f3n<\/strong>: 124 minutos<\/p>\n<p><strong>Pa\u00eds<\/strong>: Estados Unidos<\/p>\n<p><strong>Director<\/strong>: Irvin Kershner<\/p>\n<p><strong>Guion<\/strong>: Leigh Brackett y Lawrence Kasdan<\/p>\n<p><strong>M\u00fasica<\/strong>: John Williams<\/p>\n<p><strong>Fotograf\u00eda<\/strong>: Peter Suschitzky<\/p>\n<p><strong>Reparto<\/strong>:\u00a0Mark Hamill,\u00a0Harrison Ford,\u00a0Carrie Fisher,\u00a0Frank Oz,\u00a0Billy Dee Williams,\u00a0David Prowse,\u00a0Alec Guinness,\u00a0Anthony Daniels,\u00a0Kenny Baker,\u00a0Peter Mayhew,\u00a0Jeremy Bulloch,\u00a0Kenneth Colley,\u00a0Bruce Boa,\u00a0Julian Glover,\u00a0Denis Lawson,\u00a0Michael Culver,\u00a0John Ratzenberger y\u00a0Michael Sheard<\/p>\n<p><strong>Productora<\/strong>: 20th Century Fox<\/p>\n<p><strong>G\u00e9nero<\/strong>: Ciencia ficci\u00f3n \/ Aventuras<\/p>\n<p><strong>Trilog\u00eda de precuelas\u00a0(1999-2005):\u00a0&#8216;<a title=\"\u2018Star Wars. Episodio I: La amenaza fantasma\u2019, Lucas reinicia su saga\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/11\/star-wars-episodio-i-la-amenaza-fantasma-lucas-reinicia-su-saga\/\" target=\"_blank\">La amenaza fantasma<\/a>&#8216;,\u00a0&#8216;<a title=\"\u2018Star Wars. Episodio II: El ataque de los clones\u2019, mejor, pero todav\u00eda no\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/14\/star-wars-episodio-ii-el-ataque-de-los-clones-mejor-pero-todavia-no\/\" target=\"_blank\">El ataque de los clones<\/a>&#8216;<\/strong>\u00a0y\u00a0<strong>&#8216;<a title=\"\u2018Star Wars. Episodio III: La venganza de los Sith\u2019, cierre por todo lo alto de la segunda trilog\u00eda\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/16\/star-wars-episodio-iii-la-venganza-de-los-sith-cierre-por-todo-lo-alto-de-la-segunda-trilogia\/\" target=\"_blank\">La venganza de los Sith<\/a>&#8216;<\/strong><\/p>\n<p><strong>Trilog\u00eda original (1977-1983): &#8216;<a title=\"\u2018Star Wars. Episodio IV: Una nueva esperanza\u2019, as\u00ed comenz\u00f3 el mayor fen\u00f3meno fan de la historia del cine\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/18\/star-wars-episodio-iv-una-nueva-esperanza-asi-comenzo-el-mayor-fenomeno-fan-de-la-historia-del-cine\/\" target=\"_blank\">Una nueva esperanza<\/a>&#8216;, &#8216;<a title=\"\u2018Star Wars. Episodio V: El imperio contraataca\u2019, \u201cLuke, soy tu padre\u201d\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/21\/star-wars-episodio-v-el-imperio-contraataca-luke-soy-tu-padre\/\" target=\"_blank\">El imperio contraataca<\/a>&#8216;<\/strong>\u00a0y\u00a0<strong>&#8216;<a title=\"\u2018Star Wars. Episodio VI: El retorno del Jedi\u2019, la m\u00e1s floja de la trilog\u00eda original\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/23\/star-wars-episodio-vi-el-retorno-del-jedi-la-mas-floja-de-la-trilogia-original\/\">El retorno del Jedi<\/a>&#8216;<\/strong><\/p>\n<p><strong>Trilog\u00eda de secuelas (2015-): &#8216;<a title=\"\u2018Star Wars. Episodio VII: El despertar de la Fuerza\u2019, Abrams lleva la saga a otro nivel\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/25\/star-wars-episodio-vii-el-despertar-de-la-fuerza-abrams-lleva-la-saga-a-otro-nivel\/\">El despertar de la Fuerza<\/a>&#8216;<\/strong><\/p>\n<p>Tras un ataque sorpresa de las tropas imperiales a las bases camufladas de la alianza rebelde, Luke Skywalker, en compa\u00f1\u00eda de R2D2, parte hacia el planeta Dagobah en busca de Yoda, el \u00faltimo maestro Jedi, para que le ense\u00f1e los secretos de la Fuerza. Mientras, Han Solo, la princesa Leia, Chewbacca, y C3PO esquivan a las fuerzas imperiales y piden refugio al antiguo propietario del Halc\u00f3n Milenario, Lando Calrissian, en la ciudad minera de Bespin, donde les prepara una trampa urdida por Darth Vader. (<a href=\"http:\/\/www.filmaffinity.com\/es\/film605090.html\">FilmAffinity<\/a>)<\/p>\n<p>Quinta entrega en la saga de <strong>&#8216;Star Wars&#8217;<\/strong>. Se trata de la segunda pel\u00edcula m\u00e1s oscura de la heptalog\u00eda, al nivel de <strong>&#8216;<a title=\"\u2018Star Wars. Episodio III: La venganza de los Sith\u2019, cierre por todo lo alto de la segunda trilog\u00eda\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/16\/star-wars-episodio-iii-la-venganza-de-los-sith-cierre-por-todo-lo-alto-de-la-segunda-trilogia\/\">La venganza de los Sith<\/a>&#8216;<\/strong>, casualmente son las dos mejores pel\u00edculas de toda la serie. Nos encontramos ante la segunda pel\u00edcula de la saga sin &#8220;final feliz&#8221;, pero sin ser una pel\u00edcula de transici\u00f3n como <strong>&#8216;<a title=\"\u2018Star Wars. Episodio II: El ataque de los clones\u2019, mejor, pero todav\u00eda no\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/14\/star-wars-episodio-ii-el-ataque-de-los-clones-mejor-pero-todavia-no\/\">El ataque de los clones<\/a>&#8216;<\/strong>, esta vez todo tiene sentido, encontr\u00e1ndonos ante un episodio necesario y vital en el transcurso de la historia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"vertical-align: middle;\" src=\"https:\/\/i.kinja-img.com\/gawker-media\/image\/upload\/bgsg6s4expcobcvfquxh.jpg\" alt=\"\" width=\"1280\" height=\"720\" \/><\/p>\n<p>Pr\u00e1cticamente el mismo reparto de <strong>&#8216;<a title=\"\u2018Star Wars. Episodio IV: Una nueva esperanza\u2019, as\u00ed comenz\u00f3 el mayor fen\u00f3meno fan de la historia del cine\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/18\/star-wars-episodio-iv-una-nueva-esperanza-asi-comenzo-el-mayor-fenomeno-fan-de-la-historia-del-cine\/\">Una nueva esperanza<\/a>&#8216;<\/strong>\u00a0regresa a <strong>&#8216;El imperio contraataca&#8217;<\/strong>. Primer cambio de director de toda la franquicia, <strong>George Lucas <\/strong>pasa a ser productor, mientras que <strong>Irvin Kershner<\/strong>\u00a0se hace cargo de la direcci\u00f3n de la cinta.<\/p>\n<p><strong>&#8216;El imperio contraataca&#8217;<\/strong>\u00a0incluye esas transiciones de las que me quejaba en <strong>&#8216;<a title=\"\u2018Star Wars. Episodio III: La venganza de los Sith\u2019, cierre por todo lo alto de la segunda trilog\u00eda\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/16\/star-wars-episodio-iii-la-venganza-de-los-sith-cierre-por-todo-lo-alto-de-la-segunda-trilogia\/\">La venganza de los Sith<\/a>&#8216;<\/strong>, pero como dije en aquella ocasi\u00f3n, en los a\u00f1os 70 y 80 era un recurso que pod\u00eda salvarse, en pleno siglo XXI no.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"vertical-align: middle;\" src=\"\/\/cdn.collider.com\/wp-content\/uploads\/Yoda-Empire-Strikes-Back-image-3.jpg\" alt=\"\" width=\"1450\" height=\"815\" \/><\/p>\n<p>Uno de los mayores aciertos de esta entrega es el tratamiento de personajes. Toma cuerpo y gana en fuerza el villano de la saga, Darth Vader. El antagonista de <strong>&#8216;<a title=\"\u2018Star Wars. Episodio IV: Una nueva esperanza\u2019, as\u00ed comenz\u00f3 el mayor fen\u00f3meno fan de la historia del cine\" href=\"http:\/\/blogs.diariovasco.com\/fotograma\/2015\/12\/18\/star-wars-episodio-iv-una-nueva-esperanza-asi-comenzo-el-mayor-fenomeno-fan-de-la-historia-del-cine\/\">Una nueva esperanza<\/a>&#8216;<\/strong>\u00a0aqu\u00ed impone, y protagoniza la que probablemente sea la escena m\u00e1s famosa de toda la franquicia, dejando para la posteridad el c\u00e9lebre: &#8220;Luke, soy tu padre&#8221;. En el Episodio V debuta Yoda. El conocido personaje verde adiestrar\u00e1 a Luke Skywalker, <strong>Mark Hamill<\/strong>, en las artes Jedi. Y profundiza en la relaci\u00f3n de <strong>Harrison Ford<\/strong>\u00a0(Han Solo)\u00a0y <strong>Carrie Fisher<\/strong>\u00a0(Leia), que aprendan <strong>Hayden Christensen<\/strong>\u00a0y <strong>Natalie Portman<\/strong>.<\/p>\n<p><strong>&#8216;El imperio contraataca&#8217;<\/strong>\u00a0es el episodio m\u00e1s claustrof\u00f3bico de la saga. Se trata de un cap\u00edtulo oscuro y agobiante, con un guion bien elaborado y en el que los personajes est\u00e1n bien construidos, todas las piezas encajan y todo tiene sentido. En contra tiene que sigue incluyendo secuencias algo infantiles.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"vertical-align: middle;\" src=\"\/\/www.fandomfest.com\/wp-content\/uploads\/2015\/03\/Image-for-London-Is-Getting-A-Special-Empire-Strikes-Back-Screening.jpg\" alt=\"\" width=\"1920\" height=\"818\" \/><\/p>\n<p><strong>Lo mejor<\/strong>: tono oscuro y el mejor guion de toda la heptalog\u00eda.<\/p>\n<div><strong>Lo peor<\/strong>: sigue teniendo un tono algo infantil.<\/div>\n<div><a href=\"\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-94\" title=\"7,5\" src=\"\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75.png\" alt=\"\" width=\"300\" height=\"29\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75.png 564w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75-300x30.png 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/L1qVxC5qgNo?rel=0\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>STAR WARS. EPISODIO V: EL IMPERIO CONTRAATACA T\u00edtulo original: Star Wars. Episode V: The Empire Strikes Back A\u00f1o: 1980 Duraci\u00f3n: 124 minutos Pa\u00eds: Estados Unidos Director: Irvin Kershner Guion: Leigh Brackett y Lawrence Kasdan M\u00fasica: John Williams Fotograf\u00eda: Peter Suschitzky Reparto:\u00a0Mark Hamill,\u00a0Harrison Ford,\u00a0Carrie Fisher,\u00a0Frank Oz,\u00a0Billy Dee Williams,\u00a0David Prowse,\u00a0Alec Guinness,\u00a0Anthony Daniels,\u00a0Kenny Baker,\u00a0Peter Mayhew,\u00a0Jeremy Bulloch,\u00a0Kenneth Colley,\u00a0Bruce Boa,\u00a0Julian [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[99,231,355,402,446,633,655,745,889,993,1075,1214,1309,1372,1435,1436,1672,1768,1791,2021,2343,2426],"class_list":["post-241","post","type-post","status-publish","format-standard","hentry","category-aventuras","category-ciencia-ficcion","tag-alec-guinness","tag-anthony-daniels","tag-billy-dee-williams","tag-bruce-boa","tag-carrie-fisher","tag-david-prowse","tag-denis-lawson","tag-el-imperio-contraataca","tag-frank-oz","tag-harrison-ford","tag-irvin-kershner","tag-jeremy-bulloch","tag-john-ratzenberger","tag-julian-glover","tag-kenneth-colley","tag-kenny-baker","tag-mark-hamill","tag-michael-culver","tag-michael-sheard","tag-peter-mayhew","tag-star-wars","tag-the-empire-strikes-back"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/comments?post=241"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/241\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media?parent=241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/categories?post=241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/tags?post=241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}