{"id":2679,"date":"2020-02-20T09:00:11","date_gmt":"2020-02-20T08:00:11","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/fotograma\/?p=2679"},"modified":"2020-02-17T17:51:36","modified_gmt":"2020-02-17T16:51:36","slug":"los-dias-que-vendran","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/fotograma\/2020\/02\/20\/los-dias-que-vendran\/","title":{"rendered":"&#8216;Los d\u00edas que vendr\u00e1n&#8217;: \u00edntimo y cercano viaje de 9 meses"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2686\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/01\/dias-que-vendran-cartel.jpg\" alt=\"Los d\u00edas que vendr\u00e1n\" width=\"307\" height=\"453\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/01\/dias-que-vendran-cartel.jpg 307w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/01\/dias-que-vendran-cartel-203x300.jpg 203w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/>LOS D\u00cdAS QUE VENDR\u00c1N<\/strong><\/p>\n<p><strong>T\u00edtulo original<\/strong>:\u00a0Los d\u00edas que vendr\u00e1n (Els dies que vindran)<\/p>\n<p><strong>A\u00f1o<\/strong>:\u00a02019<\/p>\n<p><strong>Duraci\u00f3n<\/strong>:\u00a094 minutos<\/p>\n<p><strong>Pa\u00eds<\/strong>:\u00a0Espa\u00f1a<\/p>\n<p><strong>Direcci\u00f3n<\/strong>:\u00a0Carlos Marques-Marcet<\/p>\n<p><strong>Guion<\/strong>:\u00a0Coral Cruz, Clara Roquet y Carlos Marques-Marcet<\/p>\n<p><strong>Fotograf\u00eda<\/strong>:\u00a0Alex Garc\u00eda<\/p>\n<p><strong>Reparto<\/strong>:\u00a0David Verdaguer, Maria Rodr\u00edguez Soto, Albert Prat y Sergi Torrecilla<\/p>\n<p><strong>Productora<\/strong>:\u00a0Lastor Media \/ Avalon P.C \/ ICAA \/ Movistar+ \/ TVC<\/p>\n<p><strong>G\u00e9nero<\/strong>:\u00a0Drama \/ Rom\u00e1ntico<\/p>\n<p><strong>Sinopsis<\/strong>:\u00a0Vir y Llu\u00eds hace solo un a\u00f1o que salen juntos, cuando descubren que est\u00e1n \u201cembarazados\u201d. Durante 9 meses, seguiremos la aventura de esta joven pareja barcelonesa, el giro enorme que dar\u00e1 su vida, sus miedos, alegr\u00edas, sus expectativas y las realidades que, durante su embarazo, crecen ante ellos, intentando aprender a ser tres cuando ni siquiera hab\u00edan tenido tiempo de aprender a ser dos&#8230; (<a href=\"https:\/\/www.filmaffinity.com\/es\/film205885.html\" target=\"_blank\" rel=\"nofollow noopener\">FilmAffinity<\/a>)<\/p>\n<p><strong>&#8216;Los d\u00edas que vendr\u00e1n&#8217;<\/strong> es el retrato \u00edntimo de una pareja durante los 9 meses que dura un embarazo. Aprovechando el embarazo real de la pareja formada por\u00a0<strong>Mar\u00eda Rodr\u00edguez Soto<\/strong> y\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/01\/09\/verano-1993\/\" target=\"_blank\" rel=\"noopener\"><strong>David Verdaguer<\/strong><\/a>, ambos actores dan vida a Vir y Lluis, esta joven pareja que se embarca en la paternidad. Una pel\u00edcula tan cotidiana como humana, tan sencilla como rica en matices.<\/p>\n<p>La cinta dirigida por\u00a0<strong>Carlos Marques-Marcet<\/strong> ahonda en ese momento de m\u00e1xima intimidad en una pareja que es el que les lleva a ser padres. La ventaja con la que se encuentra la pel\u00edcula es que en este caso el embarazo es real. La cinta se vuelve una versi\u00f3n ficticia de una situaci\u00f3n real que\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/01\/09\/verano-1993\/\" target=\"_blank\" rel=\"noopener\"><strong>Verdaguer<\/strong><\/a> y\u00a0<strong>Rodr\u00edguez Soto<\/strong> est\u00e1n viviendo. Al mismo tiempo interpretan a unos personajes, pero tambi\u00e9n est\u00e1n retratando lo que viven.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2684\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/01\/dias-que-vendran-2.jpg\" alt=\"Los d\u00edas que vendr\u00e1n\" width=\"628\" height=\"353\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/01\/dias-que-vendran-2.jpg 628w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/01\/dias-que-vendran-2-300x169.jpg 300w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/p>\n<p>El verdadero potencial de\u00a0<strong>&#8216;Los d\u00edas que vendr\u00e1n&#8217;<\/strong> reside en su cotidianidad. La pel\u00edcula nos lleva directamente a un momento \u00fanico. Las peque\u00f1as discusiones, las discrepancias por el nombre, las dudas, los miedos&#8230; todo ello est\u00e1 retratado con gran acierto en la pel\u00edcula.<\/p>\n<p><strong>&#8216;Los d\u00edas que vendr\u00e1n&#8217;<\/strong> se convierte en un casi documental de nueve meses. M\u00e1s de hora y media de metraje que, como un documental, entra en la vida de dos personas e inmortaliza para siempre un momento. Todo ello con lo m\u00e1s importante para la pel\u00edcula, la naturalidad. No hay nada excesivo ni exagerado. No hay nada que se salga de lo com\u00fan, es la vida misma. Es todo tan normal, tan cercano, que llega un punto en el que la sensaci\u00f3n que da es la de conocer a estas dos personas de toda la vida.<\/p>\n<p><strong>Lo mejor<\/strong>: La naturalidad con la que aborda el momento del embarazo.<\/p>\n<p><strong>Lo peor<\/strong>: No pasa por ser un casi documental, un reality, al que le falta algo m\u00e1s para redondearlo como pel\u00edcula.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-93\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/7-300x30.png\" alt=\"Los d\u00edas que vendr\u00e1n\" width=\"300\" height=\"30\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/7-300x30.png 300w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/7.png 564w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><iframe loading=\"lazy\" title=\"Los di\u0301as que vendra\u0301n - Trailer (HD)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Vat3bYeoiyQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Los d\u00edas que vendr\u00e1n&#8217; se convierte en un casi documental de nueve meses. Todo ello con lo m\u00e1s importante para la pel\u00edcula, la naturalidad y la cercanidad<\/p>\n","protected":false},"author":101,"featured_media":2685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,14],"tags":[6628,6630,3815,6632,6631,6627,6629],"class_list":["post-2679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-drama","category-romantico","tag-albert-prat","tag-carlos-marques-marcet","tag-david-verdaguer","tag-els-dies-que-vindran","tag-los-dias-que-vendran","tag-maria-rodriguez-soto","tag-sergi-torrecilla"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/2679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/comments?post=2679"}],"version-history":[{"count":3,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/2679\/revisions"}],"predecessor-version":[{"id":2690,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/2679\/revisions\/2690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media\/2685"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media?parent=2679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/categories?post=2679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/tags?post=2679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}