{"id":3593,"date":"2020-09-22T09:00:47","date_gmt":"2020-09-22T07:00:47","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/fotograma\/?p=3593"},"modified":"2020-09-18T15:33:04","modified_gmt":"2020-09-18T13:33:04","slug":"el-diablo-a-todas-horas","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/fotograma\/2020\/09\/22\/el-diablo-a-todas-horas\/","title":{"rendered":"\u2018El diablo a todas horas\u2019: viaje a la Am\u00e9rica profunda"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3596\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/09\/diablo-todas-horas-cartel.jpg\" alt=\"El diablo a todas horas\" width=\"307\" height=\"453\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/09\/diablo-todas-horas-cartel.jpg 307w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/09\/diablo-todas-horas-cartel-203x300.jpg 203w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/>EL DIABLO A TODAS HORAS<\/strong><\/p>\n<p><strong>T\u00edtulo original<\/strong>:\u00a0The Devil All the Time<\/p>\n<p><strong>A\u00f1o<\/strong>:\u00a02020<\/p>\n<p><strong>Duraci\u00f3n<\/strong>:\u00a0138 minutos<\/p>\n<p><strong>Pa\u00eds<\/strong>:\u00a0Estados Unidos<\/p>\n<p><strong>Direcci\u00f3n<\/strong>:\u00a0Antonio Campos<\/p>\n<p><strong>Guion<\/strong>:\u00a0Antonio Campos y Paulo Campos<\/p>\n<p><strong>Novela<\/strong>: Donald Roy Pollock<\/p>\n<p><strong>M\u00fasica<\/strong>:\u00a0Danny Bensi y Saunder Jurriaans<\/p>\n<p><strong>Fotograf\u00eda<\/strong>:\u00a0Lol Crawley<\/p>\n<p><strong>Reparto<\/strong>:\u00a0Robert Pattinson, Tom Holland, Bill Skarsg\u00e5rd, Mia Wasikowska, Jason Clarke, Sebastian Stan, Riley Keough, Haley Bennett, Mia Goth, Eliza Scanlen, Tracy Letts, Gregory Kelly, Gabriel Ebert, Emma Coulter, Harry Melling, Douglas Hodge, Lucy Faust, Drew Starkey y Kristin Griffith<\/p>\n<p><strong>Productora<\/strong>:\u00a0Netflix \/ BorderLine Films \/ Ninestory Pictures<\/p>\n<p><strong>G\u00e9nero<\/strong>:\u00a0Thriller \/ Drama<\/p>\n<p><strong>Sinopsis<\/strong>:\u00a0Desesperado por salvar a su mujer, Willard Russell convierte sus oraciones en un sacrificio. Las acciones de Russel llevan a su hijo Arvin a pasar de ser un ni\u00f1o que sufre abusos en el instituto a convertirse en un hombre que sabe cu\u00e1ndo y c\u00f3mo ha de pasar a la acci\u00f3n. Los acontecimientos que se dan lugar en Knockemstiff desatan una tormenta de fe, violencia y redenci\u00f3n que se desarrolla a lo largo de dos d\u00e9cadas. (<a href=\"https:\/\/www.filmaffinity.com\/es\/film267933.html\" target=\"_blank\" rel=\"nofollow noopener\">FilmAffinity<\/a>)<\/p>\n<p>Entre toda la morralla cinematogr\u00e1fica de producci\u00f3n propia que estrena a lo largo del a\u00f1o <a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/06\/14\/alex-strangelove\/\" target=\"_blank\" rel=\"noopener\"><strong>Netflix<\/strong><\/a>, destacan unas pocas pel\u00edculas rescatables, con alguna que otra muy decente. \u2018<strong>El diablo a todas horas<\/strong>\u2019 no es ninguna maravilla, pero s\u00ed que es una muy decente cinta que nos sumerge en la Am\u00e9rica profunda, en un ambiente cargado en este drama sure\u00f1o.<\/p>\n<p>La historia nos lleva a la Am\u00e9rica profunda. Un soldado vuelve de la Segunda Guerra Mundial y comienza una nueva vida en un entorno profundamente religioso. Se casa y tiene un hijo. Paralelamente, una pareja empieza su descenso a las profundidades al empezar a matar a los autoestopistas que recogen en la carretera.<\/p>\n<p>\u2018<strong>El diablo a todas horas<\/strong>\u2019 es una sucesi\u00f3n de desafortunadas situaciones de un grupo de personas profundamente religiosas. La pel\u00edcula de <strong>Antonio Campos<\/strong> retrata a esta Am\u00e9rica rural, marcada por el sheriff, el predicador o el miedo. Un entorno donde cualquier cosa es obra de Dios o el Diablo. Un entorno empobrecido y presa de su propio entorno, algo que la pel\u00edcula consigue captar a la perfecci\u00f3n con su ambientaci\u00f3n claustrof\u00f3bica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3594\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/09\/diablo-todas-horas-2.jpg\" alt=\"El diablo a todas horas\" width=\"628\" height=\"353\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/09\/diablo-todas-horas-2.jpg 628w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/09\/diablo-todas-horas-2-300x169.jpg 300w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/p>\n<p>\u2018<strong>El diablo a todas horas<\/strong>\u2019 es interesante, principalmente, por reunir un reparto de caras conocidas que salen de su zona de confort con mucho acierto. <a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2019\/07\/09\/spiderman-lejos-de-casa\/\" target=\"_blank\" rel=\"noopener\"><strong>Tom Holland<\/strong><\/a> cumple en un papel m\u00e1s duro y adulto del habitual suyo, lejos de esos personajes ani\u00f1ados que ha interpretado anteriormente. El brit\u00e1nico sigue creciendo como actor y aqu\u00ed le vemos en una de sus mejores interpretaciones hasta la fecha. Ojal\u00e1 tenga oportunidad de seguir creciendo al margen de su <strong>&#8216;<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2017\/08\/01\/spiderman-homecoming-critica-crine-marvel\/\" target=\"_blank\" rel=\"noopener\">Spiderman<\/a>&#8216;<\/strong>.<\/p>\n<p>En papeles m\u00e1s peque\u00f1os vemos a <a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2019\/09\/10\/it-capitulo-2\/\" target=\"_blank\" rel=\"noopener\"><strong>Bill Skarsg\u00e5rd<\/strong><\/a>, <a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/10\/16\/first-man\/\" target=\"_blank\" rel=\"noopener\"><strong>Jason Clarke<\/strong><\/a>, <a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/10\/23\/harry-potter-y-la-piedra-filosofal\/\" target=\"_blank\" rel=\"noopener\"><strong>Harry Melling<\/strong><\/a> y <a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2016\/05\/04\/capitan-america-el-soldado-de-invierno-cuando-marvel-hace-peliculas-serias\/\" target=\"_blank\" rel=\"noopener\"><strong>Sebastian Stan<\/strong><\/a>, todos ellos muy correctos. El primero lleva el peso de los primeros compases de la cinta, y cuesta verle sin el maquillaje de payaso de \u2018<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2017\/09\/12\/critica-it-stephen-king-stranger-things\/\" target=\"_blank\" rel=\"noopener\"><strong>It<\/strong><\/a>\u2019. El que aprovecha bien su poco tiempo en pantalla es <a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2020\/08\/27\/tenet\/\" target=\"_blank\" rel=\"noopener\"><strong>Robert Pattinson<\/strong><\/a>, interpretando muy dignamente a un predicador vomitivo. El reparto femenino con <a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2015\/10\/23\/la-cumbre-escarlata-terror-gotico-tenido-de-rojo\/\" target=\"_blank\" rel=\"noopener\"><strong>Mia Wasikowska<\/strong><\/a>, <strong>Haley Bennett<\/strong> o <strong>Riley Keough<\/strong> est\u00e1 m\u00e1s desaprovechado. Con el potencial que tienen estas actrices.<\/p>\n<p>En lo que falla \u2018<strong>El diablo a todas horas<\/strong>\u2019 es en mantener un ritmo acorde en todo momento. Brilla al principio y al final, y en alg\u00fan momento puntual durante el resto de la pel\u00edcula, pero no consigue que su largo metraje mantenga el inter\u00e9s en todo momento. La banda sonora no es gran cosa tampoco. La abundancia de personajes tampoco ayuda.<\/p>\n<p>Los puntos fuertes son que visualmente es un ejercicio interesante de cine. Una fotograf\u00eda con grano, que nos recuerda al cine de hace d\u00e9cadas. La elecci\u00f3n del casting y los escenarios, otros aciertos que se puede apuntar <strong>Campos<\/strong>.<\/p>\n<p>\u2018<strong>El diablo a todas horas<\/strong>\u2019 es una decente pel\u00edcula que eleva el paup\u00e9rrimo nivel que <a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2020\/06\/30\/circus-of-books\/\" target=\"_blank\" rel=\"noopener\"><strong>Netflix<\/strong><\/a> ha mostrado hasta ahora en sus producciones originales de cine. No es ninguna maravilla, pero s\u00ed de lo m\u00e1s apetecible entre todo lo nuevo que nos ha llegado en lo que a cine se refiere recientemente.<\/p>\n<p><strong>Lo mejor<\/strong>: El reparto, todos fuera de su zona de confort.<\/p>\n<p><strong>Lo peor<\/strong>: La parte femenina del reparto ten\u00eda potencial para mucho m\u00e1s. La duraci\u00f3n, media hora menos no le habr\u00eda hecho da\u00f1o<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-93\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/7-300x30.png\" alt=\"El diablo a todas horas\" width=\"300\" height=\"30\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/7-300x30.png 300w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/7.png 564w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><iframe loading=\"lazy\" title=\"El diablo a todas horas, con Tom Holland y Robert Pattinson | Tr\u00e1iler oficial | Netflix\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/KtN6fpjRSHs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2018El diablo a todas horas\u2019 es una decente pel\u00edcula que eleva el paup\u00e9rrimo nivel que Netflix ha mostrado hasta ahora en sus producciones originales de cine<\/p>\n","protected":false},"author":101,"featured_media":3595,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,18],"tags":[349,6189,7878,6565,7876,7875,7874,7873,4752,1169,7879,7877,3645,1757,2139,4835,2278,2472,2497],"class_list":["post-3593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-drama","category-thriller","tag-bill-skarsgard","tag-douglas-hodge","tag-drew-starkey","tag-eliza-scanlen","tag-emma-coulter","tag-gabriel-ebert","tag-gregory-kelly","tag-haley-bennett","tag-harry-melling","tag-jason-clarke","tag-kristin-griffith","tag-lucy-faust","tag-mia-goth","tag-mia-wasikowska","tag-riley-keough","tag-robert-pattinson","tag-sebastian-stan","tag-tom-holland","tag-tracy-letts"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/comments?post=3593"}],"version-history":[{"count":1,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3593\/revisions"}],"predecessor-version":[{"id":3597,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3593\/revisions\/3597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media\/3595"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media?parent=3593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/categories?post=3593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/tags?post=3593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}