{"id":3770,"date":"2021-11-02T09:00:03","date_gmt":"2021-11-02T08:00:03","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/fotograma\/?p=3770"},"modified":"2021-07-15T17:47:39","modified_gmt":"2021-07-15T15:47:39","slug":"stonewall","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/fotograma\/2021\/11\/02\/stonewall\/","title":{"rendered":"&#8216;Stonewall&#8217;: &#8220;Hay que tener m\u00e1s valor para ponerse un vestido que una corbata&#8221;"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3771\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/12\/stonewall-cartel.jpg\" alt=\"Stonewall\" width=\"307\" height=\"453\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/12\/stonewall-cartel.jpg 307w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/12\/stonewall-cartel-203x300.jpg 203w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/>STONEWALL<\/strong><\/p>\n<p><strong>T\u00edtulo original<\/strong>:\u00a0Stonewall<\/p>\n<p><strong>A\u00f1o<\/strong>:\u00a02015<\/p>\n<p><strong>Duraci\u00f3n<\/strong>: 129 minutos<\/p>\n<p><strong>Pa\u00eds<\/strong>:\u00a0Estados Unidos<\/p>\n<p><strong>Direcci\u00f3n<\/strong>:\u00a0Roland Emmerich<\/p>\n<p><strong>Guion<\/strong>:\u00a0Jon Robin Baitz<\/p>\n<p><strong>M\u00fasica<\/strong>:\u00a0Rob Simonsen<\/p>\n<p><strong>Fotograf\u00eda<\/strong>:\u00a0Markus F\u00f6rderer<\/p>\n<p><strong>Reparto<\/strong>:\u00a0Jeremy Irvine, Ron Perlman, Jonathan Rhys Meyers, Joey King, Caleb Landry Jones, Matt Craven, Mark Camacho, Atticus Dean Mitchell, Nathaly Thibault, Andrea Frankle, Jonny Beauchamp y Vlad Alexis<\/p>\n<p><strong>Productora<\/strong>:\u00a0Centropolis Entertainment, Mel&#8217;s Cite du Cinema<\/p>\n<p><strong>G\u00e9nero<\/strong>:\u00a0Drama<\/p>\n<p><strong>Sinopsis<\/strong>:\u00a0En junio de 1969, una serie de hechos desembocaron en violentos disturbios en el bar Stonewall Inn de Greenwich Village, frecuentado por gays y transexuales. Este fue el punto de partida de los movimientos que reivindican la igualdad de derechos de la poblaci\u00f3n homosexual. (<a href=\"https:\/\/www.filmaffinity.com\/es\/film427986.html\" target=\"_blank\" rel=\"nofollow noopener\">FilmAffinity<\/a>)<\/p>\n<p><strong>&#8216;Stonewall&#8217;<\/strong> es una de estas pel\u00edculas masacradas por la cr\u00edtica que terminan fracasando injustamente en taquilla. Se trata de una pel\u00edcula peque\u00f1ita, con sus errores, pero no la atrocidad de la que habl\u00f3 la cr\u00edtica en su momento.<\/p>\n<p>La cinta narra el inicio del llamado orgullo gay, que comenz\u00f3 con unos disturbios que tuvieron lugar en el local Stonewall de Nueva York y en sus aleda\u00f1os. Se trata de unos disturbios que se produjeron tras las innumerables redadas que este local recib\u00eda. El imaginario popular tambi\u00e9n las ha relacionado con la muerte pr\u00f3xima a esas fechas de\u00a0<strong>Judy Garland<\/strong>, pero ser\u00eda ridiculizar algo que se llevaba gestando demasiado tiempo y que antes o despu\u00e9s ten\u00eda que estallar. Todo esto se produce en un contexto donde las personas gays no pod\u00edan trabajar para el gobierno, donde se les consideraba enfermos mentales, donde no pod\u00edan reunirse o donde no pod\u00edan venderles alcohol, entre otras lindezas. Un caldo de cultivo que si no explotaba entonces iba a explotar m\u00e1s pronto que tarde.<\/p>\n<p>En\u00a0<strong>&#8216;Stonewall&#8217;<\/strong>, como en muchas otras pel\u00edculas que nos quieren contar un hecho hist\u00f3rico, se centra la mirada en un personaje y se cuenta a trav\u00e9s de sus ojos. En este caso seguimos a Danny,\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/08\/02\/mamma-mia-una-y-otra-vez\/\" target=\"_blank\" rel=\"noopener\"><strong>Jeremy Irvine<\/strong><\/a>, un joven de un pueblo de Indiana que llega a Nueva York despu\u00e9s de que sus padres le echaran tras descubrir su homosexualidad. Pronto encontrar\u00e1 refugio en un grupo de personas LGTBI de la zona gay de Nueva York, con el que tenemos una peque\u00f1a muestra del ambiente de la zona.<\/p>\n<p>El problema de\u00a0<strong>&#8216;Stonewall&#8217;<\/strong> es no acertar con el tono adecuado que requiere la historia. Intenta jugar en la misma liga de pel\u00edculas como\u00a0<strong>&#8216;Milk&#8217;<\/strong> o\u00a0<strong>&#8216;<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2017\/06\/27\/pride-orgullo-cine-britanico-con-letras-de-oro\/\" target=\"_blank\" rel=\"noopener\">Pride<\/a>&#8216;<\/strong>, pero sin conseguir el grado de acierto de ellas. No obstante, insisto, no es la atrocidad de la que hablaron las cr\u00edticas. Se trata de una pincelada adecuada para dar a conocer de forma simple y accesible en qu\u00e9 consisti\u00f3 esa primera piedra que dio comienzo al orgullo gay. Al igual que ocurr\u00eda con\u00a0<strong>&#8216;Philadelphia&#8217;<\/strong>, que no contaba su historia para las personas ya concienciadas sobre la problem\u00e1tica del VIH y el Sida,\u00a0<strong>&#8216;Stonewall&#8217;<\/strong> no cuenta esta historia para las personas que ya est\u00e1n familiarizadas con lo que all\u00ed ocurri\u00f3. Se trata de una pel\u00edcula accesible para que lo vea el p\u00fablico heterosexual, menos receptivo hacia este tipo de historias, y no salga corriendo. Ese p\u00fablico que mira por encima del hombro en una marcha del orgullo es al que intenta apelar\u00a0<strong>Roland Emmerich<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3773\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/12\/stonewall-2.jpg\" alt=\"Stonewall\" width=\"628\" height=\"353\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/12\/stonewall-2.jpg 628w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2020\/12\/stonewall-2-300x169.jpg 300w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/p>\n<p>Otro problema es, precisamente, su director. No pongo en cuesti\u00f3n el activismo y el compromiso de\u00a0<strong>Emmerich<\/strong> con una comunidad a la que \u00e9l tambi\u00e9n pertenece. Pero s\u00ed que pongo en cuesti\u00f3n que sea \u00e9l la persona adecuada para dirigir la cinta. Un director con experiencia de sobra en pel\u00edculas de desastres de toda clase y condici\u00f3n no era la opci\u00f3n adecuada. Esta historia merec\u00eda ser contada, pero quiz\u00e1 un director menos marcado lo hubiese hecho mejor. O, al menos, no le hubieran puesto a parir como a \u00e9l. Eso s\u00ed, \u00e9l pag\u00f3 pr\u00e1cticamente toda la pel\u00edcula. Por lo que gracias.<\/p>\n<p>La pel\u00edcula en ning\u00fan caso pretende ser un fiel reflejo de lo que all\u00ed sucedi\u00f3, para eso veamos documentales.\u00a0<strong>&#8216;Stonewall&#8217;<\/strong> es lo que\u00a0<strong>&#8216;<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2017\/04\/13\/titanic-epica-amor-y-emocion-cine-en-estado-puro\/\" target=\"_blank\" rel=\"noopener\">Titanic<\/a>&#8216;<\/strong>, salvando las enormes distancias, una forma de contar esa historia, de acercarla al p\u00fablico. Es cierto que se reduce la importancia que tuvo la comunidad trans, drag queen y afroamericana en lo sucedido y que todo se cuenta desde la perspectiva de un chico blanco guap\u00edsimo y heteronormativo. Pero esta no es una pel\u00edcula para los ya convencidos y conocedores.<\/p>\n<p><a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/08\/02\/mamma-mia-una-y-otra-vez\/\" target=\"_blank\" rel=\"noopener\"><strong>Jeremy Irvine<\/strong><\/a> da vida al protagonista con convicci\u00f3n. Un actor que se pasea por el set con acierto, sin caer en la caricatura y que cautiva con su aspecto entre\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2017\/04\/04\/rebelde-sin-causa-lo-interesante-es-lo-que-insinua-no-lo-que-muestra\/\" target=\"_blank\" rel=\"noopener\"><strong>James Dean<\/strong><\/a> y\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2014\/09\/26\/un-tranvia-llamado-deseo-brando-y-las-mujeres-2\/\" target=\"_blank\" rel=\"noopener\"><strong>Marlon Brando<\/strong><\/a> en la \u00e9poca. Una imagen buscada que era importante porque, nos guste m\u00e1s o nos guste menos, el p\u00fablico general heterosexual, tiene enormes problemas cuando se trata de acercarse a la comunidad LGTBI, algo que no sucede al rev\u00e9s.<\/p>\n<p><strong>&#8216;Stonewall&#8217;<\/strong> no es perfecta, ni mucho menos. Languidece a la hora de convencer del todo de lo que all\u00ed ocurri\u00f3 en junio de 1969. Fracasa por no ser m\u00e1s ambiciosa. Fracasa porque es imposible que traspase los prejuicios de la cr\u00edtica o del p\u00fablico generalista. Y fracasa porque es una pel\u00edcula muy menor. Pero no es ni mucho menos un horror, ni una pel\u00edcula atroz.\u00a0<strong>&#8216;Stonewall&#8217;<\/strong> es una pel\u00edcula de introducci\u00f3n. Amable con un espectador alejado de la comunidad LGTBI y su historia. Una pel\u00edcula que pretende homenajear lo sucedido en Nueva York en el 69 y no ser una fiel recreaci\u00f3n. Estoy convencido de que el tiempo la terminar\u00e1 reivindicando de cierta forma.<\/p>\n<p><strong>Lo mejor<\/strong>: El final y que esta historia merec\u00eda ser contada.<\/p>\n<p><strong>Lo peor<\/strong>: La elecci\u00f3n del director y que no se le diera el beneficio de la duda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-92\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/65-300x30.png\" alt=\"Stonewall\" width=\"300\" height=\"30\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/65-300x30.png 300w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/65.png 564w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><iframe loading=\"lazy\" title=\"Stonewall Official Trailer 1 (2015) - Jonathan Rhys Meyers, Ron Perlman Movie HD\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/LGEJmPwB4yI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Stonewall&#8217; es una pel\u00edcula de introducci\u00f3n. Amable con un espectador alejado de la comunidad LGTBI y su historia que no pretende ser una recreaci\u00f3n fiel.<\/p>\n","protected":false},"author":101,"featured_media":3772,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[8213,8212,419,4394,1285,8211,8214,1670,1714,2647,6937,2178,8210,8215],"class_list":["post-3770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-drama","tag-andrea-frankle","tag-atticus-dean-mitchell","tag-caleb-landry-jones","tag-jeremy-irvine","tag-joey-king","tag-jonathan-rhys-meyers","tag-jonny-beauchamp","tag-mark-camacho","tag-matt-craven","tag-nathaly-thibault","tag-roland-emmerich","tag-ron-perlman","tag-stonewall","tag-vlad-alexis"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/comments?post=3770"}],"version-history":[{"count":1,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3770\/revisions"}],"predecessor-version":[{"id":3774,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3770\/revisions\/3774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media\/3772"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media?parent=3770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/categories?post=3770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/tags?post=3770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}