{"id":3808,"date":"2021-03-16T09:00:20","date_gmt":"2021-03-16T08:00:20","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/fotograma\/?p=3808"},"modified":"2021-03-14T17:01:00","modified_gmt":"2021-03-14T16:01:00","slug":"rebelion-a-bordo","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/fotograma\/2021\/03\/16\/rebelion-a-bordo\/","title":{"rendered":"&#8216;Rebeli\u00f3n a bordo&#8217;: aventuras marinas como las de antes"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3812\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/rebelion-bordo-cartel.jpg\" alt=\"Rebeli\u00f3n a bordo\" width=\"307\" height=\"453\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/rebelion-bordo-cartel.jpg 307w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/rebelion-bordo-cartel-203x300.jpg 203w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/>REBELI\u00d3N A BORDO<\/strong><\/p>\n<p><strong>T\u00edtulo original<\/strong>:\u00a0Mutiny on the Bounty<\/p>\n<p><strong>A\u00f1o<\/strong>:\u00a01962<\/p>\n<p><strong>Duraci\u00f3n<\/strong>:\u00a0178 minutos<\/p>\n<p><strong>Pa\u00eds<\/strong>:\u00a0Estados Unidos<\/p>\n<p><strong>Direcci\u00f3n<\/strong>:\u00a0Lewis Milestone<\/p>\n<p><strong>Guion<\/strong>:\u00a0Charles Lederer<\/p>\n<p><strong>M\u00fasica<\/strong>:\u00a0Bronislau Kaper<\/p>\n<p><strong>Fotograf\u00eda<\/strong>:\u00a0Robert Surtees<\/p>\n<p><strong>Reparto<\/strong>:\u00a0Marlon Brando, Trevor Howard, Richard Harris, Hugh Griffith, Richard Haydn, Tarita, Percy Herbert, Duncan Lamont, Gordon Jackson, Chips Rafferty, Noel Purcell, Ashley Cowan, Eddie Byrne, Frank Silvera, Tim Seely y Keith McConnell<\/p>\n<p><strong>Productora<\/strong>:\u00a0Metro-Goldwyn-Mayer (MGM)<\/p>\n<p><strong>G\u00e9nero<\/strong>:\u00a0Aventuras<\/p>\n<p><strong>Sinopsis<\/strong>:\u00a0En 1787, el Bounty zarpa del puerto de Portsmouth con destino a Tahit\u00ed para cargar el fruto del \u00e1rbol del pan. El capit\u00e1n Bligh, que desea llegar cuanto antes a la isla, impone una f\u00e9rrea disciplina a bordo. Cuando llegan, la tripulaci\u00f3n se encuentra con un aut\u00e9ntico para\u00edso que nada tiene que ver con el infierno vivido durante el viaje. (<a href=\"https:\/\/www.filmaffinity.com\/es\/film294780.html\" target=\"_blank\" rel=\"nofollow noopener\">FilmAffinity<\/a>)<\/p>\n<p><strong>&#8216;Rebeli\u00f3n a bordo&#8217;<\/strong> es uno de estos cl\u00e1sicos malditos que se han ido dejando de lado. Una pel\u00edcula rodada a principios de los a\u00f1os 60 y que es un remake de\u00a0<strong>&#8216;La tragedia de la Bounty&#8217;<\/strong> que protagoniz\u00f3\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2020\/06\/16\/lo-que-el-viento-se-llevo\/\" target=\"_blank\" rel=\"noopener\"><strong>Clark Gable<\/strong><\/a> 30 a\u00f1os antes. La cinta cuenta la historia de la expedici\u00f3n del Bounty, un nav\u00edo que ten\u00eda el encargo de ir hasta Tahit\u00ed y regresar con ejemplares del \u00e1rbol del pan para plantar en Reino Unido y utilizarlo como superalimento. Spoiler: acab\u00f3 todo como el rosario de la aurora.<\/p>\n<p><strong>&#8216;Rebeli\u00f3n a bordo&#8217;<\/strong> la podemos dividir en tres partes, cada una de una hora, aproximadamente. La primera hora nos cuenta el viaje, la segunda la estancia en Tahit\u00ed y la tercera la rebeli\u00f3n y posterior hu\u00edda de los amotinados. La cinta se recrea demasiado en la primera hora y deja la \u00faltima como algo m\u00e1s r\u00e1pido, ventilando los diferentes momentos con demasiada celeridad. Hubiese sido m\u00e1s interesante, creo yo, dedicar m\u00e1s tiempo a la rebeli\u00f3n en s\u00ed y a las consecuencias posteriores de los amotinados y los que siguiendo siendo fieles al capit\u00e1n Bligh.<\/p>\n<p>La cinta es de la vieja escuela. Obertura, primer acto, entreacto, segundo acto y cierre. Una pel\u00edcula que cost\u00f3 un verdadero pastizal para la \u00e9poca, 19 millones. Desde el principio estuvo envuelta en pol\u00e9mica por parte de la prensa especializada que critic\u00f3 la actitud de\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2014\/09\/26\/un-tranvia-llamado-deseo-brando-y-las-mujeres-2\/\" target=\"_blank\" rel=\"noopener\"><strong>Marlon Brando<\/strong><\/a> en el set de rodaje. Un\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2015\/07\/10\/apocalypse-now-brillante-retrato-sobre-el-horror-y-el-delirio-de-la-guerra\/\" target=\"_blank\" rel=\"noopener\"><strong>Brando<\/strong><\/a> que era la gran estrella de la funci\u00f3n y que posteriormente se casar\u00eda con su compa\u00f1era de rodaje,\u00a0<strong>Tarita<\/strong>, quiz\u00e1 el dato que m\u00e1s haya trascendido a la historia de esta pel\u00edcula.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3811\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/rebelion-bordo-1.jpg\" alt=\"Rebeli\u00f3n a bordo\" width=\"628\" height=\"353\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/rebelion-bordo-1.jpg 628w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/rebelion-bordo-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/p>\n<p>En cuanto a la pel\u00edcula es un derroche de medios realmente impresionante. El cine de barcos siempre ha sido muy dif\u00edcil de rodar, pero ya en el a\u00f1o 1962,\u00a0<strong>Lewis Milestone<\/strong>, dio buena cuenta de que se puede rodar cine con barcos y en alta mar si se quiere. Ese rodaje en escenarios naturales le da un plus que el cine de pantalla verde al que estamos acostumbrados ahora no tiene. La belleza del paisaje, el barco, las islas, las playas o el vestuario suman enteros.<\/p>\n<p>En el plano actoral\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2014\/09\/26\/un-tranvia-llamado-deseo-brando-y-las-mujeres-2\/\" target=\"_blank\" rel=\"noopener\"><strong>Marlon Brando<\/strong><\/a> roba todo el protagonismo al reparto. El actor, m\u00e1s comedido en palabras que en otras cintas, es en buena parte de la cinta un ente que vemos de fondo y de pasada, pero que cuando es protagonista se luce como ninguno. Ya he expresado en numerosas ocasiones en este blog que es un actor que admiro, y aqu\u00ed, aunque no es uno de sus grandes trabajos, es una nueva lecci\u00f3n de su capacidad actoral. Se luce especialmente en ese tramo final de pel\u00edcula en las Pitcairn.\u00a0<strong>Trevor Howard<\/strong> y\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2018\/10\/23\/harry-potter-y-la-piedra-filosofal\/\" target=\"_blank\" rel=\"noopener\"><strong>Richard Harris<\/strong><\/a> completan el estelar reparto.<\/p>\n<p><strong>&#8216;Rebeli\u00f3n a bordo&#8217;<\/strong> es un cl\u00e1sico que ha ca\u00eddo en el olvido por la mala prensa que recibi\u00f3 en la \u00e9poca y por el fracaso en taquilla que result\u00f3 ser. Una pel\u00edcula que es de los mejores ejemplos de cine de aventuras marinas. Rodada hace 60 a\u00f1os y luce como si fuera una pel\u00edcula reciente, un prodigio.<\/p>\n<p><strong>Lo mejor<\/strong>: El trabajo de fotograf\u00eda, decoraci\u00f3n, vestuario, m\u00fasica, efectos especiales&#8230; el derroche t\u00e9cnico.<\/p>\n<p><strong>Lo peor<\/strong>: Las injustas cr\u00edticas que recibi\u00f3 y que haya quedado para la posteridad como pel\u00edcula maldita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-94\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75-300x30.png\" alt=\"Rebeli\u00f3n a bordo\" width=\"300\" height=\"30\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75-300x30.png 300w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/75.png 564w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><iframe loading=\"lazy\" title=\"Mutiny on the Bounty (1962) - The Mutiny Scene (5\/9) | Movieclips\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/t0oqEjxOUww?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Rebeli\u00f3n a bordo&#8217; es un cl\u00e1sico que ha ca\u00eddo en el olvido por la mala prensa que recibi\u00f3 en la \u00e9poca y por el fracaso en taquilla que result\u00f3 ser<\/p>\n","protected":false},"author":101,"featured_media":3810,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[8299,8297,8295,8300,8301,8296,2917,8303,8306,1682,8304,8298,8294,8305,2125,8292,8293,8302,8291],"class_list":["post-3808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aventuras","tag-ashley-cowan","tag-chips-rafferty","tag-duncan-lamont","tag-eddie-byrne","tag-frank-silvera","tag-gordon-jackson","tag-hugh-griffith","tag-keith-mcconnell","tag-lewis-milestone","tag-marlon-brando","tag-mutiny-on-the-bounty","tag-noel-purcell","tag-percy-herbert","tag-rebelion-a-bordo","tag-richard-harris","tag-richard-haydn","tag-tarita","tag-tim-seely","tag-trevor-howard"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/comments?post=3808"}],"version-history":[{"count":2,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3808\/revisions"}],"predecessor-version":[{"id":3814,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3808\/revisions\/3814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media\/3810"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media?parent=3808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/categories?post=3808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/tags?post=3808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}