{"id":3836,"date":"2021-12-30T09:00:54","date_gmt":"2021-12-30T08:00:54","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/fotograma\/?p=3836"},"modified":"2021-07-15T17:46:33","modified_gmt":"2021-07-15T15:46:33","slug":"la-noche-americana","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/fotograma\/2021\/12\/30\/la-noche-americana\/","title":{"rendered":"&#8216;La noche americana&#8217;: declaraci\u00f3n de amor al cine de Truffaut"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3839\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/noche-americana-cartel.jpg\" alt=\"La noche americana\" width=\"307\" height=\"453\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/noche-americana-cartel.jpg 307w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/noche-americana-cartel-203x300.jpg 203w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/>LA NOCHE AMERICANA<\/strong><\/p>\n<p><strong>T\u00edtulo original<\/strong>: La Nuit am\u00e9ricaine<\/p>\n<p><strong>A\u00f1o<\/strong>:\u00a01973<\/p>\n<p><strong>Duraci\u00f3n<\/strong>:\u00a0115 minutos<\/p>\n<p><strong>Pa\u00eds<\/strong>:\u00a0Francia \/ Italia<\/p>\n<p><strong>Direcci\u00f3n<\/strong>:\u00a0Fran\u00e7ois Truffaut<\/p>\n<p><strong>Guion<\/strong>:\u00a0Fran\u00e7ois Truffaut, Jean-Louis Richard y Suzanne Schiffman<\/p>\n<p><strong>M\u00fasica<\/strong>:\u00a0Georges Delerue<\/p>\n<p><strong>Fotograf\u00eda<\/strong>:\u00a0Pierre-William Glenn<\/p>\n<p><strong>Reparto<\/strong>:\u00a0Jean-Pierre L\u00e9aud, Jacqueline Bisset, Nathalie Baye, Alexandra Stewart, Jean-Pierre Aumont, Fran\u00e7ois Truffaut, Valentina Cortese, Dani, Jean Champion, Nike Arrighi, Maurice Seveno, David Markham, Bernard Menez, Gaston Joly, Z\u00e9na\u00efde Rossi, Xavier Saint-Macary, Marc Boyle, Walter Bal, Jean-Fran\u00e7ois St\u00e9venin y Pierre Zucca<\/p>\n<p><strong>Productora<\/strong>:\u00a0Les Films du Carrosse, PECF, PECF<\/p>\n<p><strong>G\u00e9nero<\/strong>:\u00a0Drama \/ Comedia<\/p>\n<p><strong>Sinopsis<\/strong>:\u00a0Una pel\u00edcula que va a rodarse comienza con la llegada de los actores y los miembros del equipo t\u00e9cnico, pero pronto el rodaje tropieza con una serie de dificultades que afectan tanto a los miembros del equipo como a la propia pel\u00edcula. (<a href=\"https:\/\/www.filmaffinity.com\/es\/film113826.html\" target=\"_blank\" rel=\"nofollow noopener\">FilmAffinity<\/a>)<\/p>\n<p><strong>&#8216;La noche americana&#8217;<\/strong> es la declaraci\u00f3n de amor al cine de un enamorado del cine como\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2020\/01\/30\/los-400-golpes\/\" target=\"_blank\" rel=\"noopener\"><strong>Fran\u00e7ois Truffaut<\/strong><\/a>. Alguien que hizo del cine su medio de vida, que viv\u00eda por y para el cine y que dej\u00f3 un legado de pel\u00edculas brillante entre las que destaca esta oda al s\u00e9ptimo arte. Una pel\u00edcula que cuenta el proceso de grabaci\u00f3n de una pel\u00edcula y los problemas y retos que plantean a su equipo. La historia que cuenta da exactamente lo mismo, porque aqu\u00ed lo interesante es c\u00f3mo un gran cineasta como\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2015\/09\/21\/dias-de-festival-4-eva-no-duerme-high-rise-y-hitchcocktruffaut\/\" target=\"_blank\" rel=\"noopener\"><strong>Truffaut<\/strong><\/a> acerca el proceso de hacer una pel\u00edcula a los espectadores menos acostumbrados a ver lo que ocurre detr\u00e1s de las bambalinas.<\/p>\n<p>En\u00a0<strong>&#8216;La noche americana&#8217;<\/strong> descubrimos la importancia que tiene cada uno de los miembros del equipo de rodaje en el resultado de la pel\u00edcula.\u00a0<a href=\"https:\/\/blogs.diariovasco.com\/fotograma\/2020\/01\/30\/los-400-golpes\/\" target=\"_blank\" rel=\"noopener\"><strong>Truffaut<\/strong><\/a> reivindica desde las scripts a los guionistas, los actores, los directores de diferentes departamentos y el propio director de la pel\u00edcula. Nos habla de las rarezas del equipo de actores y c\u00f3mo en ocasiones estas rarezas obligan a cambiar los planes, modificar el guion o los textos. Vemos c\u00f3mo una toma se tiene que repetir una y otra vez hasta dar con el tono que se busca, vemos c\u00f3mo los actores utilizan trucos para recordar los guiones, etc. Es una pel\u00edcula que nos dice c\u00f3mo se fabrica la nieve o c\u00f3mo hacen para que las velas o las chimeneas iluminen tanto una habitaci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3837\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/noche-americana-2.jpg\" alt=\"La noche americana\" width=\"628\" height=\"353\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/noche-americana-2.jpg 628w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2021\/01\/noche-americana-2-300x169.jpg 300w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/p>\n<p>Al fin y al cabo,\u00a0<strong>&#8216;La noche americana&#8217;<\/strong> es una pel\u00edcula que muestra las costuras del cine desde la honestidad, el sentido del humor y el amor al medio. Porque hasta el t\u00edtulo evoca al cine. La noche americana es como se conoce a la t\u00e9cnica de rodar de d\u00eda y hacer que parezca de noche empleando filtros. Una t\u00e9cnica que en ingl\u00e9s se conoce como &#8220;day by night&#8221; y que se emplea cada vez menos, al mejorar la t\u00e9cnica para poder grabar de noche con la suficiente fidelidad de imagen.<\/p>\n<p>Tal vez no sea la pel\u00edcula ideal para quienes buscan historias, porque aqu\u00ed hay poco de eso. Pero s\u00ed que es la pel\u00edcula perfecta para quienes aman profundamente el cine. Un canto de amor al s\u00e9ptimo arte a trav\u00e9s del rodaje de una pel\u00edcula que nunca podremos ver. Una reivindicaci\u00f3n de esta profesi\u00f3n que hace magia mediante im\u00e1genes.<\/p>\n<p><strong>Lo mejor<\/strong>: Es una joya imprescindible para todo cin\u00e9filo.<\/p>\n<p><strong>Lo peor<\/strong>: La historia que narra importa realmente poco.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-96\" src=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/85-300x30.png\" alt=\"\" width=\"300\" height=\"30\" srcset=\"https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/85-300x30.png 300w, https:\/\/blogs.diariovasco.com\/fotograma\/wp-content\/uploads\/sites\/71\/2014\/11\/85.png 564w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><iframe loading=\"lazy\" title=\"Trailer La nuit ame\u0301ricaine-La noche americana- Day For Night\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/DKoEVBHMp3s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA NOCHE AMERICANA T\u00edtulo original: La Nuit am\u00e9ricaine A\u00f1o:\u00a01973 Duraci\u00f3n:\u00a0115 minutos Pa\u00eds:\u00a0Francia \/ Italia Direcci\u00f3n:\u00a0Fran\u00e7ois Truffaut Guion:\u00a0Fran\u00e7ois Truffaut, Jean-Louis Richard y Suzanne Schiffman M\u00fasica:\u00a0Georges Delerue Fotograf\u00eda:\u00a0Pierre-William Glenn Reparto:\u00a0Jean-Pierre L\u00e9aud, Jacqueline Bisset, Nathalie Baye, Alexandra Stewart, Jean-Pierre Aumont, Fran\u00e7ois Truffaut, Valentina Cortese, Dani, Jean Champion, Nike Arrighi, Maurice Seveno, David Markham, Bernard Menez, Gaston Joly, Z\u00e9na\u00efde [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":3838,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,11],"tags":[8336,8344,8339,8343,881,8345,1107,8340,8350,8337,6101,8353,8352,8348,8342,1867,8341,8351,8338,8349,8347,8346],"class_list":["post-3836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comedia","category-drama","tag-alexandra-stewart","tag-bernard-menez","tag-dani","tag-david-markham","tag-francois-truffaut","tag-gaston-joly","tag-jacqueline-bisset","tag-jean-champion","tag-jean-francois-stevenin","tag-jean-pierre-aumont","tag-jean-pierre-leaud","tag-la-noche-americana","tag-la-nuit-americaine","tag-marc-boyle","tag-maurice-seveno","tag-nathalie-baye","tag-nike-arrighi","tag-pierre-zucca","tag-valentina-cortese","tag-walter-bal","tag-xavier-saint-macary","tag-zenaide-rossi"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/comments?post=3836"}],"version-history":[{"count":1,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3836\/revisions"}],"predecessor-version":[{"id":3840,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/posts\/3836\/revisions\/3840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media\/3838"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/media?parent=3836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/categories?post=3836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/fotograma\/wp-json\/wp\/v2\/tags?post=3836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}