{"id":169,"date":"2014-10-23T12:34:22","date_gmt":"2014-10-23T11:34:22","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/la-bola-entro\/?p=169"},"modified":"2014-10-23T12:34:22","modified_gmt":"2014-10-23T11:34:22","slug":"el-tenista-sin-ranking","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/2014\/10\/23\/el-tenista-sin-ranking\/","title":{"rendered":"El tenista sin ranking"},"content":{"rendered":"<p>Hace ex\u00e1ctamente un a\u00f1o, un servidor despotricaba en este blog en torno a la actitud de un tenista que acudi\u00f3 a un torneo estando lesionado para \u00fanicamente llevarse el premio met\u00e1lico de su presencia en primera ronda tras iniciar un simulacro de partido. Fue el 21 de octubre en el \u00c1gora de Valencia donde Janko Tipsarevic disput\u00f3 apenas tres juegos ante Marcel Granollers y se retiraba por problemas en su pie izquierdo. Se embols\u00f3 10.400 euros por 19 minutos de partido, pero lo que nadie supon\u00eda es que aquellos fuesen los \u00faltimos euros en premios que se llevar\u00eda el tenista serbio desde aquella fecha.<\/p>\n<p>Desde entonces una serie de interminables y delicadas lesiones le han mantenido en el dique seco, de forma que no ha podido estrenar su raqueta en este a\u00f1o 2014. Esto conlleva la p\u00e9rdida total de puntos en su casillero y el no aparecer en la clasificaci\u00f3n ATP con ning\u00fan ranking. Oficialmente no existe en las clasificaciones, cuando hace un a\u00f1o figuraba en el puesto 28. Hace unos d\u00edas, en su perfil de twitter publicaba un mensaje que lo confirmaba:<\/p>\n<p><a href=\"\/la-bola-entro\/wp-content\/uploads\/sites\/140\/2014\/10\/tenir.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-170\" src=\"\/la-bola-entro\/wp-content\/uploads\/sites\/140\/2014\/10\/tenir.jpg\" alt=\"\" width=\"489\" height=\"199\" srcset=\"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-content\/uploads\/sites\/140\/2014\/10\/tenir.jpg 636w, https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-content\/uploads\/sites\/140\/2014\/10\/tenir-300x122.jpg 300w\" sizes=\"auto, (max-width: 489px) 100vw, 489px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>As\u00ed es, Janko se ha quedado sin puntos al pasar todo un a\u00f1o sin poder asistir a ning\u00fan torneo ATP. Sus problemas en el tal\u00f3n de Aquiles de su pie izquierdo no le permitieron aparecer en ning\u00fan torneo a cierre de 2013 tras el de Valencia. La recuperaci\u00f3n en un primer momento se alarg\u00f3 y se uni\u00f3 al nacimiento de su primer hijo lo que hac\u00eda suponer que su regreso llegar\u00eda bien entrada la temporada de tierra. Pero la cosa se torci\u00f3. Unas pruebas reflejaron la aparici\u00f3n de un tumor benigno en esa zona del tal\u00f3n. La dolencia, com\u00fanmente denominada fibromatosis fue intervenida el pasado junio, pero tras tres meses de tratamiento y cuando estaba a punto de comenzar a andar se descubri\u00f3 que el tumor hab\u00eda vuelto a reaparecer.<\/p>\n<p><a href=\"\/la-bola-entro\/wp-content\/uploads\/sites\/140\/2014\/10\/Tips.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-172\" style=\"margin: 5px\" src=\"\/la-bola-entro\/wp-content\/uploads\/sites\/140\/2014\/10\/Tips.jpg\" alt=\"\" width=\"565\" height=\"333\" srcset=\"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-content\/uploads\/sites\/140\/2014\/10\/Tips.jpg 620w, https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-content\/uploads\/sites\/140\/2014\/10\/Tips-300x177.jpg 300w\" sizes=\"auto, (max-width: 565px) 100vw, 565px\" \/><\/a>&#8220;La agon\u00eda de esta lesi\u00f3n parece no tener fin&#8221;, confesaba Janko en septiembre, cuando fue intervenido nuevamente en Frankfurt del tumor que apareci\u00f3 cerca de la cicatriz que hab\u00eda dejado la primera intervenci\u00f3n. &#8220;Vivir en suspenso, cuando nadie puede garantizar el resultado es una sensaci\u00f3n horrible. Lo m\u00e1s dif\u00edcil para un atleta es no saber cu\u00e1ndo puede volver a la cancha&#8221;, se\u00f1alaba apenado.<\/p>\n<p>Durante este \u00faltimo mes, el tenista ha colgado en twitter diferentes v\u00eddeos de su proceso de recuperaci\u00f3n. Colg\u00f3 im\u00e1genes de uno de sus entrenos con una silla en la que apoyaba su pierna lesionada mientras golpeaba la pelota en la pista de tenis. Afortunadamente esta vez la recuperaci\u00f3n marcha m\u00e1s r\u00e1pida y ya apoya su pie izquierdo. Su regreso est\u00e1 programado para las primeras semanas de enero del a\u00f1o pr\u00f3ximo, ya que ha afirmado que ser\u00e1 de la partida en el torneo de Chennai en la India, una de las competiciones que aparecen en su palmar\u00e9s ya que se alz\u00f3 con la victoria en 2013. Esperemos que pronto volvamos a ver su gran talento sobre las pistas y disfrutemos de aquel serbio que lleg\u00f3 a ser el n\u00famero 8 del mundo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El serbio Janko Tipsarevic acaba de cumplir un a\u00f1o sin jugar debido a una fibromatosis (tumor benigno) en el tal\u00f3n izquierdo. Tras 365 d\u00edas sin jugar, sigue con su recuperaci\u00f3n y al no tener puntos ATP ha desaparecido de las clasificaciones.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2000,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[17,32,124,135,137,142,147],"class_list":["post-169","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-atp","tag-chennai","tag-serbia","tag-tenis","tag-tipsarevic","tag-tumor","tag-valencia"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-json\/wp\/v2\/posts\/169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-json\/wp\/v2\/users\/2000"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-json\/wp\/v2\/comments?post=169"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-json\/wp\/v2\/posts\/169\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-json\/wp\/v2\/media?parent=169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-json\/wp\/v2\/categories?post=169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/la-bola-entro\/wp-json\/wp\/v2\/tags?post=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}