{"id":1651,"date":"2015-11-26T11:37:09","date_gmt":"2015-11-26T10:37:09","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/lacasadecora\/?p=1651"},"modified":"2015-11-26T11:37:09","modified_gmt":"2015-11-26T10:37:09","slug":"2016-nuevo-color-del-ano-rose-quartz","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/lacasadecora\/2016-nuevo-color-del-ano-rose-quartz\/2015\/11\/26\/","title":{"rendered":"2016: nuevo color del a\u00f1o: Rose Quartz"},"content":{"rendered":"\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-1651 gallery-columns-2 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/1-habitacion-paredes.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/1-habitacion-paredes-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/2-pantone-rose-quartz.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/2-pantone-rose-quartz-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/3-piedra-rosa.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/3-piedra-rosa-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/4-estar-butaca-pared.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/4-estar-butaca-pared-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/4-estar-butaca-pared-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/4-estar-butaca-pared-300x300.jpg 300w, https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/4-estar-butaca-pared.jpg 600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/5-ropa-en-calle.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/5-ropa-en-calle-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/6-desfile-traje-completo.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-content\/uploads\/sites\/59\/2015\/11\/6-desfile-traje-completo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>El color del 2015 ha sido el Marsala, un granate c\u00e1lido, y este pr\u00f3ximo 2016, ya ha sido presentado por Pantone, como color del a\u00f1o el Rose Quartz 13-1520.<\/p>\n<p>Un color suave y muy femenino. Un rosa empolvado muy apropiado para dar un toque rom\u00e1ntico a cualquier espacio. Muy usado \u00faltimamente en moda, por los grandes dise\u00f1adores, queda muy bien como contrapunto a colores mas fuertes y oscuros, como el marr\u00f3n, gris antracita y negro\u2026<\/p>\n<p>Tambi\u00e9n se puede usar como color \u00fanico, con diferentes tonalidades del mismo, dejando al entorno un aspecto muy c\u00e1lido y agradable<\/p>\n<p>Os gusta el nuevo color del 2016 \u2026?<\/p>\n<p>Lo usar\u00edas en tu propia vivienda \u2026?<\/p>\n<p>Fotos v\u00eda: google<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El color del 2015 ha sido el Marsala, un granate c\u00e1lido, y este pr\u00f3ximo 2016, ya ha sido presentado por Pantone, como color del a\u00f1o el Rose Quartz 13-1520. Un color suave y muy femenino. Un rosa empolvado muy apropiado para dar un toque rom\u00e1ntico a cualquier espacio. Muy usado \u00faltimamente en moda, por los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":88,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[56,106,169],"class_list":["post-1651","post","type-post","status-publish","format-standard","hentry","category-casa","tag-color","tag-inspiracion","tag-rosa"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/posts\/1651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/comments?post=1651"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/posts\/1651\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/media?parent=1651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/categories?post=1651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/lacasadecora\/wp-json\/wp\/v2\/tags?post=1651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}